{"id":4797,"date":"2021-11-05T07:56:00","date_gmt":"2021-11-05T07:56:00","guid":{"rendered":"http:\/\/casasolo.es\/?p=4797"},"modified":"2022-09-06T09:02:40","modified_gmt":"2022-09-06T09:02:40","slug":"2o-premio-concurso-internacional-para-el-diseno-de-la-nueva-sede-del-barcelona-institute-of-science-and-technology-bist","status":"publish","type":"post","link":"https:\/\/casasolo.es\/en\/2o-premio-concurso-internacional-para-el-diseno-de-la-nueva-sede-del-barcelona-institute-of-science-and-technology-bist\/","title":{"rendered":"2\u00ba Premio. Concurso internacional para el dise\u00f1o de la nueva sede del Barcelona Institute of Science and Technology BIST"},"content":{"rendered":"\n<p>El edificio se dise\u00f1a en dos partes diferenciadas: un z\u00f3calo que se relaciona con la altura de los antiguos cuarteles y aloja los espacios comunes, dando continuidad a la ciudad, y un volumen ligero que contiene todo el programa de laboratorios.<\/p>\n\n\n\n<p>Las plantas giran en torno a un gran atrio que constituye la imagen m\u00e1s representativa del BIST. Cuatro n\u00facleos verticales en sus esquinas contienen escaleras, ascensores y ba\u00f1os. El n\u00facleo principal de ascensores transparentes panor\u00e1micos ir\u00e1 subiendo con una mirada al mar, convirtiendo el ascenso en un espect\u00e1culo.<\/p>\n\n\n\n<p>El atrio cubierto funciona como un espacio bioclim\u00e1tico, y se abre con grandes agujeros en unas terrazas de doble altura que relacionan el edificio con el mar y la ciudad. Estas terrazas permiten espacios de trabajo m\u00e1s relajados y lugares de encuentro, que se integran con el anillo de circulaci\u00f3n de cada planta.<\/p>\n\n\n\n<p>Una terraza perimetral envuelve los espacios de trabajo, protegiendo del sol y ofreciendo espacios abiertos conectados con el exterior en todas partes.<\/p>\n\n\n\n<p>En la planta m\u00e1s alta, se ubica un espacio protegido por la cubierta invernadero que permite todo tipo de actividades.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-gallery aligncenter has-nested-images columns-1 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"4810\" src=\"http:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Exterior-02_BAAS-MONEO-BROCK-CASASOLO-1024x1024.jpeg\" alt=\"\" class=\"wp-image-4810\" srcset=\"https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Exterior-02_BAAS-MONEO-BROCK-CASASOLO-1024x1024.jpeg 1024w, https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Exterior-02_BAAS-MONEO-BROCK-CASASOLO-300x300.jpeg 300w, https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Exterior-02_BAAS-MONEO-BROCK-CASASOLO-150x150.jpeg 150w, https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Exterior-02_BAAS-MONEO-BROCK-CASASOLO-768x768.jpeg 768w, https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Exterior-02_BAAS-MONEO-BROCK-CASASOLO.jpeg 1181w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"4807\" src=\"http:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Exterior-01_BAAS-MONEO-BROCK-CASASOLO-1024x1024.jpeg\" alt=\"\" class=\"wp-image-4807\" srcset=\"https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Exterior-01_BAAS-MONEO-BROCK-CASASOLO-1024x1024.jpeg 1024w, https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Exterior-01_BAAS-MONEO-BROCK-CASASOLO-300x300.jpeg 300w, https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Exterior-01_BAAS-MONEO-BROCK-CASASOLO-150x150.jpeg 150w, https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Exterior-01_BAAS-MONEO-BROCK-CASASOLO-768x768.jpeg 768w, https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Exterior-01_BAAS-MONEO-BROCK-CASASOLO.jpeg 1181w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"4798\" src=\"http:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Agora_BAAS-MONEO-BROCK-CASASOLO-1024x683.jpeg\" alt=\"\" class=\"wp-image-4798\" srcset=\"https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Agora_BAAS-MONEO-BROCK-CASASOLO-1024x683.jpeg 1024w, https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Agora_BAAS-MONEO-BROCK-CASASOLO-300x200.jpeg 300w, https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Agora_BAAS-MONEO-BROCK-CASASOLO-768x512.jpeg 768w, https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Agora_BAAS-MONEO-BROCK-CASASOLO-1536x1024.jpeg 1536w, https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Agora_BAAS-MONEO-BROCK-CASASOLO.jpeg 1771w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"717\" height=\"1024\" data-id=\"4801\" src=\"http:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Atrio_BAAS-MONEO-BROCK-CASASOLO-717x1024.jpeg\" alt=\"\" class=\"wp-image-4801\" srcset=\"https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Atrio_BAAS-MONEO-BROCK-CASASOLO-717x1024.jpeg 717w, https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Atrio_BAAS-MONEO-BROCK-CASASOLO-210x300.jpeg 210w, https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Atrio_BAAS-MONEO-BROCK-CASASOLO-768x1097.jpeg 768w, https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Atrio_BAAS-MONEO-BROCK-CASASOLO-1075x1536.jpeg 1075w, https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Atrio_BAAS-MONEO-BROCK-CASASOLO.jpeg 1181w\" sizes=\"(max-width: 717px) 100vw, 717px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"546\" data-id=\"4816\" src=\"http:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Terraza-interior_BAAS-MONEO-BROCK-CASASOLO-1024x546.jpeg\" alt=\"\" class=\"wp-image-4816\" srcset=\"https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Terraza-interior_BAAS-MONEO-BROCK-CASASOLO-1024x546.jpeg 1024w, https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Terraza-interior_BAAS-MONEO-BROCK-CASASOLO-300x160.jpeg 300w, https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Terraza-interior_BAAS-MONEO-BROCK-CASASOLO-768x410.jpeg 768w, https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Terraza-interior_BAAS-MONEO-BROCK-CASASOLO-1536x819.jpeg 1536w, https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Terraza-interior_BAAS-MONEO-BROCK-CASASOLO.jpeg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"4813\" src=\"http:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Terraza-exterior_BAAS-MONEO-BROCK-CASASOLO-768x1024.jpeg\" alt=\"\" class=\"wp-image-4813\" srcset=\"https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Terraza-exterior_BAAS-MONEO-BROCK-CASASOLO-768x1024.jpeg 768w, https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Terraza-exterior_BAAS-MONEO-BROCK-CASASOLO-225x300.jpeg 225w, https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Terraza-exterior_BAAS-MONEO-BROCK-CASASOLO-1152x1536.jpeg 1152w, https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Terraza-exterior_BAAS-MONEO-BROCK-CASASOLO.jpeg 1181w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"4804\" src=\"http:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Cubierta_BAAS-MONEO-BROCK-CASASOLO-1024x1024.jpeg\" alt=\"\" class=\"wp-image-4804\" srcset=\"https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Cubierta_BAAS-MONEO-BROCK-CASASOLO-1024x1024.jpeg 1024w, https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Cubierta_BAAS-MONEO-BROCK-CASASOLO-300x300.jpeg 300w, https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Cubierta_BAAS-MONEO-BROCK-CASASOLO-150x150.jpeg 150w, https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Cubierta_BAAS-MONEO-BROCK-CASASOLO-768x768.jpeg 768w, https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Cubierta_BAAS-MONEO-BROCK-CASASOLO.jpeg 1181w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<figcaption class=\"blocks-gallery-caption\">Im\u00e1genes: Playtime<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El equipo formado por BAAS + MONEO BROCK + CASA SOLO ha sido finalista, recibiendo el 2\u00ba premio, en el concurso de la nueva sede del Barcelona Institute of Science and Technology BIST, en el Antic Mercat del Peix en Barcelona.<\/p>\n","protected":false},"author":1,"featured_media":4807,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[136,137],"class_list":["post-4797","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar","tag-bist","tag-concurso-internacional"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>2\u00ba Premio. Concurso internacional para el dise\u00f1o de la nueva sede del Barcelona Institute of Science and Technology BIST - CASA SOLO arquitectos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casasolo.es\/en\/2o-premio-concurso-internacional-para-el-diseno-de-la-nueva-sede-del-barcelona-institute-of-science-and-technology-bist\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2\u00ba Premio. Concurso internacional para el dise\u00f1o de la nueva sede del Barcelona Institute of Science and Technology BIST - CASA SOLO arquitectos\" \/>\n<meta property=\"og:description\" content=\"El equipo formado por BAAS + MONEO BROCK + CASA SOLO ha sido finalista, recibiendo el 2\u00ba premio, en el concurso de la nueva sede del Barcelona Institute of Science and Technology BIST, en el Antic Mercat del Peix en Barcelona.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casasolo.es\/en\/2o-premio-concurso-internacional-para-el-diseno-de-la-nueva-sede-del-barcelona-institute-of-science-and-technology-bist\/\" \/>\n<meta property=\"og:site_name\" content=\"CASA SOLO arquitectos\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-05T07:56:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-06T09:02:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Exterior-01_BAAS-MONEO-BROCK-CASASOLO.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1181\" \/>\n\t<meta property=\"og:image:height\" content=\"1181\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"PH STUDIO\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"PH STUDIO\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/casasolo.es\/en\/2o-premio-concurso-internacional-para-el-diseno-de-la-nueva-sede-del-barcelona-institute-of-science-and-technology-bist\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/casasolo.es\/en\/2o-premio-concurso-internacional-para-el-diseno-de-la-nueva-sede-del-barcelona-institute-of-science-and-technology-bist\/\"},\"author\":{\"name\":\"PH STUDIO\",\"@id\":\"https:\/\/casasolo.es\/en\/#\/schema\/person\/b41f2cfcd2692379bec3ae2da04002b0\"},\"headline\":\"2\u00ba Premio. Concurso internacional para el dise\u00f1o de la nueva sede del Barcelona Institute of Science and Technology BIST\",\"datePublished\":\"2021-11-05T07:56:00+00:00\",\"dateModified\":\"2022-09-06T09:02:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/casasolo.es\/en\/2o-premio-concurso-internacional-para-el-diseno-de-la-nueva-sede-del-barcelona-institute-of-science-and-technology-bist\/\"},\"wordCount\":218,\"publisher\":{\"@id\":\"https:\/\/casasolo.es\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/casasolo.es\/en\/2o-premio-concurso-internacional-para-el-diseno-de-la-nueva-sede-del-barcelona-institute-of-science-and-technology-bist\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Exterior-01_BAAS-MONEO-BROCK-CASASOLO.jpeg\",\"keywords\":[\"BIST\",\"Concurso Internacional\"],\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/casasolo.es\/en\/2o-premio-concurso-internacional-para-el-diseno-de-la-nueva-sede-del-barcelona-institute-of-science-and-technology-bist\/\",\"url\":\"https:\/\/casasolo.es\/en\/2o-premio-concurso-internacional-para-el-diseno-de-la-nueva-sede-del-barcelona-institute-of-science-and-technology-bist\/\",\"name\":\"2\u00ba Premio. Concurso internacional para el dise\u00f1o de la nueva sede del Barcelona Institute of Science and Technology BIST - CASA SOLO arquitectos\",\"isPartOf\":{\"@id\":\"https:\/\/casasolo.es\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/casasolo.es\/en\/2o-premio-concurso-internacional-para-el-diseno-de-la-nueva-sede-del-barcelona-institute-of-science-and-technology-bist\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/casasolo.es\/en\/2o-premio-concurso-internacional-para-el-diseno-de-la-nueva-sede-del-barcelona-institute-of-science-and-technology-bist\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Exterior-01_BAAS-MONEO-BROCK-CASASOLO.jpeg\",\"datePublished\":\"2021-11-05T07:56:00+00:00\",\"dateModified\":\"2022-09-06T09:02:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/casasolo.es\/en\/2o-premio-concurso-internacional-para-el-diseno-de-la-nueva-sede-del-barcelona-institute-of-science-and-technology-bist\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/casasolo.es\/en\/2o-premio-concurso-internacional-para-el-diseno-de-la-nueva-sede-del-barcelona-institute-of-science-and-technology-bist\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/casasolo.es\/en\/2o-premio-concurso-internacional-para-el-diseno-de-la-nueva-sede-del-barcelona-institute-of-science-and-technology-bist\/#primaryimage\",\"url\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Exterior-01_BAAS-MONEO-BROCK-CASASOLO.jpeg\",\"contentUrl\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Exterior-01_BAAS-MONEO-BROCK-CASASOLO.jpeg\",\"width\":1181,\"height\":1181},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/casasolo.es\/en\/2o-premio-concurso-internacional-para-el-diseno-de-la-nueva-sede-del-barcelona-institute-of-science-and-technology-bist\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/casasolo.es\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"2\u00ba Premio. Concurso internacional para el dise\u00f1o de la nueva sede del Barcelona Institute of Science and Technology BIST\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/casasolo.es\/en\/#website\",\"url\":\"https:\/\/casasolo.es\/en\/\",\"name\":\"CASA SOLO arquitectos\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/casasolo.es\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/casasolo.es\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/casasolo.es\/en\/#organization\",\"name\":\"CASA SOLO arquitectos\",\"url\":\"https:\/\/casasolo.es\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/casasolo.es\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2021\/10\/casasolo-logo.svg\",\"contentUrl\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2021\/10\/casasolo-logo.svg\",\"caption\":\"CASA SOLO arquitectos\"},\"image\":{\"@id\":\"https:\/\/casasolo.es\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/casasolo.es\/en\/#\/schema\/person\/b41f2cfcd2692379bec3ae2da04002b0\",\"name\":\"PH STUDIO\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/casasolo.es\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1c4771d67760d55d3bbd348e233bc4adcb9d3ee6a3f78131e3dc5300381a2979?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1c4771d67760d55d3bbd348e233bc4adcb9d3ee6a3f78131e3dc5300381a2979?s=96&d=mm&r=g\",\"caption\":\"PH STUDIO\"},\"url\":\"https:\/\/casasolo.es\/en\/author\/ph-studio\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2\u00ba Premio. Concurso internacional para el dise\u00f1o de la nueva sede del Barcelona Institute of Science and Technology BIST - CASA SOLO arquitectos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casasolo.es\/en\/2o-premio-concurso-internacional-para-el-diseno-de-la-nueva-sede-del-barcelona-institute-of-science-and-technology-bist\/","og_locale":"en_US","og_type":"article","og_title":"2\u00ba Premio. Concurso internacional para el dise\u00f1o de la nueva sede del Barcelona Institute of Science and Technology BIST - CASA SOLO arquitectos","og_description":"El equipo formado por BAAS + MONEO BROCK + CASA SOLO ha sido finalista, recibiendo el 2\u00ba premio, en el concurso de la nueva sede del Barcelona Institute of Science and Technology BIST, en el Antic Mercat del Peix en Barcelona.","og_url":"https:\/\/casasolo.es\/en\/2o-premio-concurso-internacional-para-el-diseno-de-la-nueva-sede-del-barcelona-institute-of-science-and-technology-bist\/","og_site_name":"CASA SOLO arquitectos","article_published_time":"2021-11-05T07:56:00+00:00","article_modified_time":"2022-09-06T09:02:40+00:00","og_image":[{"width":1181,"height":1181,"url":"https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Exterior-01_BAAS-MONEO-BROCK-CASASOLO.jpeg","type":"image\/jpeg"}],"author":"PH STUDIO","twitter_card":"summary_large_image","twitter_misc":{"Written by":"PH STUDIO","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/casasolo.es\/en\/2o-premio-concurso-internacional-para-el-diseno-de-la-nueva-sede-del-barcelona-institute-of-science-and-technology-bist\/#article","isPartOf":{"@id":"https:\/\/casasolo.es\/en\/2o-premio-concurso-internacional-para-el-diseno-de-la-nueva-sede-del-barcelona-institute-of-science-and-technology-bist\/"},"author":{"name":"PH STUDIO","@id":"https:\/\/casasolo.es\/en\/#\/schema\/person\/b41f2cfcd2692379bec3ae2da04002b0"},"headline":"2\u00ba Premio. Concurso internacional para el dise\u00f1o de la nueva sede del Barcelona Institute of Science and Technology BIST","datePublished":"2021-11-05T07:56:00+00:00","dateModified":"2022-09-06T09:02:40+00:00","mainEntityOfPage":{"@id":"https:\/\/casasolo.es\/en\/2o-premio-concurso-internacional-para-el-diseno-de-la-nueva-sede-del-barcelona-institute-of-science-and-technology-bist\/"},"wordCount":218,"publisher":{"@id":"https:\/\/casasolo.es\/en\/#organization"},"image":{"@id":"https:\/\/casasolo.es\/en\/2o-premio-concurso-internacional-para-el-diseno-de-la-nueva-sede-del-barcelona-institute-of-science-and-technology-bist\/#primaryimage"},"thumbnailUrl":"https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Exterior-01_BAAS-MONEO-BROCK-CASASOLO.jpeg","keywords":["BIST","Concurso Internacional"],"articleSection":["Sin categorizar"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/casasolo.es\/en\/2o-premio-concurso-internacional-para-el-diseno-de-la-nueva-sede-del-barcelona-institute-of-science-and-technology-bist\/","url":"https:\/\/casasolo.es\/en\/2o-premio-concurso-internacional-para-el-diseno-de-la-nueva-sede-del-barcelona-institute-of-science-and-technology-bist\/","name":"2\u00ba Premio. Concurso internacional para el dise\u00f1o de la nueva sede del Barcelona Institute of Science and Technology BIST - CASA SOLO arquitectos","isPartOf":{"@id":"https:\/\/casasolo.es\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casasolo.es\/en\/2o-premio-concurso-internacional-para-el-diseno-de-la-nueva-sede-del-barcelona-institute-of-science-and-technology-bist\/#primaryimage"},"image":{"@id":"https:\/\/casasolo.es\/en\/2o-premio-concurso-internacional-para-el-diseno-de-la-nueva-sede-del-barcelona-institute-of-science-and-technology-bist\/#primaryimage"},"thumbnailUrl":"https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Exterior-01_BAAS-MONEO-BROCK-CASASOLO.jpeg","datePublished":"2021-11-05T07:56:00+00:00","dateModified":"2022-09-06T09:02:40+00:00","breadcrumb":{"@id":"https:\/\/casasolo.es\/en\/2o-premio-concurso-internacional-para-el-diseno-de-la-nueva-sede-del-barcelona-institute-of-science-and-technology-bist\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casasolo.es\/en\/2o-premio-concurso-internacional-para-el-diseno-de-la-nueva-sede-del-barcelona-institute-of-science-and-technology-bist\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/casasolo.es\/en\/2o-premio-concurso-internacional-para-el-diseno-de-la-nueva-sede-del-barcelona-institute-of-science-and-technology-bist\/#primaryimage","url":"https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Exterior-01_BAAS-MONEO-BROCK-CASASOLO.jpeg","contentUrl":"https:\/\/casasolo.es\/wp-content\/uploads\/2022\/09\/Concurso-BIST-Exterior-01_BAAS-MONEO-BROCK-CASASOLO.jpeg","width":1181,"height":1181},{"@type":"BreadcrumbList","@id":"https:\/\/casasolo.es\/en\/2o-premio-concurso-internacional-para-el-diseno-de-la-nueva-sede-del-barcelona-institute-of-science-and-technology-bist\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/casasolo.es\/en\/"},{"@type":"ListItem","position":2,"name":"2\u00ba Premio. Concurso internacional para el dise\u00f1o de la nueva sede del Barcelona Institute of Science and Technology BIST"}]},{"@type":"WebSite","@id":"https:\/\/casasolo.es\/en\/#website","url":"https:\/\/casasolo.es\/en\/","name":"CASA SOLO arquitectos","description":"","publisher":{"@id":"https:\/\/casasolo.es\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casasolo.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/casasolo.es\/en\/#organization","name":"CASA SOLO arquitectos","url":"https:\/\/casasolo.es\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/casasolo.es\/en\/#\/schema\/logo\/image\/","url":"https:\/\/casasolo.es\/wp-content\/uploads\/2021\/10\/casasolo-logo.svg","contentUrl":"https:\/\/casasolo.es\/wp-content\/uploads\/2021\/10\/casasolo-logo.svg","caption":"CASA SOLO arquitectos"},"image":{"@id":"https:\/\/casasolo.es\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/casasolo.es\/en\/#\/schema\/person\/b41f2cfcd2692379bec3ae2da04002b0","name":"PH STUDIO","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/casasolo.es\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1c4771d67760d55d3bbd348e233bc4adcb9d3ee6a3f78131e3dc5300381a2979?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1c4771d67760d55d3bbd348e233bc4adcb9d3ee6a3f78131e3dc5300381a2979?s=96&d=mm&r=g","caption":"PH STUDIO"},"url":"https:\/\/casasolo.es\/en\/author\/ph-studio\/"}]}},"_links":{"self":[{"href":"https:\/\/casasolo.es\/en\/wp-json\/wp\/v2\/posts\/4797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casasolo.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casasolo.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casasolo.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/casasolo.es\/en\/wp-json\/wp\/v2\/comments?post=4797"}],"version-history":[{"count":0,"href":"https:\/\/casasolo.es\/en\/wp-json\/wp\/v2\/posts\/4797\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casasolo.es\/en\/wp-json\/wp\/v2\/media\/4807"}],"wp:attachment":[{"href":"https:\/\/casasolo.es\/en\/wp-json\/wp\/v2\/media?parent=4797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casasolo.es\/en\/wp-json\/wp\/v2\/categories?post=4797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casasolo.es\/en\/wp-json\/wp\/v2\/tags?post=4797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}