{"id":2035,"date":"2020-04-07T11:58:25","date_gmt":"2020-04-07T11:58:25","guid":{"rendered":"http:\/\/casasolo.es\/?p=2035"},"modified":"2020-04-07T11:58:25","modified_gmt":"2020-04-07T11:58:25","slug":"la-arquitectura-del-covid-19","status":"publish","type":"post","link":"https:\/\/casasolo.es\/en\/la-arquitectura-del-covid-19\/","title":{"rendered":"La \u201carquitectura\u201d de la COVID-19"},"content":{"rendered":"<p><!--:es--><br \/>\nSorprendi\u00f3 a todo el mundo, arquitectos incluidos, que en Wuhan 7.000 trabajadores empezaran a construir el Hospital Huoshenshan de 1000 camas, que iba a estar terminado en 10 d\u00edas. En otro distrito de Wuhan, de forma solapada, iniciaron la construcci\u00f3n del Hospital Lieshenshan de 1.600 camas, que entr\u00f3 en funcionamiento una semana m\u00e1s tarde. China ya ten\u00eda experiencia en este tipo de situaciones. En 2003, para combatir la epidemia de SARS, en Beijing se hab\u00eda construido un hospital en s\u00f3lo 7 d\u00edas. Al principio, cuando el Dr. Li Wanliang detect\u00f3 varios casos de una neumon\u00eda at\u00edpica, las autoridades no le prestaron la atenci\u00f3n debida. Pero desde el 20 de enero, en que se declar\u00f3 el estado de emergencia y se confin\u00f3 a toda la poblaci\u00f3n de la provincia de Hubei,  China tom\u00f3 decisiones acertadas para controlar la epidemia. <\/p>\n<p>La epidemia se transform\u00f3 en pandemia. Apenas dos meses m\u00e1s tarde, un nuevo  coronavirus muy agresivo de alta morbilidad, ya identificado como SARS-CoV-2,  se ha diseminado por dos centenares de pa\u00edses de todo el mundo. Tarde y mal, en muchos de ellos, se han establecido restricciones de movilidad y controles insuficientes en muchos casos, que han conducido a un estr\u00e9s de sus sistemas sanitarios jam\u00e1s experimentado hasta ahora. Las medidas tomadas, y sus consecuencias de todo tipo, no se podr\u00e1n evaluar hasta que se consiga el objetivo primordial de control de la pandemia. Las formas de combatirla han sido diversas, seg\u00fan las estructuras pol\u00edticas, sociales, econ\u00f3micas y sanitarias de cada estado.<br \/>\nSer\u00eda una temeridad no aprender de las lecciones recibidas, y no establecer los medios y las soluciones necesarias para evitar en el futuro los errores cometidos. La toma de decisiones deber\u00e1 hacerse mediante un consenso amplio, tanto a nivel local como global. <\/p>\n<p>La pandemia, que afecta de modo m\u00e1s severo a las zonas urbanas, probablemente conducir\u00e1 a un debate sobre su densidad y planificaci\u00f3n. El confinamiento tambi\u00e9n debe proporcionar datos sobre el uso y carencias de los diversos tipos actuales de vivienda, tanto individual como colectiva. Se requerir\u00e1n aportaciones desde todas las disciplinas. La urban\u00edstica y la arquitectura est\u00e1n, sin duda, entre ellas. <\/p>\n<p>A estas dos disciplinas, y especialmente desde la planificaci\u00f3n sanitaria y el dise\u00f1o de hospitales, les he dedicado la mayor parte de mi trabajo hasta mi retirada de la primera l\u00ednea, hace unos a\u00f1os. Desde el confinamiento obligado, y admitido por convicci\u00f3n, he sentido la necesidad de compartir algunas reflexiones, centradas en esa parcela espec\u00edfica del conocimiento.<\/p>\n<p>En estos momentos de autodefensa contra la pandemia, la mayor\u00eda de los pa\u00edses afectados \u2013 y tambi\u00e9n aquellos que a\u00fan no han experimentado la COVID-19 con toda su crudeza \u2013 est\u00e1n abocando los m\u00e1ximos recursos para reforzar sus infraestructuras de salud, tal como hicieron en China hace ya m\u00e1s de dos meses. Se est\u00e1n instalando o realizando construcciones de todo tipo para apoyar a los hospitales y centros sanitarios ya establecidos. <\/p>\n<p>En diarios y publicaciones especializadas, se est\u00e1n publicando reportajes y art\u00edculos sobre c\u00f3mo se organizan estos dispositivos en diversos pa\u00edses. Al leerlos, me llam\u00f3  la atenci\u00f3n que a menudo se emplee el t\u00e9rmino arquitectura para referirse a ellos.   Lo primero que me vino a la mente fue la famosa frase escrita por el historiador y cr\u00edtico de arte Sir Nikolaus Pevsner: \u201cA bicycle shed is a building; Lincoln Cathedral is a piece of architecture\u201d.  La frase de Pevsner me permite distinguir entre dos v\u00edas de trabajo relativas a los hospitales que, siendo a lo mejor complementarias, debemos mantener vivas en el futuro. E incluso mucho m\u00e1s activas.<\/p>\n<p>Es evidente que los cobertizos para bicicletas son hoy tan necesarios, y alguien dir\u00eda que incluso m\u00e1s, que las catedrales. Y seg\u00fan que cobertizo para bicicletas tambi\u00e9n podr\u00eda ser considerado como arquitectura. Pero lo que en este momento creo que es interesante subrayar es la existencia de dos l\u00edneas de investigaci\u00f3n que no se deben confundir. En una tragedia como la que se est\u00e1 viviendo en todo el mundo es del todo imprescindible habilitar soluciones de emergencia. Son, en general, \u201ccobertizos de bicicletas\u201d, imprescindibles para poder sobrevivir en estos imprevisibles momentos de crisis.<\/p>\n<p>Esa es la primera l\u00ednea de trabajo que debe plantearse una vez se recupere la actividad de las empresas, que actualmente se ve mermada por disposiciones y decisiones colectivas, tomadas en beneficio de la salud p\u00fablica. En el caso de China, la r\u00e9plica del Hospital Xiaotangshan que se construy\u00f3 en Wuhan en s\u00f3lo diez d\u00edas, fue un \u201ccobertizo\u201d que ya ven\u00eda muy trabajado de experiencias anteriores, como el SARS de 2003. Ah\u00ed es donde entra la planificaci\u00f3n. Se deber\u00e1n planificar en las ciudades espacios libres para situaciones de emergencia, cercanos a los hospitales. Los solares a ellos destinados tambi\u00e9n deber\u00e1n disponer de espacios de reserva. En zonas urbanas densamente pobladas, la existencia en los alrededores de pabellones o instalaciones deportivas, podr\u00eda cumplir la misma funci\u00f3n que las zonas libres. A parte de las instalaciones y dispositivos militares, casi siempre precarios aunque de gran ayuda en muchos casos, se deben destinar recursos e imaginaci\u00f3n a potenciar soluciones civiles m\u00e1s humanizadas. A\u00fan en circunstancias tan dram\u00e1ticas como las actuales, y las que especialmente suceden en el norte de Italia, son de destacar algunas iniciativas como la del hospital de la Feria de Milano.<\/p>\n<p><a attid=\"2037\"  href=\"http:\/\/casasolo.es\/wp-content\/uploads\/2020\/06\/cas2.png\"><img fetchpriority=\"high\" decoding=\"async\" src=\"http:\/\/casasolo.es\/wp-content\/uploads\/2020\/06\/cas2.png\" alt=\"cas2\" width=\"540\" height=\"537\" class=\"alignnone size-full wp-image-2037\" srcset=\"https:\/\/casasolo.es\/wp-content\/uploads\/2020\/06\/cas2.png 540w, https:\/\/casasolo.es\/wp-content\/uploads\/2020\/06\/cas2-300x298.png 300w, https:\/\/casasolo.es\/wp-content\/uploads\/2020\/06\/cas2-150x150.png 150w\" sizes=\"(max-width: 540px) 100vw, 540px\" \/><\/a> <\/p>\n<p>Tambi\u00e9n en Milan, la iniciativa de dise\u00f1o para la reutilizaci\u00f3n de contenedores como m\u00f3dulos de aislamiento realizada por CRA Associati, es de car\u00e1cter menos local y m\u00e1s global. Iniciativas de este tipo, o como los m\u00f3dulos hinchables que fabrica Tecnodimensi\u00f3n en Girona, podr\u00edan ser impulsadas por organismos internacionales, incluso para mejorar la gesti\u00f3n presente de algunos programas de Naciones Unidas. Para ello ser\u00e1 necesario contar con profesionales sanitarios, ingenieros y arquitectos, especialmente preparados. <\/p>\n<p><a attid=\"2038\"  href=\"http:\/\/casasolo.es\/wp-content\/uploads\/2020\/06\/cas1.png\"><img decoding=\"async\" src=\"http:\/\/casasolo.es\/wp-content\/uploads\/2020\/06\/cas1.png\" alt=\"cas1\" width=\"529\" height=\"339\" class=\"alignnone size-full wp-image-2038\" srcset=\"https:\/\/casasolo.es\/wp-content\/uploads\/2020\/06\/cas1.png 529w, https:\/\/casasolo.es\/wp-content\/uploads\/2020\/06\/cas1-300x192.png 300w\" sizes=\"(max-width: 529px) 100vw, 529px\" \/><\/a><\/p>\n<p>La segunda l\u00ednea de trabajo deber\u00eda evitar ser contaminada por la anterior como producto de la urgencia y de las prisas, pues correr\u00eda el peligro de debilitarse. Es la de los nuevos hospitales, o los ya existentes que puedan tener previstas renovaciones o ampliaciones futuras. Es lo que, salvando la discusi\u00f3n de las bicicletas y la iglesia, se entiende por arquitectura hospitalaria. Incluso en la China Popular, se sabe distinguir entre un hospital de campa\u00f1a y un hospital como el Gulou de Nanjing  , por ejemplo.<br \/>\nDespu\u00e9s de la Guerra Civil, en una situaci\u00f3n de reconstrucci\u00f3n y de recuperaci\u00f3n econ\u00f3mica del pa\u00eds, el INSALUD de forma centralizada, y sobre todo a partir de los a\u00f1os Sesenta, construy\u00f3 en Espa\u00f1a algunos \u201ccobertizos para bicicletas\u201d. Casi siempre se levantaron en poco m\u00e1s de seis meses. Cumplieron con su cometido; pero eran hospitales de campa\u00f1a \u2013 de hecho lo eran, pero de otro tipo \u2013 y no creo que pudieran considerarse arquitectura. Adem\u00e1s, esos \u201chospitales kleenex\u201d de franjas azules y blancas, dan muchos problemas de mantenimiento y reparaci\u00f3n como ha podido comprobar la Generalitat de Catalunya, desde que asumi\u00f3 las competencias en 1981. <\/p>\n<p>Con el progresivo traspaso de competencias, en todas las Comunidades Aut\u00f3nomas casi siempre se recuper\u00f3 la arquitectura. Disponemos en nuestro pa\u00eds de excelentes arquitectos, y no s\u00f3lo especialistas, que han hecho de los hospitales espa\u00f1oles un referente a nivel europeo. No hace falta justificar aqu\u00ed el papel positivo de la arquitectura en las actividades humanas. Cualquier sociedad avanzada sabe distinguir, o debe, lo que las ra\u00edces hist\u00f3ricas, culturales y sociales le aportan. <\/p>\n<p><a attid=\"2036\"  href=\"http:\/\/casasolo.es\/wp-content\/uploads\/2020\/06\/cas.png\"><img decoding=\"async\" src=\"http:\/\/casasolo.es\/wp-content\/uploads\/2020\/06\/cas.png\" alt=\"cas\" width=\"540\" height=\"448\" class=\"alignnone size-full wp-image-2036\" srcset=\"https:\/\/casasolo.es\/wp-content\/uploads\/2020\/06\/cas.png 540w, https:\/\/casasolo.es\/wp-content\/uploads\/2020\/06\/cas-300x249.png 300w\" sizes=\"(max-width: 540px) 100vw, 540px\" \/><\/a><\/p>\n<p>De la situaci\u00f3n actual de carga intensiva a que los hospitales est\u00e1n sometidos debido a la pandemia, ser\u00e1 necesario extraer experiencia para aplicarla en el dise\u00f1o futuro. Algunas ideas de partida, tales como:<\/p>\n<p>a)\tAmbientes cada vez m\u00e1s humanizados, confort, luz natural, domesticidad, dado que las estancias medias posiblemente tender\u00e1n a incrementarse en el futuro.<br \/>\nb)\tZonas exteriores o terrazas donde los pacientes, y tambi\u00e9n el personal, puedan recuperar fuerzas.<br \/>\nc)\tLos espacios amplios y di\u00e1fanos, como grandes salas de espera, vest\u00edbulos o \u201chospital streets\u201d deber\u00e1n dotarse de tomas cl\u00ednicas para poder acoger camas .<br \/>\nd)\tLas dimensiones de las habitaciones est\u00e1ndar permitir\u00e1n intubar a un paciente.<br \/>\ne)\tSistemas adicionales de comunicaciones centralizados que permitan convertir camas est\u00e1ndar en puntos de cuidados intensivos controlados a distancia, s\u00f3lo con aportaci\u00f3n de los equipos necesarios (monitores, bombas de perfusi\u00f3n, respiradores, \u2026)<br \/>\nf)\tConjuntos f\u00e1ciles de ser aislados, tanto en las instalaciones como en lo f\u00edsico.<br \/>\ng)\tEdificios cercanos, o integrados en el conjunto, que puedan ser utilizados como residencia.<br \/>\nh)\tEvitar que se ocupen espacios di\u00e1fanos, tanto interiores como exteriores, mediante actuaciones no programadas. Necesidad de planificaci\u00f3n actualizada, mediante planes directores, que prevean situaciones catastr\u00f3ficas o de epidemias.<br \/>\ni)\tPriorizar, siempre que se pueda, soluciones bajas y \u201copen-ended\u201d frente a las concentradas.<br \/>\nj)\tCirculaciones horizontales, incluso sin diferenciar, frente a la multiplicidad de ascensores.<br \/>\nk)\tEstudio e implantaci\u00f3n de sistemas rob\u00f3ticos.<br \/>\nl)\tPriorizar la conectividad exterior 5G, a nivel de profesionales y tambi\u00e9n de los pacientes, sobre todo con el exterior en casos de aislamiento estricto.<br \/>\nm)\tAprovechar el dise\u00f1o Age-friendly Hospitals para modificar la percepci\u00f3n que los mayores van a tener de los hospitales como lugares inh\u00f3spitos y peligrosos.<\/p>\n<p>Las residencias de la tercera edad no deben quedar al margen de los sistemas de salud. La cruda realidad actual as\u00ed lo aconseja. No se pueden limitar s\u00f3lo a lo social. Muchas de las ideas que surjan para los centros sanitarios tambi\u00e9n se les deben aplicar. En ellas, en momentos de infecciones que provienen del exterior se ha comprobado que el mejor remedio es el confinamiento, incluso de los integrantes del personal que lo aceptasen. Esas contingencias, a partir de ahora, deber\u00e1n estar previstas.<\/p>\n<p>Los hospitales est\u00e1n respondiendo muy bien, aumentando su capacidad mediante reorganizaciones internas, con la imaginaci\u00f3n y el esfuerzo personal de los equipos de profesionales que los est\u00e1n utilizando.  Especializar hospitales, una soluci\u00f3n que emula los antiguos hospitales de Infecciosos, o habilitar dispositivos de soporte como los hoteles que tienen gran cantidad de habitaciones, complementan el esfuerzo de quienes est\u00e1n en contacto directo con el paciente. Pero sin personas y equipos no sirven para nada.<\/p>\n<p>Primero las personas, por ese orden. Es evidente que con las infraestructuras no basta. El personal que atendi\u00f3 a los pacientes del hospital construido en 10 d\u00edas junto a Vulcan Hill en Wuhan, era personal sanitario procedente del Ej\u00e9rcito Popular, unos 1400 m\u00e9dicos. Sin personal el hospital era imposible que funcione. El personal es el \u00fanico recurso que no se puede fabricar. Es insustituible, no son m\u00e1quinas. Debe cuidarse mucho m\u00e1s que ellas. La formaci\u00f3n y preparaci\u00f3n para casos como el presente, que pueden ser cada vez m\u00e1s frecuentes es indispensable. La consideraci\u00f3n que merece todo el personal, sanitario y no sanitario, que atiende a los dispositivos de salud, ya no s\u00f3lo econ\u00f3mica, tambi\u00e9n es primordial. <\/p>\n<p>En segundo lugar, los equipos. El sistema debe estar preparado y tener reservas, o la capacidad estrat\u00e9gica de conseguirlas en un corto espacio de tiempo, para enfrentarse a situaciones como la actual u otras parecidas. Veremos si a partir de este momento las administraciones y los gobiernos priorizan aquellos sectores y empresas que se han mostrado imprescindibles, o aquellas otras que hemos echado en falta por permitir que desaparecieran. O que desaparecer\u00e1n si despu\u00e9s de esto se sigue priorizando lo de siempre y no de llevan a cabo planes de rescate. El BCE, si es que Europa existe, debe poner en marcha las rotativas, aunque ello pudiera suponer una devaluaci\u00f3n del euro.<\/p>\n<p>La arquitectura forma parte de la cultura de un pa\u00eds, y debe preservarse. La defensa de la cultura en situaciones como la presente, no debe olvidarse. Nos ayuda a permanecer en nuestras casas benefici\u00e1ndonos del poder estabilizador de la m\u00fasica, el arte, la literatura, o la poes\u00eda. Un pa\u00eds con personas m\u00e1s educadas y responsables, necesitar\u00eda menos controles para mantener la salud p\u00fablica. Ya lo dec\u00eda esa pintada anarco que corr\u00eda all\u00e1 por los Sesenta del siglo pasado: \u201cM\u00e1s poes\u00eda y menos polic\u00eda\u201d. Pero ello requiere estructuras muy democr\u00e1ticas, y pol\u00edticas avanzadas. Este no es el lugar para debatirlo, aunque es apremiante.<\/p>\n<p><strong>Francesc Pernas Gal\u00ed, arquitecto. Presidente de CASA SOLO.<br \/>\n<\/strong><\/p>\n<p>Este art\u00edculo ha sido publicado en <a href=\"https:\/\/hospitecnia.com\/arquitectura\/diseno-y-reflexion\/arquitectura-covid19\/\">Hospitecnia<\/a>.<\/p>\n<p><em>V\u00e9ase por ejemplo: \u201dCinco arquitecturas urgentes y ef\u00edmeras para combatir el Coronavirus\u201d, Diario El Mundo, 1 de abril de 2020, o \u201cArquitectura contra la pandemia\u201d, Diario El Pa\u00eds, 2 de abril de 2020.<br \/>\n\u201cUn cobertizo para bicicletas es una construcci\u00f3n; la Catedral de Lincoln es una pieza de arquitectura\u201d.  Sir Nikolaus Pevsner (1902-1983), An outline of European architecture, 1945 p.XVI.<br \/>\nEl 31 de marzo se puso en marcha la primera fase del Ospedale Fiera Milano, como anexo dependiente del Policl\u00ednico de Mil\u00e1n, un dispositivo de m\u00e1s 200 camas de UCI, construido en 10 d\u00edas. \u201d\u2026No hicimos un hospital de campa\u00f1a como en el pasado, sino un hospital especializado, con respeto para el paciente y los trabajadores de la salud\u2026\u201d (Mensaje de Guido Bertolaso, asesor de la Lombard\u00eda para la emergencia del coronavirus).<br \/>\nCURA, Connected Unit for Respiratory Ailments, dise\u00f1ada por CRA, Carlo Ratti Asociados, con Italo Rota. Contenedores de 6&#215;2,4&#215;2,6m.reutilizados como m\u00f3dulos de aislamiento conectables, de los que se est\u00e1 produciendo un prototipo financiado por UniCredit. Ver foto 1.<br \/>\nDrum Tower del Hospital Gulou de Nanjing, Lemanarc SA, arquitectos. 2012. Ver foto 2.<br \/>\nHospital street, o espina, del Hospital Comarcal del Alt Pened\u00e9s, Casa S\u00f3lo Arquitectos. Un ejemplo con capacidad para que se aplique esta estrategia. Ver foto 3.<\/em><\/p>\n<p><!--:--><br \/>\n<!--:en--><br \/>\nThe COVID-19 pandemic, which affects a large part of the world, promotes reflection in all areas. Architecture and Planning are undoubtedly among them. The public health emergency placed a strong pressure on the healthcare system and infrastructures. Hospitals responded well due to the effort and creativity of the healthcare professionals. Healthcare personnel is the only resource that cannot be manufactured or built. <\/p>\n<p>The reuse of buildings and the addition of new facilities of all kinds was used to support and provide more space to hospitals. Some media use the term &#8220;architecture&#8221; to define these actions. During critical situations, it is essential to activate emergency solutions for survival. However, these solutions do not meet any of the qualities of today\u2019s healthcare architecture, neither for patients nor for those who work there. These solutions are, as Nikolaus Pevsner would say, &#8220;bicycle sheds&#8221;.<\/p>\n<p>The emergency must be the exception. We must work to improve our ability to respond in critical situations and use these experiences to advance, even faster, in the current lines of research of the healthcare architecture. The COVID-19 \u201carchitecture\u201d is not here to stay. You cannot even have a building for every disease. That is something of past centuries. Architecture, including healthcare architecture, is part of a country\u2019s culture. It must be preserved and, in times like these, it should not be forgotten when building health facilities.<\/p>\n<p>The article is written by <strong>Francesc Pernas Gal\u00ed, architect and president of CASA SOLO<br \/>\n<\/strong> and has been published on <a href=\"https:\/\/hospitecnia.com\/arquitectura\/diseno-y-reflexion\/arquitectura-covid19\/\">Hospitecnia<\/a>.<\/p>\n<p><!--:--><br \/>\n<!--:ca--><br \/>\nEs pot llegir la versi\u00f3 original de l&#8217;article escrit per <strong>Francesc Pernas Gal\u00ed, arquitecte i president de CASA SOLO<\/strong> <a href=\"http:\/\/casasolo.es\/?p=2035\">aqu\u00ed<\/a>.<br \/>\nAquesta informaci\u00f3 s\u2019ha publicat a <a href=\"https:\/\/hospitecnia.com\/arquitectura\/diseno-y-reflexion\/arquitectura-covid19\/\">Hospitecnia<\/a>.<\/p>\n<p><!--:--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sorprendi\u00f3 a todo el mundo, arquitectos incluidos, que en Wuhan 7.000 trabajadores empezaran a construir el Hospital Huoshenshan de 1000 camas, que iba a estar terminado en 10 d\u00edas. En otro distrito de Wuhan, de forma solapada, iniciaron la construcci\u00f3n del Hospital Lieshenshan de 1.600 camas, que entr\u00f3 en funcionamiento una semana m\u00e1s tarde. China [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":2036,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[85,6],"tags":[],"class_list":["post-2035","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-covid-19","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>arquitectura covid<\/title>\n<meta name=\"description\" content=\"arquitectura covid\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casasolo.es\/en\/la-arquitectura-del-covid-19\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"arquitectura covid\" \/>\n<meta property=\"og:description\" content=\"arquitectura covid\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casasolo.es\/en\/la-arquitectura-del-covid-19\/\" \/>\n<meta property=\"og:site_name\" content=\"CASA SOLO arquitectos\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-07T11:58:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casasolo.es\/wp-content\/uploads\/2020\/06\/cas.png\" \/>\n\t<meta property=\"og:image:width\" content=\"540\" \/>\n\t<meta property=\"og:image:height\" content=\"448\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"casaweb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"casaweb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/casasolo.es\/en\/la-arquitectura-del-covid-19\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/casasolo.es\/en\/la-arquitectura-del-covid-19\/\"},\"author\":{\"name\":\"casaweb\",\"@id\":\"https:\/\/casasolo.es\/en\/#\/schema\/person\/5fc60cf44aa387460af4ccaa862ac1b4\"},\"headline\":\"La \u201carquitectura\u201d de la COVID-19\",\"datePublished\":\"2020-04-07T11:58:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/casasolo.es\/en\/la-arquitectura-del-covid-19\/\"},\"wordCount\":2637,\"publisher\":{\"@id\":\"https:\/\/casasolo.es\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/casasolo.es\/en\/la-arquitectura-del-covid-19\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2020\/06\/cas.png\",\"articleSection\":[\"Covid-19\",\"Noticias Corporativas\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/casasolo.es\/en\/la-arquitectura-del-covid-19\/\",\"url\":\"https:\/\/casasolo.es\/en\/la-arquitectura-del-covid-19\/\",\"name\":\"arquitectura covid\",\"isPartOf\":{\"@id\":\"https:\/\/casasolo.es\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/casasolo.es\/en\/la-arquitectura-del-covid-19\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/casasolo.es\/en\/la-arquitectura-del-covid-19\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2020\/06\/cas.png\",\"datePublished\":\"2020-04-07T11:58:25+00:00\",\"description\":\"arquitectura covid\",\"breadcrumb\":{\"@id\":\"https:\/\/casasolo.es\/en\/la-arquitectura-del-covid-19\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/casasolo.es\/en\/la-arquitectura-del-covid-19\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/casasolo.es\/en\/la-arquitectura-del-covid-19\/#primaryimage\",\"url\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2020\/06\/cas.png\",\"contentUrl\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2020\/06\/cas.png\",\"width\":540,\"height\":448},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/casasolo.es\/en\/la-arquitectura-del-covid-19\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/casasolo.es\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La \u201carquitectura\u201d de la COVID-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/casasolo.es\/en\/#website\",\"url\":\"https:\/\/casasolo.es\/en\/\",\"name\":\"CASA SOLO arquitectos\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/casasolo.es\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/casasolo.es\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/casasolo.es\/en\/#organization\",\"name\":\"CASA SOLO arquitectos\",\"url\":\"https:\/\/casasolo.es\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/casasolo.es\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2021\/10\/casasolo-logo.svg\",\"contentUrl\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2021\/10\/casasolo-logo.svg\",\"caption\":\"CASA SOLO arquitectos\"},\"image\":{\"@id\":\"https:\/\/casasolo.es\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/casasolo.es\/en\/#\/schema\/person\/5fc60cf44aa387460af4ccaa862ac1b4\",\"name\":\"casaweb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/casasolo.es\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fc9cf1dfa9383b5d06e9ea4952a17ca69d4f4a2f3a07f60d4b52a5cd6e11ca07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fc9cf1dfa9383b5d06e9ea4952a17ca69d4f4a2f3a07f60d4b52a5cd6e11ca07?s=96&d=mm&r=g\",\"caption\":\"casaweb\"},\"url\":\"https:\/\/casasolo.es\/en\/author\/casaweb\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"arquitectura covid","description":"arquitectura covid","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casasolo.es\/en\/la-arquitectura-del-covid-19\/","og_locale":"en_US","og_type":"article","og_title":"arquitectura covid","og_description":"arquitectura covid","og_url":"https:\/\/casasolo.es\/en\/la-arquitectura-del-covid-19\/","og_site_name":"CASA SOLO arquitectos","article_published_time":"2020-04-07T11:58:25+00:00","og_image":[{"width":540,"height":448,"url":"https:\/\/casasolo.es\/wp-content\/uploads\/2020\/06\/cas.png","type":"image\/png"}],"author":"casaweb","twitter_card":"summary_large_image","twitter_misc":{"Written by":"casaweb","Est. reading time":"13 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/casasolo.es\/en\/la-arquitectura-del-covid-19\/#article","isPartOf":{"@id":"https:\/\/casasolo.es\/en\/la-arquitectura-del-covid-19\/"},"author":{"name":"casaweb","@id":"https:\/\/casasolo.es\/en\/#\/schema\/person\/5fc60cf44aa387460af4ccaa862ac1b4"},"headline":"La \u201carquitectura\u201d de la COVID-19","datePublished":"2020-04-07T11:58:25+00:00","mainEntityOfPage":{"@id":"https:\/\/casasolo.es\/en\/la-arquitectura-del-covid-19\/"},"wordCount":2637,"publisher":{"@id":"https:\/\/casasolo.es\/en\/#organization"},"image":{"@id":"https:\/\/casasolo.es\/en\/la-arquitectura-del-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/casasolo.es\/wp-content\/uploads\/2020\/06\/cas.png","articleSection":["Covid-19","Noticias Corporativas"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/casasolo.es\/en\/la-arquitectura-del-covid-19\/","url":"https:\/\/casasolo.es\/en\/la-arquitectura-del-covid-19\/","name":"arquitectura covid","isPartOf":{"@id":"https:\/\/casasolo.es\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casasolo.es\/en\/la-arquitectura-del-covid-19\/#primaryimage"},"image":{"@id":"https:\/\/casasolo.es\/en\/la-arquitectura-del-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/casasolo.es\/wp-content\/uploads\/2020\/06\/cas.png","datePublished":"2020-04-07T11:58:25+00:00","description":"arquitectura covid","breadcrumb":{"@id":"https:\/\/casasolo.es\/en\/la-arquitectura-del-covid-19\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casasolo.es\/en\/la-arquitectura-del-covid-19\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/casasolo.es\/en\/la-arquitectura-del-covid-19\/#primaryimage","url":"https:\/\/casasolo.es\/wp-content\/uploads\/2020\/06\/cas.png","contentUrl":"https:\/\/casasolo.es\/wp-content\/uploads\/2020\/06\/cas.png","width":540,"height":448},{"@type":"BreadcrumbList","@id":"https:\/\/casasolo.es\/en\/la-arquitectura-del-covid-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/casasolo.es\/en\/"},{"@type":"ListItem","position":2,"name":"La \u201carquitectura\u201d de la COVID-19"}]},{"@type":"WebSite","@id":"https:\/\/casasolo.es\/en\/#website","url":"https:\/\/casasolo.es\/en\/","name":"CASA SOLO arquitectos","description":"","publisher":{"@id":"https:\/\/casasolo.es\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casasolo.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/casasolo.es\/en\/#organization","name":"CASA SOLO arquitectos","url":"https:\/\/casasolo.es\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/casasolo.es\/en\/#\/schema\/logo\/image\/","url":"https:\/\/casasolo.es\/wp-content\/uploads\/2021\/10\/casasolo-logo.svg","contentUrl":"https:\/\/casasolo.es\/wp-content\/uploads\/2021\/10\/casasolo-logo.svg","caption":"CASA SOLO arquitectos"},"image":{"@id":"https:\/\/casasolo.es\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/casasolo.es\/en\/#\/schema\/person\/5fc60cf44aa387460af4ccaa862ac1b4","name":"casaweb","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/casasolo.es\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fc9cf1dfa9383b5d06e9ea4952a17ca69d4f4a2f3a07f60d4b52a5cd6e11ca07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fc9cf1dfa9383b5d06e9ea4952a17ca69d4f4a2f3a07f60d4b52a5cd6e11ca07?s=96&d=mm&r=g","caption":"casaweb"},"url":"https:\/\/casasolo.es\/en\/author\/casaweb\/"}]}},"_links":{"self":[{"href":"https:\/\/casasolo.es\/en\/wp-json\/wp\/v2\/posts\/2035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casasolo.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casasolo.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casasolo.es\/en\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/casasolo.es\/en\/wp-json\/wp\/v2\/comments?post=2035"}],"version-history":[{"count":0,"href":"https:\/\/casasolo.es\/en\/wp-json\/wp\/v2\/posts\/2035\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casasolo.es\/en\/wp-json\/wp\/v2\/media\/2036"}],"wp:attachment":[{"href":"https:\/\/casasolo.es\/en\/wp-json\/wp\/v2\/media?parent=2035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casasolo.es\/en\/wp-json\/wp\/v2\/categories?post=2035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casasolo.es\/en\/wp-json\/wp\/v2\/tags?post=2035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}