{"id":1496,"date":"2017-02-10T14:49:41","date_gmt":"2017-02-10T14:49:41","guid":{"rendered":"http:\/\/casasolo.es\/?p=1496"},"modified":"2017-02-10T14:49:41","modified_gmt":"2017-02-10T14:49:41","slug":"ii-edificios-hospitalarios-de-consumo-casi-nulo","status":"publish","type":"post","link":"https:\/\/casasolo.es\/en\/ii-edificios-hospitalarios-de-consumo-casi-nulo\/","title":{"rendered":"Edificios hospitalarios de consumo casi nulo"},"content":{"rendered":"<p><!--:es--><\/p>\n<p>El dise\u00f1o de edificios hospitalarios de consumo casi nulo toma cada vez m\u00e1s importancia en la arquitectura actual, ya que se trata de una tipolog\u00eda de edificaci\u00f3n p\u00fablica que se encuentra en funcionamiento las 24 horas del d\u00eda y con grandes requerimientos tecnol\u00f3gicos, donde el ahorro energ\u00e9tico adquiere un papel protagonista.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" src=\"http:\/\/casasolo.es\/wp-content\/uploads\/2016\/10\/nuevo-centro-hospitalario-luxemburgo-00.jpg\" alt=\"nuevo-centro-hospitalario-luxemburgo-00\" width=\"1200\" height=\"625\" class=\"alignnone size-full wp-image-1418\" srcset=\"https:\/\/casasolo.es\/wp-content\/uploads\/2016\/10\/nuevo-centro-hospitalario-luxemburgo-00.jpg 1200w, https:\/\/casasolo.es\/wp-content\/uploads\/2016\/10\/nuevo-centro-hospitalario-luxemburgo-00-300x156.jpg 300w, https:\/\/casasolo.es\/wp-content\/uploads\/2016\/10\/nuevo-centro-hospitalario-luxemburgo-00-1024x533.jpg 1024w, https:\/\/casasolo.es\/wp-content\/uploads\/2016\/10\/nuevo-centro-hospitalario-luxemburgo-00-768x400.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p>Tanto la Estrategia Europea 2020 como la Estrategia Catalana para la Renovaci\u00f3n Energ\u00e9tica de los Edificios (ECREE) plantean la redirecci\u00f3n de la arquitectura hacia una vertiente m\u00e1s sostenible, que consuma menos energ\u00eda y promueva el uso de energ\u00edas renovables para afrontar el cambio clim\u00e1tico.<\/p>\n<p>Hoy en d\u00eda el sector de la edificaci\u00f3n consume el 40% del total de la energ\u00eda en la Uni\u00f3n Europea y se estima que siga creciendo. Por este motivo en CASA Solo trabajamos en el dise\u00f1o de centros sanitarios que minimicen la demanda energ\u00e9tica y el potencien el uso de fuentes de energ\u00edas renovables.<\/p>\n<p>Veamos los aspectos clave a tener en cuenta en el dise\u00f1o de edificios hospitalarios de consumo casi nulo.<\/p>\n<h2>Reducci\u00f3n de la demanda energ\u00e9tica<\/h2>\n<p>Minimizar el consumo energ\u00e9tico de los hospitales es esencial para lograr edificios hospitalarios de consumo casi nulo. Para conseguir este objetivo y contribuir al ahorro energ\u00e9tico existen toda una serie de posibilidades arquitect\u00f3nicas y constructivas a tener en cuenta.<\/p>\n<h3>Preexistencias y orientaci\u00f3n solar<\/h3>\n<p>El primero de los aspectos a valorar en el momento de dise\u00f1ar un hospital es su entorno y orientaci\u00f3n. Tras realizar un an\u00e1lisis de las preexistencias se obtienen estrategias de actuaci\u00f3n para adaptar el edificio al lugar, en la medida de lo posible.<\/p>\n<p>Ser\u00e1n de especial importancia factores como la inclinaci\u00f3n del solar la presencia de vegetaci\u00f3n, para plantear alternativas como el aprovechamiento de la inercia t\u00e9rmica del terreno o bien la creaci\u00f3n de espacios sombr\u00edos y frescos en verano.<\/p>\n<p>La orientaci\u00f3n tambi\u00e9n tomar\u00e1 un papel muy relevante dada la gran variedad de espacios que presenta un centro sanitario y sus distintos requerimientos de iluminaci\u00f3n, desde la entrada de luz natural en las habitaciones de los pacientes hasta el hermetismo de los quir\u00f3fanos y las zonas m\u00e1s delicadas. <\/p>\n<h3>Captaci\u00f3n y almacenamiento de energ\u00eda<\/h3>\n<p>Los edificios hospitalarios de consumo casi nulo tambi\u00e9n se caracterizan por la incorporaci\u00f3n de sistemas de captaci\u00f3n y almacenamiento de energ\u00eda de origen renovable, como por ejemplo placas solares o fotovoltaicas, e\u00f3lica, aerotermia, geotermia, biomasa o cogeneraci\u00f3n. <\/p>\n<p>Dependiendo de la latitud, asoleamiento y orograf\u00eda del solar ser\u00e1n m\u00e1s adecuados unos mecanismos de captaci\u00f3n y almacenamiento de energ\u00eda u otros. El aprovechamiento de la inercia t\u00e9rmica del terreno, el uso de la geotermia o la buena resoluci\u00f3n constructiva de la envolvente del edificio son algunos ejemplos que mejoran considerablemente el ahorro energ\u00e9tico de un hospital.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/casasolo.es\/wp-content\/uploads\/2017\/02\/edificios-hospitalarios-consumo-casi-nulo-00.jpg\" alt=\"edificios-hospitalarios-consumo-casi-nulo-00\" width=\"1200\" height=\"708\" class=\"alignnone size-full wp-image-1499\" srcset=\"https:\/\/casasolo.es\/wp-content\/uploads\/2017\/02\/edificios-hospitalarios-consumo-casi-nulo-00.jpg 1200w, https:\/\/casasolo.es\/wp-content\/uploads\/2017\/02\/edificios-hospitalarios-consumo-casi-nulo-00-300x177.jpg 300w, https:\/\/casasolo.es\/wp-content\/uploads\/2017\/02\/edificios-hospitalarios-consumo-casi-nulo-00-1024x604.jpg 1024w, https:\/\/casasolo.es\/wp-content\/uploads\/2017\/02\/edificios-hospitalarios-consumo-casi-nulo-00-768x453.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<h3> El aislamiento t\u00e9rmico<\/h3>\n<p>El aislamiento t\u00e9rmico es tambi\u00e9n un aspecto clave en la construcci\u00f3n de edificios hospitalarios de consumo casi nulo, ya que permite mantener la temperatura interior del centro sanitario consumiendo menos energ\u00eda y maximizando la eficiencia de los sistemas de climatizaci\u00f3n.<\/p>\n<p>En funci\u00f3n del sistema constructivo empleado para la el dise\u00f1o y ejecuci\u00f3n del hospital se emplear\u00e1 un grosor y tipo de aislamiento u otro, para de este modo cumplir con las exigencias de como m\u00ednimo el confort t\u00e9rmico exigido por el c\u00f3digo t\u00e9cnico y proporcionar a los usuarios una estancia agradable con menor consumo energ\u00e9tico.<\/p>\n<p>Con frecuencia nos encontramos con edificios hospitalarios que cuentan con un aislamiento t\u00e9rmico inferior al necesario, debido a que son infraestructuras antiguas o que se quiere ahorrar en costes iniciales que no son sustanciales.  <\/p>\n<p>Sin embargo, la elecci\u00f3n de un buen aislamiento t\u00e9rmico es una inversi\u00f3n de cara al futuro que un edificio de la magnitud de un hospital amortiza en muy pocos a\u00f1os con el ahorro energ\u00e9tico que genera. Esta amortizaci\u00f3n se mejorar\u00e1 con los incrementos de los precios de la energ\u00eda que ya estamos empezando a experimentar en Espa\u00f1a este 2017.<\/p>\n<p>Tambi\u00e9n cabe destacar la importancia de una buena resoluci\u00f3n t\u00e9cnica del edificio, garantizando en todo momento la continuidad del aislamiento en toda la envolvente para evitar de este modo los puentes t\u00e9rmicos. Para ello la utilizaci\u00f3n de fachadas ventiladas ha sido una gran apuesta en todos los proyectos desarrollados por CASA Solo desde un inicio.<\/p>\n<h3>La ventilaci\u00f3n<\/h3>\n<p>La ventilaci\u00f3n de un hospital tambi\u00e9n deber\u00eda ser un requerimiento imprescindible para dotar a los usuarios de una estancia agradable y para lograr edificios hospitalarios de consumo casi nulo, especialmente en primavera y oto\u00f1o, cuando una buena ventilaci\u00f3n natural puede reducir en gran medida el aporte energ\u00e9tico para la refrigeraci\u00f3n. <\/p>\n<p>Esta ventilaci\u00f3n deber\u00eda ser posible en estancias m\u00e1s p\u00fablicas como habitaciones, consultas, zonas de espera y circulaciones. En \u00e1reas cr\u00edticas las normativas de ventilaci\u00f3n y seguridad sanitaria establecen que todo el volumen de aire debe ser filtrado y movido artificialmente, siempre con sistemas de climatizaci\u00f3n lo m\u00e1s eficientes posibles.<\/p>\n<p>Con el objetivo de potenciar la ventilaci\u00f3n natural del edificio es necesario tener en cuenta la disposici\u00f3n estrat\u00e9gica de las aberturas y la introducci\u00f3n de elementos o geometr\u00edas que permitan que el hospital respire, como ahora patios interiores que mejoran la calidad del edificio.<\/p>\n<h3>El agua<\/h3>\n<p>El \u00faltimo de los aspectos clave para reducir la demanda energ\u00e9tica en edificios hospitalarios de consumo casi nulo es el ahorro de agua mediante sus diferentes opciones de reutilizaci\u00f3n.<\/p>\n<p>Para maximizar el ahorro de agua es recomendable recolectar el agua de la lluvia y reaprovecharla para el riego de las zonas ajardinadas del hospital o bien para ciertos aparatos sanitarios, mediante un filtraje previo.<\/p>\n<p>En cuanto a las aguas grises (lavamanos y duchas) es recomendable hacer una red separativa de las aguas negras, para poder reaprovecharlas para su uso en retretes, siempre con un previo tratamiento. <\/p>\n<p>Esta medida tan sencilla puede suponer un gran ahorro de agua y deber\u00eda extenderse a otros tipos de edificios donde, como en los hospitales, el consumo de agua es muy elevado.<\/p>\n<p>Para complementar estos mecanismos de ahorro de agua tambi\u00e9n es posible instalar sistemas de regulaci\u00f3n en la grifer\u00eda de los ba\u00f1os y aseos del centro sanitario, para de este modo minimizar el consumo de agua diario.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/casasolo.es\/wp-content\/uploads\/2017\/02\/edificios-hospitalarios-consumo-casi-nulo-01.jpg\" alt=\"edificios-hospitalarios-consumo-casi-nulo-01\" width=\"1200\" height=\"795\" class=\"alignnone size-full wp-image-1501\" srcset=\"https:\/\/casasolo.es\/wp-content\/uploads\/2017\/02\/edificios-hospitalarios-consumo-casi-nulo-01.jpg 1200w, https:\/\/casasolo.es\/wp-content\/uploads\/2017\/02\/edificios-hospitalarios-consumo-casi-nulo-01-300x199.jpg 300w, https:\/\/casasolo.es\/wp-content\/uploads\/2017\/02\/edificios-hospitalarios-consumo-casi-nulo-01-1024x678.jpg 1024w, https:\/\/casasolo.es\/wp-content\/uploads\/2017\/02\/edificios-hospitalarios-consumo-casi-nulo-01-768x509.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<h2>Utilizaci\u00f3n de energ\u00edas renovables <\/h2>\n<p>Junto con la reducci\u00f3n de la demanda energ\u00e9tica de un hospital tambi\u00e9n es esencial plantear el uso de energ\u00edas renovables en el mismo.<\/p>\n<p>Algunas de las opciones m\u00e1s comunes son los paneles solares fotovoltaicos, t\u00e9rmicos y termodin\u00e1micos, los cuales permiten generar electricidad o calentar el agua del edificio hospitalario.<\/p>\n<p>La energ\u00eda geot\u00e9rmica, procedente de la tierra, tambi\u00e9n es una alternativa interesante a contemplar puesto que permite grandes ahorros respecto a sistemas tradicionales de producci\u00f3n de agua fr\u00eda y caliente para los sistemas de climatizaci\u00f3n de un centro sanitario.<\/p>\n<p>Su inversi\u00f3n inicial elevada se amortiza en pocos a\u00f1os y supone un gran ahorro en combustibles f\u00f3siles.<\/p>\n<p>&#8212;&#8212;&#8212;-<\/p>\n<p>Como siempre, finalizar record\u00e1ndoos el compromiso de CASA Solo con el dise\u00f1o de espacios sanitarios eficientes y respetuosos con el medio ambiente.<\/p>\n<p>Como arquitectos, nuestro trabajo puede contribuir a mejorar la calidad de vida de los pacientes, familiares y profesionales, as\u00ed como al ahorro energ\u00e9tico y preservar los recursos naturales de nuestro planeta. <\/p>\n<p>Nosotros asumimos esta responsabilidad investigando cada d\u00eda y poniendo al servicio de nuestros clientes hospitalarios toda nuestra experiencia y conocimiento, para juntos conseguir mejorar la calidad y la eficiencia de la asistencia sanitaria.<\/p>\n<p><!--:--><\/p>\n<p><!--:en--><\/p>\n<p>The design of hospital buildings of almost zero consumption is becoming more important in the current architecture, since it is a typology of public building that is in operation 24 hours a day and with great technological requirements, where energy saving acquires a leading role.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" src=\"http:\/\/casasolo.es\/wp-content\/uploads\/2016\/10\/nuevo-centro-hospitalario-luxemburgo-00.jpg\" alt=\"nuevo-centro-hospitalario-luxemburgo-00\" width=\"1200\" height=\"625\" class=\"alignnone size-full wp-image-1418\" srcset=\"https:\/\/casasolo.es\/wp-content\/uploads\/2016\/10\/nuevo-centro-hospitalario-luxemburgo-00.jpg 1200w, https:\/\/casasolo.es\/wp-content\/uploads\/2016\/10\/nuevo-centro-hospitalario-luxemburgo-00-300x156.jpg 300w, https:\/\/casasolo.es\/wp-content\/uploads\/2016\/10\/nuevo-centro-hospitalario-luxemburgo-00-1024x533.jpg 1024w, https:\/\/casasolo.es\/wp-content\/uploads\/2016\/10\/nuevo-centro-hospitalario-luxemburgo-00-768x400.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p>Both the European Strategy 2020 and the Catalan Strategy for Energy Renewal of Buildings (ECREE) propose the redirection of architecture towards a more sustainable, energy-efficient and renewable energy use to tackle climate change.<\/p>\n<p>Today the building sector consumes 40% of the total energy in the European Union and is estimated to continue to grow. For this reason at CASA Solo we work in the design of health centers that minimize energy demand and boost the use of renewable energy sources.<\/p>\n<p>Let&#8217;s look at the key aspects to take into account in the design of hospital buildings of almost zero consumption.<\/p>\n<h2>Reducing energy demand<\/h2>\n<p>Minimizing the energy consumption of hospitals is essential to achieve hospital buildings of almost zero consumption. In order to achieve this objective and contribute to energy saving, there is a whole series of architectural and constructive possibilities to be taken into account.<\/p>\n<h3>Pre-existences and solar orientation<\/h3>\n<p>The first aspect to be assessed when designing a hospital is its environment and orientation. After performing an analysis of the pre-existences, strategies are obtained to adapt the building to the place, as far as possible.<\/p>\n<p>Of particular importance will be factors such as the slope of the site, the presence of vegetation, to propose alternatives such as the use of the thermal inertia of the land or the creation of shady and cool spaces in summer.<\/p>\n<p>The orientation will also play a very important role given the wide variety of spaces that a health center presents and its different lighting requirements, from the entrance of natural light in the patients&#8217; rooms to the impenetrability of the operating rooms and the most delicate areas.<\/p>\n<h3>Energy capture and storage<\/h3>\n<p>Hospital buildings of almost zero consumption are also characterized by the incorporation of systems of capture and storage of energy of renewable origin, such as solar or photovoltaic, wind, aerothermal, geothermal, biomass or cogeneration.<\/p>\n<p>Depending on the latitude, sunshine and terrain of the site there will be more suitable some mechanisms of capture and storage of energy or others. The use of the thermal inertia of the land, the use of geothermal energy or the good constructive resolution of the building envelope are some examples that will considerably improve the energy saving of a hospital.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/casasolo.es\/wp-content\/uploads\/2017\/02\/edificios-hospitalarios-consumo-casi-nulo-00.jpg\" alt=\"edificios-hospitalarios-consumo-casi-nulo-00\" width=\"1200\" height=\"708\" class=\"alignnone size-full wp-image-1499\" srcset=\"https:\/\/casasolo.es\/wp-content\/uploads\/2017\/02\/edificios-hospitalarios-consumo-casi-nulo-00.jpg 1200w, https:\/\/casasolo.es\/wp-content\/uploads\/2017\/02\/edificios-hospitalarios-consumo-casi-nulo-00-300x177.jpg 300w, https:\/\/casasolo.es\/wp-content\/uploads\/2017\/02\/edificios-hospitalarios-consumo-casi-nulo-00-1024x604.jpg 1024w, https:\/\/casasolo.es\/wp-content\/uploads\/2017\/02\/edificios-hospitalarios-consumo-casi-nulo-00-768x453.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<h3>Thermal insulation<\/h3>\n<p>Thermal insulation is also a key aspect in the construction of hospital buildings of almost zero consumption, since it allows to maintain the interior temperature of the health centre consuming less energy and maximizing the efficiency of the air conditioning systems.<\/p>\n<p>Depending on the construction system used for the design and execution of the hospital, a thickness and type of insulation or other will be used, in order to meet the requirements of at least the thermal comfort required by the technical code and provide users a pleasant stay with lower energy consumption.<\/p>\n<p>We often find hospital buildings that have a thermal insulation lower than necessary, because they are old infrastructures or there is an aim to save on initial costs that are not substantial.<\/p>\n<p>However, the choice of a good thermal insulation is a future investment that a building of the magnitude of a hospital amortizes in a few years with the energy savings it generates. This amortization will be improved with the increase in energy prices that we are already beginning to experience in Spain this 2017.<\/p>\n<p>It is also important to emphasize the importance of a good technical resolution of the building, guaranteeing the continuity of the insulation throughout the enclosure to avoid thermal bridges. For this, the use of ventilated facades has been a great bet on all the projects developed by CASA Solo from the outset.<\/p>\n<h3>Ventilation<\/h3>\n<p>The ventilation of a hospital should also be an essential requirement to provide users a pleasant stay and to achieve hospital buildings of almost zero consumption, especially in spring and autumn, when good natural ventilation can greatly reduce the energy supply to cooling.<\/p>\n<p>This ventilation should be possible in public places such as rooms, inquiries, waiting areas and circulations. In critical areas, ventilation and health safety regulations establish that the entire volume of air must be filtered and artificially moved, always with the most efficient air conditioning system.<\/p>\n<p>With the aim of enhancing the natural ventilation of the building, it is necessary to take into account the strategic layout of the openings and the introduction of elements or geometries that allow the hospital to breathe, as now interior courtyards that improve the quality of the building.<\/p>\n<h3> The water<\/h3>\n<p>The last of the key aspects to reduce the energy demand in hospital buildings of almost zero consumption is the saving of water through its different reuse options.<\/p>\n<p>In order to maximize water savings, it is advisable to collect the rainwater and reuse it for irrigation of the garden areas of the hospital or for certain sanitary appliances, by means of a previous filtration.<\/p>\n<p>As for gray water (sinks and showers) it is advisable to make a network separative of the black waters, to be able to reuse them for toilets, always with a previous treatment.<\/p>\n<p>This simple measure can be a great saving of water and should be extended to other types of buildings where, as in hospitals, water consumption is very high.<\/p>\n<p>To complement these mechanisms of water saving it is also possible to install regulation systems in the faucets of the bathrooms and toilets of the health centre, in order to minimize the daily water consumption.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/casasolo.es\/wp-content\/uploads\/2017\/02\/edificios-hospitalarios-consumo-casi-nulo-01.jpg\" alt=\"edificios-hospitalarios-consumo-casi-nulo-01\" width=\"1200\" height=\"795\" class=\"alignnone size-full wp-image-1501\" srcset=\"https:\/\/casasolo.es\/wp-content\/uploads\/2017\/02\/edificios-hospitalarios-consumo-casi-nulo-01.jpg 1200w, https:\/\/casasolo.es\/wp-content\/uploads\/2017\/02\/edificios-hospitalarios-consumo-casi-nulo-01-300x199.jpg 300w, https:\/\/casasolo.es\/wp-content\/uploads\/2017\/02\/edificios-hospitalarios-consumo-casi-nulo-01-1024x678.jpg 1024w, https:\/\/casasolo.es\/wp-content\/uploads\/2017\/02\/edificios-hospitalarios-consumo-casi-nulo-01-768x509.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<h2>Use of renewable energies<\/h2>\n<p>Along with the reduction of the energy demand of a hospital, it is also essential to consider the use of renewable energy in it.<\/p>\n<p>Some of the most common options are photovoltaic, thermal and thermodynamic solar panels, which allow to generate electricity or heat the water of the hospital building.<\/p>\n<p>Geothermal energy, coming from the earth, is also an interesting alternative to contemplate since it allows great savings over traditional systems of production of hot and cold water for the air conditioning systems of a health centre.<\/p>\n<p>Its high initial investment is amortized in few years and it represents a great saving in fossil fuels.<\/p>\n<p>&#8212;&#8212;&#8212;-<\/p>\n<p>As always, we would like to finish remembering the commitment of CASA Solo with the design of efficient sanitary spaces and respectful with the environment.<\/p>\n<p>As architects, our work can contribute to improve the quality of life of patients, families and professionals, as well as energy saving and preserving the natural resources of our planet.<\/p>\n<p>We assume this responsibility by investigating every day and putting at the service of our hospital clients all our experience and knowledge, together to improve the quality and efficiency of healthcare.<\/p>\n<p><!--:--><\/p>\n<p><!--:ca--><\/p>\n<p>El disseny d&#8217;edificis hospitalaris de consum gaireb\u00e9 nul pren cada vegada m\u00e9s import\u00e0ncia en l&#8217;arquitectura actual, ja que es tracta d&#8217;una tipologia d&#8217;edificaci\u00f3 p\u00fablica que es troba en funcionament les 24 hores del dia i amb grans requeriments tecnol\u00f2gics, on l&#8217;estalvi energ\u00e8tic adquireix un paper protagonista.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" src=\"http:\/\/casasolo.es\/wp-content\/uploads\/2016\/10\/nuevo-centro-hospitalario-luxemburgo-00.jpg\" alt=\"nuevo-centro-hospitalario-luxemburgo-00\" width=\"1200\" height=\"625\" class=\"alignnone size-full wp-image-1418\" srcset=\"https:\/\/casasolo.es\/wp-content\/uploads\/2016\/10\/nuevo-centro-hospitalario-luxemburgo-00.jpg 1200w, https:\/\/casasolo.es\/wp-content\/uploads\/2016\/10\/nuevo-centro-hospitalario-luxemburgo-00-300x156.jpg 300w, https:\/\/casasolo.es\/wp-content\/uploads\/2016\/10\/nuevo-centro-hospitalario-luxemburgo-00-1024x533.jpg 1024w, https:\/\/casasolo.es\/wp-content\/uploads\/2016\/10\/nuevo-centro-hospitalario-luxemburgo-00-768x400.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p>Tant l&#8217;Estrat\u00e8gia Europea 2020 com l&#8217;Estrat\u00e8gia Catalana per a la Renovaci\u00f3 Energ\u00e8tica dels Edificis (ECREE) plantegen la redirecci\u00f3 de l&#8217;arquitectura cap a una vessant m\u00e9s sostenible, que consumeixi menys energia i promogui l&#8217;\u00fas d&#8217;energies renovables per afrontar el canvi clim\u00e0tic.<\/p>\n<p>Avui dia el sector de l&#8217;edificaci\u00f3 consumeix el 40% del total de l&#8217;energia a la Uni\u00f3 Europea i s&#8217;estima que segueixi creixent. Per aquest motiu a CASA Solo treballem en el disseny de centres sanitaris que minimitzin la demanda energ\u00e8tica i potenci\u00efn l&#8217;\u00fas de fonts d&#8217;energia renovables.<\/p>\n<p>Vegem els aspectes clau a tenir en compte en el disseny d&#8217;edificis hospitalaris de consum gaireb\u00e9 nul.<\/p>\n<h2> Reducci\u00f3 de la demanda energ\u00e8tica<\/h2>\n<p>Minimitzar el consum energ\u00e8tic dels hospitals \u00e9s essencial per aconseguir edificis hospitalaris de consum gaireb\u00e9 nul. Per aconseguir aquest objectiu i contribuir a l&#8217;estalvi energ\u00e8tic existeixen tot un seguit de possibilitats arquitect\u00f2niques i constructives a tenir en compte.<\/p>\n<h3>Preexist\u00e8ncies i orientaci\u00f3 solar<\/h3>\n<p>El primer dels aspectes a valorar en el moment de dissenyar un hospital \u00e9s el seu entorn i orientaci\u00f3. Despr\u00e9s de realitzar una an\u00e0lisi de les preexist\u00e8ncies s&#8217;obtenen estrat\u00e8gies d&#8217;actuaci\u00f3 per adaptar l&#8217;edifici al lloc, en la mesura del possible.<\/p>\n<p>Seran d&#8217;especial import\u00e0ncia factors com la inclinaci\u00f3 del solar la pres\u00e8ncia de vegetaci\u00f3, per plantejar alternatives com l&#8217;aprofitament de la in\u00e8rcia t\u00e8rmica del terreny o b\u00e9 la creaci\u00f3 d&#8217;espais ombr\u00edvols i frescos a l&#8217;estiu.<\/p>\n<p>L&#8217;orientaci\u00f3 tamb\u00e9 prendr\u00e0 un paper molt rellevant donada la gran varietat d&#8217;espais que presenta un centre sanitari i els seus diferents requeriments d&#8217;il\u00b7luminaci\u00f3, des de l&#8217;entrada de llum natural a les habitacions dels pacients fins l&#8217;hermetisme dels quir\u00f2fans i les zones m\u00e9s delicades.<\/p>\n<h3> Captaci\u00f3 i emmagatzematge d&#8217;energia<\/h3>\n<p>Els edificis hospitalaris de consum gaireb\u00e9 nul tamb\u00e9 es caracteritzen per la incorporaci\u00f3 de sistemes de captaci\u00f3 i emmagatzematge d&#8217;energia d&#8217;origen renovable, com ara plaques solars o fotovoltaiques, e\u00f2lica, aerot\u00e8rmia, geot\u00e8rmia, biomassa o cogeneraci\u00f3.<\/p>\n<p>Depenent de la latitud, l&#8217;assolellament i l&#8217;orografia del solar, seran m\u00e9s adequats uns mecanismes de captaci\u00f3 i emmagatzematge d&#8217;energia o altres. L&#8217;aprofitament de la in\u00e8rcia t\u00e8rmica del terreny, l&#8217;\u00fas de la geot\u00e8rmia o la bona resoluci\u00f3 constructiva de l&#8217;envolupant de l&#8217;edifici, s\u00f3n alguns exemples que milloren considerablement l&#8217;estalvi energ\u00e8tic d&#8217;un hospital.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/casasolo.es\/wp-content\/uploads\/2017\/02\/edificios-hospitalarios-consumo-casi-nulo-00.jpg\" alt=\"edificios-hospitalarios-consumo-casi-nulo-00\" width=\"1200\" height=\"708\" class=\"alignnone size-full wp-image-1499\" srcset=\"https:\/\/casasolo.es\/wp-content\/uploads\/2017\/02\/edificios-hospitalarios-consumo-casi-nulo-00.jpg 1200w, https:\/\/casasolo.es\/wp-content\/uploads\/2017\/02\/edificios-hospitalarios-consumo-casi-nulo-00-300x177.jpg 300w, https:\/\/casasolo.es\/wp-content\/uploads\/2017\/02\/edificios-hospitalarios-consumo-casi-nulo-00-1024x604.jpg 1024w, https:\/\/casasolo.es\/wp-content\/uploads\/2017\/02\/edificios-hospitalarios-consumo-casi-nulo-00-768x453.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<h3> L&#8217;a\u00efllament t\u00e8rmic<\/h3>\n<p>L&#8217;a\u00efllament t\u00e8rmic \u00e9s tamb\u00e9 un aspecte clau en la construcci\u00f3 d&#8217;edificis hospitalaris de consum gaireb\u00e9 nul, ja que permet mantenir la temperatura interior del centre sanitari consumint menys energia i maximitzant l&#8217;efici\u00e8ncia dels sistemes de climatitzaci\u00f3.<\/p>\n<p>En funci\u00f3 del sistema constructiu emprat per a la el disseny i execuci\u00f3 de l&#8217;hospital es far\u00e0 servir un gruix i tipus d&#8217;a\u00efllament o un altre per, d&#8217;aquesta manera, complir amb les exig\u00e8ncies de com a m\u00ednim el confort t\u00e8rmic exigit pel codi t\u00e8cnic i proporcionar als usuaris una estada agradable amb menor consum energ\u00e8tic.<\/p>\n<p>Sovint ens trobem amb edificis hospitalaris que compten amb un a\u00efllament t\u00e8rmic inferior al necessari, a causa de tractar-se d&#8217;infraestructures antigues o de voler estalviar en costos inicials que no s\u00f3n substancials.<\/p>\n<p>No obstant aix\u00f2, l&#8217;elecci\u00f3 d&#8217;un bon a\u00efllament t\u00e8rmic \u00e9s una inversi\u00f3 de cara al futur que, en un edifici de la magnitud d&#8217;un hospital, s&#8217;amortitza en molt pocs anys amb l&#8217;estalvi energ\u00e8tic que genera. Aquesta amortitzaci\u00f3 es millorar\u00e0 amb els increments dels preus de l&#8217;energia que ja estem comen\u00e7ant a experimentar a Espanya aquest 2017.<\/p>\n<p>Tamb\u00e9 cal destacar la import\u00e0ncia d&#8217;una bona resoluci\u00f3 t\u00e8cnica de l&#8217;edifici, garantint en tot moment la continu\u00eftat de l&#8217;a\u00efllament en tota la envolupant per evitar d&#8217;aquesta manera els ponts t\u00e8rmics. Per a aix\u00f2, la utilitzaci\u00f3 de fa\u00e7anes ventilades ha estat una gran aposta en tots els projectes desenvolupats per CASA Solo des d&#8217;un inici.<\/p>\n<h3> La ventilaci\u00f3<\/h3>\n<p>La ventilaci\u00f3 d&#8217;un hospital tamb\u00e9 hauria de ser un requeriment imprescindible per dotar els usuaris d&#8217;una estada agradable i per aconseguir edificis hospitalaris de consum gaireb\u00e9 nul, especialment a la primavera i la tardor, quan una bona ventilaci\u00f3 natural pot reduir en gran mesura l&#8217;aportaci\u00f3 energ\u00e8tica per la refrigeraci\u00f3.<\/p>\n<p>Aquesta ventilaci\u00f3 hauria de ser possible en estances m\u00e9s p\u00fabliques com habitacions, consultes, zones d&#8217;espera i circulacions. En \u00e0rees cr\u00edtiques les normatives de ventilaci\u00f3 i seguretat sanit\u00e0ria estableixen que tot el volum d&#8217;aire ha de ser filtrat i mogut artificialment, sempre amb sistemes de climatitzaci\u00f3 el m\u00e9s eficients possible.<\/p>\n<p>Amb l&#8217;objectiu de potenciar la ventilaci\u00f3 natural de l&#8217;edifici cal tenir en compte la disposici\u00f3 estrat\u00e8gica de les obertures i la introducci\u00f3 d&#8217;elements o geometries que permetin que l&#8217;hospital respiri, com ara patis interiors que milloren la qualitat de l&#8217;edifici.<\/p>\n<h3> L&#8217;aigua<\/h3>\n<p>L&#8217;\u00faltim dels aspectes clau per a reduir la demanda energ\u00e8tica en edificis hospitalaris de consum gaireb\u00e9 nul \u00e9s l&#8217;estalvi d&#8217;aigua mitjan\u00e7ant les seves diferents opcions de reutilitzaci\u00f3.<\/p>\n<p>Per maximitzar l&#8217;estalvi d&#8217;aigua \u00e9s recomanable recol\u00b7lectar l&#8217;aigua de la pluja i reaprofitar-la per al reg de les zones enjardinades de l&#8217;hospital o b\u00e9 per certs aparells sanitaris, mitjan\u00e7ant un filtratge previ.<\/p>\n<p>Pel que fa a les aig\u00fces grises (rentamans i dutxes) \u00e9s recomanable fer una xarxa separativa de les aig\u00fces negres, per poder reaprofita-les  per al seu \u00fas a v\u00e0ters, sempre amb un previ tractament.<\/p>\n<p>Aquesta mesura tan senzilla pot suposar un gran estalvi d&#8217;aigua i s&#8217;hauria d&#8217;estendre a altres tipus d&#8217;edificis on, com en els hospitals, el consum d&#8217;aigua \u00e9s molt elevat.<\/p>\n<p>Per complementar aquests mecanismes d&#8217;estalvi d&#8217;aigua tamb\u00e9 \u00e9s possible instal\u00b7lar sistemes de regulaci\u00f3 a les aixetes dels banys i lavabos del centre sanitari, per d&#8217;aquesta manera minimitzar el consum d&#8217;aigua diari.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/casasolo.es\/wp-content\/uploads\/2017\/02\/edificios-hospitalarios-consumo-casi-nulo-01.jpg\" alt=\"edificios-hospitalarios-consumo-casi-nulo-01\" width=\"1200\" height=\"795\" class=\"alignnone size-full wp-image-1501\" srcset=\"https:\/\/casasolo.es\/wp-content\/uploads\/2017\/02\/edificios-hospitalarios-consumo-casi-nulo-01.jpg 1200w, https:\/\/casasolo.es\/wp-content\/uploads\/2017\/02\/edificios-hospitalarios-consumo-casi-nulo-01-300x199.jpg 300w, https:\/\/casasolo.es\/wp-content\/uploads\/2017\/02\/edificios-hospitalarios-consumo-casi-nulo-01-1024x678.jpg 1024w, https:\/\/casasolo.es\/wp-content\/uploads\/2017\/02\/edificios-hospitalarios-consumo-casi-nulo-01-768x509.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<h2> Utilitzaci\u00f3 d&#8217;energies renovables<\/h2>\n<p>Juntament amb la reducci\u00f3 de la demanda energ\u00e8tica d&#8217;un hospital tamb\u00e9 \u00e9s essencial plantejar l&#8217;\u00fas d&#8217;energies renovables en el mateix.<\/p>\n<p>Algunes de les opcions m\u00e9s comuns s\u00f3n els panells solars fotovoltaics, t\u00e8rmics i termodin\u00e0mics, els quals permeten generar electricitat o escalfar l&#8217;aigua de l&#8217;edifici hospitalari.<\/p>\n<p>L&#8217;energia geot\u00e8rmica, procedent de la terra, tamb\u00e9 \u00e9s una alternativa interessant a contemplar ja que permet grans estalvis respecte a sistemes tradicionals de producci\u00f3 d&#8217;aigua freda i calenta per als sistemes de climatitzaci\u00f3 d&#8217;un centre sanitari.<\/p>\n<p>La seva inversi\u00f3 inicial elevada s&#8217;amortitza en pocs anys i suposa un gran estalvi en combustibles f\u00f2ssils.<\/p>\n<p>&#8212;&#8212;&#8212;-<\/p>\n<p>Com sempre, finalitzar recordant el comprom\u00eds de CASA Solo amb el disseny d&#8217;espais sanitaris eficients i respectuosos amb el medi ambient.<\/p>\n<p>Com a arquitectes, el nostre treball pot contribuir a millorar la qualitat de vida dels pacients, familiars i professionals, aix\u00ed com l&#8217;estalvi energ\u00e8tic i preservar els recursos naturals del nostre planeta.<\/p>\n<p>Nosaltres assumim aquesta responsabilitat investigant cada dia i posant al servei dels nostres clients hospitalaris tota la nostra experi\u00e8ncia i coneixement, per junts aconseguir millorar la qualitat i l&#8217;efici\u00e8ncia de l&#8217;assist\u00e8ncia sanit\u00e0ria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El dise\u00f1o de edificios hospitalarios de consumo casi nulo toma cada vez m\u00e1s importancia en la arquitectura actual, ya que se trata de una tipolog\u00eda de edificaci\u00f3n p\u00fablica que se encuentra en funcionamiento las 24 horas del d\u00eda y con grandes requerimientos tecnol\u00f3gicos, donde el ahorro energ\u00e9tico adquiere un papel protagonista. Tanto la Estrategia Europea [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":1418,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[24,4],"tags":[],"class_list":["post-1496","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hospitales-sostenibles","category-investigacion-en-diseno-de-hospitales"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Edificios hospitalarios de consumo casi nulo<\/title>\n<meta name=\"description\" content=\"El dise\u00f1o de edificios hospitalarios de consumo casi nulo toma cada vez m\u00e1s importancia en la arquitectura actual.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casasolo.es\/en\/ii-edificios-hospitalarios-de-consumo-casi-nulo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Edificios hospitalarios de consumo casi nulo\" \/>\n<meta property=\"og:description\" content=\"El dise\u00f1o de edificios hospitalarios de consumo casi nulo toma cada vez m\u00e1s importancia en la arquitectura actual.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casasolo.es\/en\/ii-edificios-hospitalarios-de-consumo-casi-nulo\/\" \/>\n<meta property=\"og:site_name\" content=\"CASA SOLO arquitectos\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-10T14:49:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casasolo.es\/wp-content\/uploads\/2016\/10\/nuevo-centro-hospitalario-luxemburgo-00.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"625\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"casaweb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"casaweb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"18 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/casasolo.es\/en\/ii-edificios-hospitalarios-de-consumo-casi-nulo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/casasolo.es\/en\/ii-edificios-hospitalarios-de-consumo-casi-nulo\/\"},\"author\":{\"name\":\"casaweb\",\"@id\":\"https:\/\/casasolo.es\/en\/#\/schema\/person\/5fc60cf44aa387460af4ccaa862ac1b4\"},\"headline\":\"Edificios hospitalarios de consumo casi nulo\",\"datePublished\":\"2017-02-10T14:49:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/casasolo.es\/en\/ii-edificios-hospitalarios-de-consumo-casi-nulo\/\"},\"wordCount\":3681,\"publisher\":{\"@id\":\"https:\/\/casasolo.es\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/casasolo.es\/en\/ii-edificios-hospitalarios-de-consumo-casi-nulo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2016\/10\/nuevo-centro-hospitalario-luxemburgo-00.jpg\",\"articleSection\":[\"Hospitales sostenibles\",\"Investigaci\u00f3n en dise\u00f1o de hospitales\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/casasolo.es\/en\/ii-edificios-hospitalarios-de-consumo-casi-nulo\/\",\"url\":\"https:\/\/casasolo.es\/en\/ii-edificios-hospitalarios-de-consumo-casi-nulo\/\",\"name\":\"Edificios hospitalarios de consumo casi nulo\",\"isPartOf\":{\"@id\":\"https:\/\/casasolo.es\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/casasolo.es\/en\/ii-edificios-hospitalarios-de-consumo-casi-nulo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/casasolo.es\/en\/ii-edificios-hospitalarios-de-consumo-casi-nulo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2016\/10\/nuevo-centro-hospitalario-luxemburgo-00.jpg\",\"datePublished\":\"2017-02-10T14:49:41+00:00\",\"description\":\"El dise\u00f1o de edificios hospitalarios de consumo casi nulo toma cada vez m\u00e1s importancia en la arquitectura actual.\",\"breadcrumb\":{\"@id\":\"https:\/\/casasolo.es\/en\/ii-edificios-hospitalarios-de-consumo-casi-nulo\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/casasolo.es\/en\/ii-edificios-hospitalarios-de-consumo-casi-nulo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/casasolo.es\/en\/ii-edificios-hospitalarios-de-consumo-casi-nulo\/#primaryimage\",\"url\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2016\/10\/nuevo-centro-hospitalario-luxemburgo-00.jpg\",\"contentUrl\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2016\/10\/nuevo-centro-hospitalario-luxemburgo-00.jpg\",\"width\":1200,\"height\":625},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/casasolo.es\/en\/ii-edificios-hospitalarios-de-consumo-casi-nulo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/casasolo.es\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Edificios hospitalarios de consumo casi nulo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/casasolo.es\/en\/#website\",\"url\":\"https:\/\/casasolo.es\/en\/\",\"name\":\"CASA SOLO arquitectos\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/casasolo.es\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/casasolo.es\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/casasolo.es\/en\/#organization\",\"name\":\"CASA SOLO arquitectos\",\"url\":\"https:\/\/casasolo.es\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/casasolo.es\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2021\/10\/casasolo-logo.svg\",\"contentUrl\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2021\/10\/casasolo-logo.svg\",\"caption\":\"CASA SOLO arquitectos\"},\"image\":{\"@id\":\"https:\/\/casasolo.es\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/casasolo.es\/en\/#\/schema\/person\/5fc60cf44aa387460af4ccaa862ac1b4\",\"name\":\"casaweb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/casasolo.es\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fc9cf1dfa9383b5d06e9ea4952a17ca69d4f4a2f3a07f60d4b52a5cd6e11ca07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fc9cf1dfa9383b5d06e9ea4952a17ca69d4f4a2f3a07f60d4b52a5cd6e11ca07?s=96&d=mm&r=g\",\"caption\":\"casaweb\"},\"url\":\"https:\/\/casasolo.es\/en\/author\/casaweb\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Edificios hospitalarios de consumo casi nulo","description":"El dise\u00f1o de edificios hospitalarios de consumo casi nulo toma cada vez m\u00e1s importancia en la arquitectura actual.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casasolo.es\/en\/ii-edificios-hospitalarios-de-consumo-casi-nulo\/","og_locale":"en_US","og_type":"article","og_title":"Edificios hospitalarios de consumo casi nulo","og_description":"El dise\u00f1o de edificios hospitalarios de consumo casi nulo toma cada vez m\u00e1s importancia en la arquitectura actual.","og_url":"https:\/\/casasolo.es\/en\/ii-edificios-hospitalarios-de-consumo-casi-nulo\/","og_site_name":"CASA SOLO arquitectos","article_published_time":"2017-02-10T14:49:41+00:00","og_image":[{"width":1200,"height":625,"url":"https:\/\/casasolo.es\/wp-content\/uploads\/2016\/10\/nuevo-centro-hospitalario-luxemburgo-00.jpg","type":"image\/jpeg"}],"author":"casaweb","twitter_card":"summary_large_image","twitter_misc":{"Written by":"casaweb","Est. reading time":"18 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/casasolo.es\/en\/ii-edificios-hospitalarios-de-consumo-casi-nulo\/#article","isPartOf":{"@id":"https:\/\/casasolo.es\/en\/ii-edificios-hospitalarios-de-consumo-casi-nulo\/"},"author":{"name":"casaweb","@id":"https:\/\/casasolo.es\/en\/#\/schema\/person\/5fc60cf44aa387460af4ccaa862ac1b4"},"headline":"Edificios hospitalarios de consumo casi nulo","datePublished":"2017-02-10T14:49:41+00:00","mainEntityOfPage":{"@id":"https:\/\/casasolo.es\/en\/ii-edificios-hospitalarios-de-consumo-casi-nulo\/"},"wordCount":3681,"publisher":{"@id":"https:\/\/casasolo.es\/en\/#organization"},"image":{"@id":"https:\/\/casasolo.es\/en\/ii-edificios-hospitalarios-de-consumo-casi-nulo\/#primaryimage"},"thumbnailUrl":"https:\/\/casasolo.es\/wp-content\/uploads\/2016\/10\/nuevo-centro-hospitalario-luxemburgo-00.jpg","articleSection":["Hospitales sostenibles","Investigaci\u00f3n en dise\u00f1o de hospitales"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/casasolo.es\/en\/ii-edificios-hospitalarios-de-consumo-casi-nulo\/","url":"https:\/\/casasolo.es\/en\/ii-edificios-hospitalarios-de-consumo-casi-nulo\/","name":"Edificios hospitalarios de consumo casi nulo","isPartOf":{"@id":"https:\/\/casasolo.es\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casasolo.es\/en\/ii-edificios-hospitalarios-de-consumo-casi-nulo\/#primaryimage"},"image":{"@id":"https:\/\/casasolo.es\/en\/ii-edificios-hospitalarios-de-consumo-casi-nulo\/#primaryimage"},"thumbnailUrl":"https:\/\/casasolo.es\/wp-content\/uploads\/2016\/10\/nuevo-centro-hospitalario-luxemburgo-00.jpg","datePublished":"2017-02-10T14:49:41+00:00","description":"El dise\u00f1o de edificios hospitalarios de consumo casi nulo toma cada vez m\u00e1s importancia en la arquitectura actual.","breadcrumb":{"@id":"https:\/\/casasolo.es\/en\/ii-edificios-hospitalarios-de-consumo-casi-nulo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casasolo.es\/en\/ii-edificios-hospitalarios-de-consumo-casi-nulo\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/casasolo.es\/en\/ii-edificios-hospitalarios-de-consumo-casi-nulo\/#primaryimage","url":"https:\/\/casasolo.es\/wp-content\/uploads\/2016\/10\/nuevo-centro-hospitalario-luxemburgo-00.jpg","contentUrl":"https:\/\/casasolo.es\/wp-content\/uploads\/2016\/10\/nuevo-centro-hospitalario-luxemburgo-00.jpg","width":1200,"height":625},{"@type":"BreadcrumbList","@id":"https:\/\/casasolo.es\/en\/ii-edificios-hospitalarios-de-consumo-casi-nulo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/casasolo.es\/en\/"},{"@type":"ListItem","position":2,"name":"Edificios hospitalarios de consumo casi nulo"}]},{"@type":"WebSite","@id":"https:\/\/casasolo.es\/en\/#website","url":"https:\/\/casasolo.es\/en\/","name":"CASA SOLO arquitectos","description":"","publisher":{"@id":"https:\/\/casasolo.es\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casasolo.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/casasolo.es\/en\/#organization","name":"CASA SOLO arquitectos","url":"https:\/\/casasolo.es\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/casasolo.es\/en\/#\/schema\/logo\/image\/","url":"https:\/\/casasolo.es\/wp-content\/uploads\/2021\/10\/casasolo-logo.svg","contentUrl":"https:\/\/casasolo.es\/wp-content\/uploads\/2021\/10\/casasolo-logo.svg","caption":"CASA SOLO arquitectos"},"image":{"@id":"https:\/\/casasolo.es\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/casasolo.es\/en\/#\/schema\/person\/5fc60cf44aa387460af4ccaa862ac1b4","name":"casaweb","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/casasolo.es\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fc9cf1dfa9383b5d06e9ea4952a17ca69d4f4a2f3a07f60d4b52a5cd6e11ca07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fc9cf1dfa9383b5d06e9ea4952a17ca69d4f4a2f3a07f60d4b52a5cd6e11ca07?s=96&d=mm&r=g","caption":"casaweb"},"url":"https:\/\/casasolo.es\/en\/author\/casaweb\/"}]}},"_links":{"self":[{"href":"https:\/\/casasolo.es\/en\/wp-json\/wp\/v2\/posts\/1496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casasolo.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casasolo.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casasolo.es\/en\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/casasolo.es\/en\/wp-json\/wp\/v2\/comments?post=1496"}],"version-history":[{"count":0,"href":"https:\/\/casasolo.es\/en\/wp-json\/wp\/v2\/posts\/1496\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casasolo.es\/en\/wp-json\/wp\/v2\/media\/1418"}],"wp:attachment":[{"href":"https:\/\/casasolo.es\/en\/wp-json\/wp\/v2\/media?parent=1496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casasolo.es\/en\/wp-json\/wp\/v2\/categories?post=1496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casasolo.es\/en\/wp-json\/wp\/v2\/tags?post=1496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}