{"id":1004,"date":"2015-04-16T07:59:30","date_gmt":"2015-04-16T07:59:30","guid":{"rendered":"http:\/\/casasolo.es\/?p=1004"},"modified":"2015-04-16T07:59:30","modified_gmt":"2015-04-16T07:59:30","slug":"el-periodico-local-el-potosi-se-hace-eco-de-nuestro-proyecto-para-la-ciudad-de-potosi-en-bolivia","status":"publish","type":"post","link":"https:\/\/casasolo.es\/en\/el-periodico-local-el-potosi-se-hace-eco-de-nuestro-proyecto-para-la-ciudad-de-potosi-en-bolivia\/","title":{"rendered":"El peri\u00f3dico local el Potos\u00ed se hace eco de nuestro proyecto para la ciudad de Potos\u00ed en Bolivia"},"content":{"rendered":"<p><!--:es--><br \/>\nEsta semana el peri\u00f3dico local el Potos\u00ed ha publicado nuestro proyecto para la ciudad de Potos\u00ed en Bol\u00edvia.<\/p>\n<p>A continuaci\u00f3n transcribimos la noticia<\/p>\n<h2>Invertir\u00e1n $ 46 millones en un nuevo hospital de tercer nivel<\/h2>\n<p><strong>La licitaci\u00f3n de este proyecto a dise\u00f1o final de este centro sanitario estar\u00e1 lista para julio pr\u00f3ximo. Se prev\u00e9 que est\u00e9 concluido en 2018. <\/strong><br \/>\nRoc\u00edo Ru\u00edz \u2022 El Potos\u00ed<\/p>\n<p>El nuevo hospital de tercer nivel de Potos\u00ed tendr\u00e1 una inversi\u00f3n de 46 millones de d\u00f3lares, y ya cuenta con el proyecto concluido a dise\u00f1o final y la licitaci\u00f3n de car\u00e1cter internacional se publicar\u00e1 en el mes de julio para que este a\u00f1o comience su construcci\u00f3n, inform\u00f3 ayer el gobernador F\u00e9lix Gonzales.<\/p>\n<p>\u201cEs un sue\u00f1o cumplido y un proyecto de ensue\u00f1o para los potosinos y potosinas, por el monto de inversi\u00f3n, casi 46 millones de d\u00f3lares en infraestructura y equipamiento, va a generar fuentes de trabajo para m\u00e1s de 500 personas en forma directa, pero esto generar\u00e1 un movimiento econ\u00f3mico y de gente\u201d, dijo.<\/p>\n<h2>LICITACI\u00d3N HOSPITALARIA<\/h2>\n<p>Tenemos el primer paso el proyecto a nivel TESA (T\u00e9cnico, econ\u00f3mico, social, ambiental) concluido y seguramente a partir de ahora se entrar\u00e1 en la etapa que corresponde de la licitaci\u00f3n internacional y en 2018 estar\u00edamos concluyendo el proyecto\u201d, complement\u00f3.<\/p>\n<p>Si se cumplen los plazos, en el mes de julio estar\u00eda iniciando el proyecto con la licitaci\u00f3n internacional. Aunque no precis\u00f3 montos, Gonz\u00e1les inform\u00f3 que el financiamiento corre por cuenta del Gobierno nacional y la Gobernaci\u00f3n con recursos del Banco Interamericano de Desarrollo (BID).<\/p>\n<p>El terreno est\u00e1 ubicado en Villa Para\u00edso en aproximadamente cuatro hect\u00e1reas, cercano a la carretera hacia Oruro. Una de las caracter\u00edsticas de la construcci\u00f3n de este hospital es que la licitaci\u00f3n tanto para la construcci\u00f3n y para el equipamiento ser\u00e1 una sola.<\/p>\n<p>Entre las 35 especialidades est\u00e1n: Medicina Interna, Cirug\u00eda Vascular, Cardiolog\u00eda, Proctolog\u00eda, Neumolog\u00eda, Traumatolog\u00eda, Gastroenterolog\u00eda, Neurocirug\u00eda, Neurolog\u00eda, Otorrinolaringolog\u00eda, Endocrinolog\u00eda, Oftalmolog\u00eda, Nutrici\u00f3n, Urolog\u00eda, Nefrolog\u00eda, Cirug\u00eda Pl\u00e1stica, Inmunolog\u00eda, Quemolog\u00eda, Reumatolog\u00eda, Cirug\u00eda Maxilofacial, Hematolog\u00eda, Odontolog\u00eda, Dermatolog\u00eda, Obstetricia, Geriatria, Ginecolog\u00eda, Oncolog\u00eda Pediatrica, Cirug\u00eda general Neonatolog\u00eda Cirug\u00eda abdominal, Cirug\u00eda Pedi\u00e1trica, Cirug\u00eda Tor\u00e1xica, Traumatolog\u00eda y Ortopedia infantil Medicina f\u00edsica y Rehabilitaci\u00f3n.<\/p>\n<p>\u201cM\u00e1s o menos, el total del \u00e1rea construida va a ser de 26.617 metros, con un costo en la parte de infraestructura de 31.366.000 d\u00f3lares e independientemente de eso est\u00e1n 16 millones de d\u00f3lares para el equipamiento\u201d, detall\u00f3.<\/p>\n<h2>Capacidad hospitalaria<\/h2>\n<p>&#8220;El hospital tendr\u00e1 35 especialidades para la atenci\u00f3n a la ciudadan\u00eda, contar\u00e1 con una capacidad de 276 camas y 29 consultorios. Tendr\u00e1 un equipamiento de \u00faltima tecnolog\u00eda y dise\u00f1o innovador.&#8221;<\/p>\n<p>En la explicaci\u00f3n del proyecto a dise\u00f1o final, el gerente de arquitectura de la empresa Gesti\u00f3n Integrada de Proyectos Hospitalarios \u201cEngest\u201d, Bernat Gato, detall\u00f3 que el dise\u00f1o tiene varias ventajas. Por ejemplo, para que las \u00e1reas de internaci\u00f3n tengan vistas de la ciudad y cuenten con la mayor cantidad de horas de sol.<\/p>\n<p>&#8220;El nivel tecnol\u00f3gico de las instalaciones y el nivel tecnol\u00f3gico del equipamiento son los que van a marcar la diferencia y van a situar a este centro hospitalario al nivel de los principales hospitales mundiales\u201d, dijo Gato. Adem\u00e1s, habr\u00e1 un espacio denominado \u201chospital de d\u00eda\u201d, que permitir\u00e1 a los pacientes recibir el tratamiento en el d\u00eda y retornar a sus hogares en la noche.<\/p>\n<p>Las caracter\u00edsticas del dise\u00f1o arquitect\u00f3nico permiten a este centro sanitario contar con \u00e1reas como guarder\u00eda, o alojamiento para familiares de los pacientes, tambi\u00e9n una cafeter\u00eda.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" src=\"http:\/\/casasolo.es\/wp-content\/uploads\/2015\/05\/hospital-tercer-nivel-03.jpg\" alt=\"hospital-tercer-nivel-03\" width=\"924\" height=\"1245\" class=\"alignnone size-full wp-image-1049\" srcset=\"https:\/\/casasolo.es\/wp-content\/uploads\/2015\/05\/hospital-tercer-nivel-03.jpg 924w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/05\/hospital-tercer-nivel-03-223x300.jpg 223w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/05\/hospital-tercer-nivel-03-760x1024.jpg 760w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/05\/hospital-tercer-nivel-03-768x1035.jpg 768w\" sizes=\"(max-width: 924px) 100vw, 924px\" \/><\/p>\n<p><!--:--><\/p>\n<p><!--:en--> <\/p>\n<p>This week the local newspaper Potos\u00ed has published our Project for the city of Potos\u00ed in Bolivia.<\/p>\n<p>We transcibe the article bellow<\/p>\n<p>An investment of $ 46 million in a new tertiary hospital<\/p>\n<p>The tender for this project final design of the health center will be ready by next July. Is expected to be completed in 2018.<br \/>\nRocio Ruiz \u2022 The Potos\u00ed<\/p>\n<p>The new tertiary hospital Potosi an investment of $ 46 million, and already has the project completed to final design and international tender was published in July for this year begin construction, reported yesterday Governor Felix Gonzales.<\/p>\n<p>&#8220;It&#8217;s a dream come true and a dream project for potosinos and potosinas, the investment amount, nearly $ 46 million in infrastructure and equipment, will generate jobs for more than 500 people directly, but will generate economic and people movement&#8221; he said.<\/p>\n<p>You have the first step the project TESA (technical, economic, social, environmental) level completed and surely from now will enter the stage corresponding international tender and in 2018 concluded the project would be &#8220;supplemented.<\/p>\n<p>If deadlines are met in July would be starting the project with the international tender. Although he did not specify amounts, Gonzales said the funding borne by the national Government and the Government with resources from the Inter American Development Bank (IDB).<\/p>\n<p>The land is located in Villa Paraiso in approximately four hectares, near the road to Oruro. One of the features of the construction of this hospital is that the tender for both the construction and the equipment will be one.<\/p>\n<p>Among the 35 specialties are: Internal Medicine, Vascular Surgery, Cardiology, Proctology, Pulmonology, Traumatology, Gastroenterology, Neurosurgery, Neurology, ENT, Endocrinology, Ophthalmology, Nutrition, Urology, Nephrology, Plastic Surgery, Immunology, Quemolog\u00eda, Rheumatology, Maxillofacial Surgery, Hematology, Dentistry, Dermatology, Obstetrics, Geriatrics, Gynecology, Pediatric Oncology, General Surgery Abdominal Surgery Neonatology, Pediatric Surgery, Thoracic Surgery, Traumatology and Orthopedics child physical medicine and rehabilitation.<\/p>\n<p>&#8220;More or less, the total built area is going to be of 26,617 meters at a cost to the infrastructure part of $ 31,366,000 and regardless of it being $ 16 million for equipment,&#8221; he explained.<\/p>\n<h2>Capacity of the hospital<\/h2>\n<p>You will have 35 specialties for attention to citizenship, will have a capacity of 276 beds and 29 clinics.<br \/>\nHave a tech equipment and innovative design<\/p>\n<p>In explaining the project to final design, the manager of enterprise architecture Hospital Integrated Projects &#8220;Engest&#8221; Bernat Gato, detailed design has several advantages. For example, for inpatient areas have views of the city and have the most hours of sunshine.<\/p>\n<p>&#8220;The technological level of facilities and the technological level of equipment are going to make a difference and will place this hospital to major global level hospitals,&#8221; Jack said.<\/p>\n<p>There will also be a space called &#8220;day hospital&#8221; which will allow patients to receive treatment in the day and return home at night. Architectural design features allow the health center areas count as child care, or housing for families of patients, also a cafe.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" src=\"http:\/\/casasolo.es\/wp-content\/uploads\/2015\/05\/hospital-tercer-nivel-03.jpg\" alt=\"hospital-tercer-nivel-03\" width=\"924\" height=\"1245\" class=\"alignnone size-full wp-image-1049\" srcset=\"https:\/\/casasolo.es\/wp-content\/uploads\/2015\/05\/hospital-tercer-nivel-03.jpg 924w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/05\/hospital-tercer-nivel-03-223x300.jpg 223w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/05\/hospital-tercer-nivel-03-760x1024.jpg 760w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/05\/hospital-tercer-nivel-03-768x1035.jpg 768w\" sizes=\"(max-width: 924px) 100vw, 924px\" \/><\/p>\n<p><!--:--><\/p>\n<p><!--:ca--> <\/p>\n<p>Aquesta setmana el diari local el Potos\u00ed ha publicat el nostre projecte per a la ciutat de Potos\u00ed a Bol\u00edvia.<\/p>\n<p>A continuaci\u00f3 transcrivim la not\u00edcia<\/p>\n<h2>Invertiran 46 $ milions en un nou hospital de tercer nivell<\/h2>\n<p><strong>La licitaci\u00f3 d&#8217;aquest projecte a disseny final d&#8217;aquest centre sanitari estar\u00e0 a punt per al juliol pr\u00f2xim. Es preveu que estigui acabat el 2018.<\/strong><br \/>\nRoc\u00edo Ru\u00edz \u2022 El Potos\u00ed<\/p>\n<p>El nou hospital de tercer nivell de Potos\u00ed tindr\u00e0 una inversi\u00f3 de 46 milions de d\u00f2lars, i ja compta amb el projecte concl\u00f2s a disseny final i la licitaci\u00f3 de car\u00e0cter internacional es publicar\u00e0 al mes de juliol perqu\u00e8 aquest any comenci la seva construcci\u00f3, va informar ahir el governador F\u00e9lix Gonzales.<\/p>\n<p>&#8220;\u00c9s un somni complert i un projecte de somni per als Potos\u00ed i potosinas, per la suma d&#8217;inversi\u00f3, gaireb\u00e9 46 milions de d\u00f2lars en infraestructura i equipament, generar\u00e0 fonts de treball per a m\u00e9s de 500 persones de forma directa, per\u00f2 aix\u00f2 generar\u00e0 un moviment econ\u00f2mic i de gent &#8220;, va dir.<\/p>\n<h2>LICITACI\u00d3 HOSPITALARIA<\/h2>\n<p>Tenim el primer pas el projecte a nivell TESA (T\u00e8cnic, econ\u00f2mic, social, ambiental) concl\u00f2s i segurament a partir d&#8217;ara s&#8217;entrar\u00e0 en l&#8217;etapa que correspon de la licitaci\u00f3 internacional i el 2018 estar\u00edem concloent el projecte &#8220;, va complementar.<\/p>\n<p>Si es compleixen els terminis, al mes de juliol estaria iniciant el projecte amb la licitaci\u00f3 internacional. Tot i que no va precisar sumes, Gonz\u00e1les va informar que el finan\u00e7ament va a c\u00e0rrec del Govern nacional i la Governaci\u00f3 amb recursos del Banc Interameric\u00e0 de Desenvolupament (BID).<\/p>\n<p>El terreny est\u00e0 ubicat a Vila Parad\u00eds en aproximadament quatre hect\u00e0rees, proper a la carretera cap a Oruro. Una de les caracter\u00edstiques de la construcci\u00f3 d&#8217;aquest hospital \u00e9s que la licitaci\u00f3 tant per a la construcci\u00f3 i per a l&#8217;equipament ser\u00e0 una sola.<\/p>\n<p>Entre les 35 especialitats estan: Medicina Interna, Cirurgia Vascular, Cardiologia, Proctologia, Pneumologia, Traumatologia, Gastroenterologia, Neurocirurgia, Neurologia, Otorinolaringologia, Endocrinologia, Oftalmologia, Nutrici\u00f3, Urologia, Nefrologia, Cirurgia Pl\u00e0stica, Immunologia, Quemolog\u00eda, Reumatologia, Cirurgia Maxil\u00b7lofacial, Hematologia, Odontologia, Dermatologia, Obstetr\u00edcia, Geriatria, Ginecologia, Oncologia Pedi\u00e0trica, Cirurgia general Neonatologia Cirurgia abdominal, Cirurgia Pedi\u00e0trica, Cirurgia tor\u00e0cica, Traumatologia i Ortop\u00e8dia infantil Medicina f\u00edsica i Rehabilitaci\u00f3.<\/p>\n<p>&#8220;M\u00e9s o menys, el total de l&#8217;\u00e0rea constru\u00efda ser\u00e0 de 26.617 metres, amb un cost en la part d&#8217;infraestructura de $ 31.366.000 i independentment d&#8217;aix\u00f2 estan 16 milions de d\u00f2lars per a l&#8217;equipament&#8221;, ha detallat.<\/p>\n<h2>Capacitat hospitalaria<\/h2>\n<p>Tindr\u00e0 35 especialitats per a l&#8217;atenci\u00f3 a la ciutadania, comptar\u00e0 amb una capacitat de 276 llits i 29 consultoris. Tindr\u00e0 un equipament d&#8217;\u00faltima tecnologia i disseny innovador.<\/p>\n<p>En l&#8217;explicaci\u00f3 del projecte a disseny final, el gerent d&#8217;arquitectura de l&#8217;empresa Gesti\u00f3 Integrada de Projectes Hospitalaris &#8220;Engest&#8221;, Bernat Gato, va detallar que el disseny t\u00e9 diversos avantatges. Per exemple, perqu\u00e8 les \u00e0rees d&#8217;internament tinguin vistes de la ciutat i compten amb la major quantitat d&#8217;hores de sol.<\/p>\n<p>&#8220;El nivell tecnol\u00f2gic de les instal\u00b7lacions i el nivell tecnol\u00f2gic de l&#8217;equipament s\u00f3n els que marcaran la difer\u00e8ncia i van a situar aquest centre hospitalari al nivell dels principals hospitals mundials&#8221;, va dir Gat.<\/p>\n<p>A m\u00e9s, hi haur\u00e0 un espai anomenat &#8220;hospital de dia&#8221;, que permetr\u00e0 als pacients rebre el tractament en el dia i retornar a les seves llars a la nit.<br \/>\nLes caracter\u00edstiques del disseny arquitect\u00f2nic permeten a aquest centre sanitari comptar amb \u00e0rees com a guarderia, o allotjament per a familiars dels pacients, tamb\u00e9 una cafeteria.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" src=\"http:\/\/casasolo.es\/wp-content\/uploads\/2015\/05\/hospital-tercer-nivel-03.jpg\" alt=\"hospital-tercer-nivel-03\" width=\"924\" height=\"1245\" class=\"alignnone size-full wp-image-1049\" srcset=\"https:\/\/casasolo.es\/wp-content\/uploads\/2015\/05\/hospital-tercer-nivel-03.jpg 924w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/05\/hospital-tercer-nivel-03-223x300.jpg 223w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/05\/hospital-tercer-nivel-03-760x1024.jpg 760w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/05\/hospital-tercer-nivel-03-768x1035.jpg 768w\" sizes=\"(max-width: 924px) 100vw, 924px\" \/><\/p>\n<p><!--:--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta semana el peri\u00f3dico local el Potos\u00ed ha publicado nuestro proyecto para la ciudad de Potos\u00ed en Bol\u00edvia. A continuaci\u00f3n transcribimos la noticia Invertir\u00e1n $ 46 millones en un nuevo hospital de tercer nivel La licitaci\u00f3n de este proyecto a dise\u00f1o final de este centro sanitario estar\u00e1 lista para julio pr\u00f3ximo. Se prev\u00e9 que est\u00e9 [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":1049,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-1004","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El peri\u00f3dico local el Potos\u00ed se hace eco de nuestro proyecto para la ciudad de Potos\u00ed en Bolivia - CASA SOLO arquitectos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casasolo.es\/en\/el-periodico-local-el-potosi-se-hace-eco-de-nuestro-proyecto-para-la-ciudad-de-potosi-en-bolivia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El peri\u00f3dico local el Potos\u00ed se hace eco de nuestro proyecto para la ciudad de Potos\u00ed en Bolivia - CASA SOLO arquitectos\" \/>\n<meta property=\"og:description\" content=\"Esta semana el peri\u00f3dico local el Potos\u00ed ha publicado nuestro proyecto para la ciudad de Potos\u00ed en Bol\u00edvia. A continuaci\u00f3n transcribimos la noticia Invertir\u00e1n $ 46 millones en un nuevo hospital de tercer nivel La licitaci\u00f3n de este proyecto a dise\u00f1o final de este centro sanitario estar\u00e1 lista para julio pr\u00f3ximo. Se prev\u00e9 que est\u00e9 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casasolo.es\/en\/el-periodico-local-el-potosi-se-hace-eco-de-nuestro-proyecto-para-la-ciudad-de-potosi-en-bolivia\/\" \/>\n<meta property=\"og:site_name\" content=\"CASA SOLO arquitectos\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-16T07:59:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casasolo.es\/wp-content\/uploads\/2015\/05\/hospital-tercer-nivel-03.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"924\" \/>\n\t<meta property=\"og:image:height\" content=\"1245\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"casaweb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"casaweb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/casasolo.es\/en\/el-periodico-local-el-potosi-se-hace-eco-de-nuestro-proyecto-para-la-ciudad-de-potosi-en-bolivia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/casasolo.es\/en\/el-periodico-local-el-potosi-se-hace-eco-de-nuestro-proyecto-para-la-ciudad-de-potosi-en-bolivia\/\"},\"author\":{\"name\":\"casaweb\",\"@id\":\"https:\/\/casasolo.es\/en\/#\/schema\/person\/5fc60cf44aa387460af4ccaa862ac1b4\"},\"headline\":\"El peri\u00f3dico local el Potos\u00ed se hace eco de nuestro proyecto para la ciudad de Potos\u00ed en Bolivia\",\"datePublished\":\"2015-04-16T07:59:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/casasolo.es\/en\/el-periodico-local-el-potosi-se-hace-eco-de-nuestro-proyecto-para-la-ciudad-de-potosi-en-bolivia\/\"},\"wordCount\":1715,\"publisher\":{\"@id\":\"https:\/\/casasolo.es\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/casasolo.es\/en\/el-periodico-local-el-potosi-se-hace-eco-de-nuestro-proyecto-para-la-ciudad-de-potosi-en-bolivia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2015\/05\/hospital-tercer-nivel-03.jpg\",\"articleSection\":[\"Noticias Corporativas\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/casasolo.es\/en\/el-periodico-local-el-potosi-se-hace-eco-de-nuestro-proyecto-para-la-ciudad-de-potosi-en-bolivia\/\",\"url\":\"https:\/\/casasolo.es\/en\/el-periodico-local-el-potosi-se-hace-eco-de-nuestro-proyecto-para-la-ciudad-de-potosi-en-bolivia\/\",\"name\":\"El peri\u00f3dico local el Potos\u00ed se hace eco de nuestro proyecto para la ciudad de Potos\u00ed en Bolivia - CASA SOLO arquitectos\",\"isPartOf\":{\"@id\":\"https:\/\/casasolo.es\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/casasolo.es\/en\/el-periodico-local-el-potosi-se-hace-eco-de-nuestro-proyecto-para-la-ciudad-de-potosi-en-bolivia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/casasolo.es\/en\/el-periodico-local-el-potosi-se-hace-eco-de-nuestro-proyecto-para-la-ciudad-de-potosi-en-bolivia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2015\/05\/hospital-tercer-nivel-03.jpg\",\"datePublished\":\"2015-04-16T07:59:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/casasolo.es\/en\/el-periodico-local-el-potosi-se-hace-eco-de-nuestro-proyecto-para-la-ciudad-de-potosi-en-bolivia\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/casasolo.es\/en\/el-periodico-local-el-potosi-se-hace-eco-de-nuestro-proyecto-para-la-ciudad-de-potosi-en-bolivia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/casasolo.es\/en\/el-periodico-local-el-potosi-se-hace-eco-de-nuestro-proyecto-para-la-ciudad-de-potosi-en-bolivia\/#primaryimage\",\"url\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2015\/05\/hospital-tercer-nivel-03.jpg\",\"contentUrl\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2015\/05\/hospital-tercer-nivel-03.jpg\",\"width\":924,\"height\":1245},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/casasolo.es\/en\/el-periodico-local-el-potosi-se-hace-eco-de-nuestro-proyecto-para-la-ciudad-de-potosi-en-bolivia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/casasolo.es\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El peri\u00f3dico local el Potos\u00ed se hace eco de nuestro proyecto para la ciudad de Potos\u00ed en Bolivia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/casasolo.es\/en\/#website\",\"url\":\"https:\/\/casasolo.es\/en\/\",\"name\":\"CASA SOLO arquitectos\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/casasolo.es\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/casasolo.es\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/casasolo.es\/en\/#organization\",\"name\":\"CASA SOLO arquitectos\",\"url\":\"https:\/\/casasolo.es\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/casasolo.es\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2021\/10\/casasolo-logo.svg\",\"contentUrl\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2021\/10\/casasolo-logo.svg\",\"caption\":\"CASA SOLO arquitectos\"},\"image\":{\"@id\":\"https:\/\/casasolo.es\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/casasolo.es\/en\/#\/schema\/person\/5fc60cf44aa387460af4ccaa862ac1b4\",\"name\":\"casaweb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/casasolo.es\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fc9cf1dfa9383b5d06e9ea4952a17ca69d4f4a2f3a07f60d4b52a5cd6e11ca07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fc9cf1dfa9383b5d06e9ea4952a17ca69d4f4a2f3a07f60d4b52a5cd6e11ca07?s=96&d=mm&r=g\",\"caption\":\"casaweb\"},\"url\":\"https:\/\/casasolo.es\/en\/author\/casaweb\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El peri\u00f3dico local el Potos\u00ed se hace eco de nuestro proyecto para la ciudad de Potos\u00ed en Bolivia - CASA SOLO arquitectos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casasolo.es\/en\/el-periodico-local-el-potosi-se-hace-eco-de-nuestro-proyecto-para-la-ciudad-de-potosi-en-bolivia\/","og_locale":"en_US","og_type":"article","og_title":"El peri\u00f3dico local el Potos\u00ed se hace eco de nuestro proyecto para la ciudad de Potos\u00ed en Bolivia - CASA SOLO arquitectos","og_description":"Esta semana el peri\u00f3dico local el Potos\u00ed ha publicado nuestro proyecto para la ciudad de Potos\u00ed en Bol\u00edvia. A continuaci\u00f3n transcribimos la noticia Invertir\u00e1n $ 46 millones en un nuevo hospital de tercer nivel La licitaci\u00f3n de este proyecto a dise\u00f1o final de este centro sanitario estar\u00e1 lista para julio pr\u00f3ximo. Se prev\u00e9 que est\u00e9 [&hellip;]","og_url":"https:\/\/casasolo.es\/en\/el-periodico-local-el-potosi-se-hace-eco-de-nuestro-proyecto-para-la-ciudad-de-potosi-en-bolivia\/","og_site_name":"CASA SOLO arquitectos","article_published_time":"2015-04-16T07:59:30+00:00","og_image":[{"width":924,"height":1245,"url":"https:\/\/casasolo.es\/wp-content\/uploads\/2015\/05\/hospital-tercer-nivel-03.jpg","type":"image\/jpeg"}],"author":"casaweb","twitter_card":"summary_large_image","twitter_misc":{"Written by":"casaweb","Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/casasolo.es\/en\/el-periodico-local-el-potosi-se-hace-eco-de-nuestro-proyecto-para-la-ciudad-de-potosi-en-bolivia\/#article","isPartOf":{"@id":"https:\/\/casasolo.es\/en\/el-periodico-local-el-potosi-se-hace-eco-de-nuestro-proyecto-para-la-ciudad-de-potosi-en-bolivia\/"},"author":{"name":"casaweb","@id":"https:\/\/casasolo.es\/en\/#\/schema\/person\/5fc60cf44aa387460af4ccaa862ac1b4"},"headline":"El peri\u00f3dico local el Potos\u00ed se hace eco de nuestro proyecto para la ciudad de Potos\u00ed en Bolivia","datePublished":"2015-04-16T07:59:30+00:00","mainEntityOfPage":{"@id":"https:\/\/casasolo.es\/en\/el-periodico-local-el-potosi-se-hace-eco-de-nuestro-proyecto-para-la-ciudad-de-potosi-en-bolivia\/"},"wordCount":1715,"publisher":{"@id":"https:\/\/casasolo.es\/en\/#organization"},"image":{"@id":"https:\/\/casasolo.es\/en\/el-periodico-local-el-potosi-se-hace-eco-de-nuestro-proyecto-para-la-ciudad-de-potosi-en-bolivia\/#primaryimage"},"thumbnailUrl":"https:\/\/casasolo.es\/wp-content\/uploads\/2015\/05\/hospital-tercer-nivel-03.jpg","articleSection":["Noticias Corporativas"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/casasolo.es\/en\/el-periodico-local-el-potosi-se-hace-eco-de-nuestro-proyecto-para-la-ciudad-de-potosi-en-bolivia\/","url":"https:\/\/casasolo.es\/en\/el-periodico-local-el-potosi-se-hace-eco-de-nuestro-proyecto-para-la-ciudad-de-potosi-en-bolivia\/","name":"El peri\u00f3dico local el Potos\u00ed se hace eco de nuestro proyecto para la ciudad de Potos\u00ed en Bolivia - CASA SOLO arquitectos","isPartOf":{"@id":"https:\/\/casasolo.es\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casasolo.es\/en\/el-periodico-local-el-potosi-se-hace-eco-de-nuestro-proyecto-para-la-ciudad-de-potosi-en-bolivia\/#primaryimage"},"image":{"@id":"https:\/\/casasolo.es\/en\/el-periodico-local-el-potosi-se-hace-eco-de-nuestro-proyecto-para-la-ciudad-de-potosi-en-bolivia\/#primaryimage"},"thumbnailUrl":"https:\/\/casasolo.es\/wp-content\/uploads\/2015\/05\/hospital-tercer-nivel-03.jpg","datePublished":"2015-04-16T07:59:30+00:00","breadcrumb":{"@id":"https:\/\/casasolo.es\/en\/el-periodico-local-el-potosi-se-hace-eco-de-nuestro-proyecto-para-la-ciudad-de-potosi-en-bolivia\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casasolo.es\/en\/el-periodico-local-el-potosi-se-hace-eco-de-nuestro-proyecto-para-la-ciudad-de-potosi-en-bolivia\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/casasolo.es\/en\/el-periodico-local-el-potosi-se-hace-eco-de-nuestro-proyecto-para-la-ciudad-de-potosi-en-bolivia\/#primaryimage","url":"https:\/\/casasolo.es\/wp-content\/uploads\/2015\/05\/hospital-tercer-nivel-03.jpg","contentUrl":"https:\/\/casasolo.es\/wp-content\/uploads\/2015\/05\/hospital-tercer-nivel-03.jpg","width":924,"height":1245},{"@type":"BreadcrumbList","@id":"https:\/\/casasolo.es\/en\/el-periodico-local-el-potosi-se-hace-eco-de-nuestro-proyecto-para-la-ciudad-de-potosi-en-bolivia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/casasolo.es\/en\/"},{"@type":"ListItem","position":2,"name":"El peri\u00f3dico local el Potos\u00ed se hace eco de nuestro proyecto para la ciudad de Potos\u00ed en Bolivia"}]},{"@type":"WebSite","@id":"https:\/\/casasolo.es\/en\/#website","url":"https:\/\/casasolo.es\/en\/","name":"CASA SOLO arquitectos","description":"","publisher":{"@id":"https:\/\/casasolo.es\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casasolo.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/casasolo.es\/en\/#organization","name":"CASA SOLO arquitectos","url":"https:\/\/casasolo.es\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/casasolo.es\/en\/#\/schema\/logo\/image\/","url":"https:\/\/casasolo.es\/wp-content\/uploads\/2021\/10\/casasolo-logo.svg","contentUrl":"https:\/\/casasolo.es\/wp-content\/uploads\/2021\/10\/casasolo-logo.svg","caption":"CASA SOLO arquitectos"},"image":{"@id":"https:\/\/casasolo.es\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/casasolo.es\/en\/#\/schema\/person\/5fc60cf44aa387460af4ccaa862ac1b4","name":"casaweb","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/casasolo.es\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fc9cf1dfa9383b5d06e9ea4952a17ca69d4f4a2f3a07f60d4b52a5cd6e11ca07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fc9cf1dfa9383b5d06e9ea4952a17ca69d4f4a2f3a07f60d4b52a5cd6e11ca07?s=96&d=mm&r=g","caption":"casaweb"},"url":"https:\/\/casasolo.es\/en\/author\/casaweb\/"}]}},"_links":{"self":[{"href":"https:\/\/casasolo.es\/en\/wp-json\/wp\/v2\/posts\/1004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casasolo.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casasolo.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casasolo.es\/en\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/casasolo.es\/en\/wp-json\/wp\/v2\/comments?post=1004"}],"version-history":[{"count":0,"href":"https:\/\/casasolo.es\/en\/wp-json\/wp\/v2\/posts\/1004\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casasolo.es\/en\/wp-json\/wp\/v2\/media\/1049"}],"wp:attachment":[{"href":"https:\/\/casasolo.es\/en\/wp-json\/wp\/v2\/media?parent=1004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casasolo.es\/en\/wp-json\/wp\/v2\/categories?post=1004"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casasolo.es\/en\/wp-json\/wp\/v2\/tags?post=1004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}