{"id":5245,"date":"2023-01-23T11:42:52","date_gmt":"2023-01-23T11:42:52","guid":{"rendered":"https:\/\/casasolo.es\/casa-solo-es-trasllada\/"},"modified":"2023-01-23T13:51:50","modified_gmt":"2023-01-23T13:51:50","slug":"casa-solo-es-trasllada","status":"publish","type":"post","link":"https:\/\/casasolo.es\/ca\/casa-solo-es-trasllada\/","title":{"rendered":"CASA SOLO es trasllada"},"content":{"rendered":"\n<p>Despr\u00e9s de 35 anys d&#8217;activitat a Cerdanyola del Vall\u00e8s, CASA SOLO trasllada la seva seu a la capital catalana.<\/p>\n\n<p>Davant la necessitat creixent de millorar la seva infraestructura, fomentar sin\u00e8rgies, facilitar les col\u00b7laboracions i el treball en equip, apropar-se als clients i empreses col\u00b7laboradores; hem decidit traslladar-nos a la sisena planta de la Torre Est de l\u00b4Edifici Trade, dissenyat per Coderch i constru\u00eft a finals dels anys seixanta.<\/p>\n\n<p>En aquesta nova oficina compartim espai amb <a href=\"http:\/\/www.ginabarcelona.com\/?lang=ca\"><strong>GINA Barcelona Architects<\/strong><\/a>, grup d&#8217; estudis d&#8217; arquitectura de la ciutat, del qual som un dels socis fundadors. <\/p>\n\n<p>La planta, d&#8217;uns 400 m2, ha estat remodelada de manera integral. Compta amb dues grans \u00e0rees de treball, diversos offices, una gran sala de reunions, despatxos d&#8217;atenci\u00f3 individual, sala d&#8217;impressi\u00f3, sala de maquetaci\u00f3 i cantina, a m\u00e9s de gaudir de vistes 360 graus a la ciutat.<\/p>\n\n<p>Un canvi d&#8217;entorn complementat amb el recent canvi d&#8217;interf\u00edcie web, marca l&#8217;inici duna nova etapa per a l&#8217;empresa, que avan\u00e7a amb m\u00e9s energia encara.<\/p>\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"505\" src=\"https:\/\/casasolo.es\/wp-content\/uploads\/2023\/01\/Edificios-Trade-Coderch_2-1024x505.jpg\" alt=\"\" class=\"wp-image-5235\" srcset=\"https:\/\/casasolo.es\/wp-content\/uploads\/2023\/01\/Edificios-Trade-Coderch_2-1024x505.jpg 1024w, https:\/\/casasolo.es\/wp-content\/uploads\/2023\/01\/Edificios-Trade-Coderch_2-300x148.jpg 300w, https:\/\/casasolo.es\/wp-content\/uploads\/2023\/01\/Edificios-Trade-Coderch_2-768x379.jpg 768w, https:\/\/casasolo.es\/wp-content\/uploads\/2023\/01\/Edificios-Trade-Coderch_2-1536x757.jpg 1536w, https:\/\/casasolo.es\/wp-content\/uploads\/2023\/01\/Edificios-Trade-Coderch_2-2048x1010.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Despr\u00e9s de 35 anys d&#8217;activitat a Cerdanyola del Vall\u00e8s, CASA SOLO trasllada la seva seu a la capital catalana. Davant la necessitat creixent de millorar la seva infraestructura, fomentar sin\u00e8rgies, facilitar les col\u00b7laboracions i el treball en equip, apropar-se als clients i empreses col\u00b7laboradores; hem decidit traslladar-nos a la sisena planta de la Torre Est [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":5233,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[123],"tags":[],"class_list":["post-5245","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized-ca"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CASA SOLO es trasllada - CASA SOLO arquitectos<\/title>\n<meta name=\"description\" content=\"Despr\u00e9s de 35 anys d&#039;activitat a Cerdanyola del Vall\u00e8s, CASA SOLO trasllada la seva seu a la capital catalana.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casasolo.es\/ca\/casa-solo-es-trasllada\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CASA SOLO es trasllada - CASA SOLO arquitectos\" \/>\n<meta property=\"og:description\" content=\"Despr\u00e9s de 35 anys d&#039;activitat a Cerdanyola del Vall\u00e8s, CASA SOLO trasllada la seva seu a la capital catalana.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casasolo.es\/ca\/casa-solo-es-trasllada\/\" \/>\n<meta property=\"og:site_name\" content=\"CASA SOLO arquitectos\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-23T11:42:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-23T13:51:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casasolo.es\/wp-content\/uploads\/2023\/01\/Edificio-Trade-Coderch-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"casaweb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"casaweb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/casasolo.es\/ca\/casa-solo-es-trasllada\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/casasolo.es\/ca\/casa-solo-es-trasllada\/\"},\"author\":{\"name\":\"casaweb\",\"@id\":\"https:\/\/casasolo.es\/ca\/#\/schema\/person\/5fc60cf44aa387460af4ccaa862ac1b4\"},\"headline\":\"CASA SOLO es trasllada\",\"datePublished\":\"2023-01-23T11:42:52+00:00\",\"dateModified\":\"2023-01-23T13:51:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/casasolo.es\/ca\/casa-solo-es-trasllada\/\"},\"wordCount\":175,\"publisher\":{\"@id\":\"https:\/\/casasolo.es\/ca\/#organization\"},\"image\":{\"@id\":\"https:\/\/casasolo.es\/ca\/casa-solo-es-trasllada\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2023\/01\/Edificio-Trade-Coderch-scaled.jpg\",\"articleSection\":[\"Uncategorized @ca\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/casasolo.es\/ca\/casa-solo-es-trasllada\/\",\"url\":\"https:\/\/casasolo.es\/ca\/casa-solo-es-trasllada\/\",\"name\":\"CASA SOLO es trasllada - CASA SOLO arquitectos\",\"isPartOf\":{\"@id\":\"https:\/\/casasolo.es\/ca\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/casasolo.es\/ca\/casa-solo-es-trasllada\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/casasolo.es\/ca\/casa-solo-es-trasllada\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2023\/01\/Edificio-Trade-Coderch-scaled.jpg\",\"datePublished\":\"2023-01-23T11:42:52+00:00\",\"dateModified\":\"2023-01-23T13:51:50+00:00\",\"description\":\"Despr\u00e9s de 35 anys d'activitat a Cerdanyola del Vall\u00e8s, CASA SOLO trasllada la seva seu a la capital catalana.\",\"breadcrumb\":{\"@id\":\"https:\/\/casasolo.es\/ca\/casa-solo-es-trasllada\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/casasolo.es\/ca\/casa-solo-es-trasllada\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/casasolo.es\/ca\/casa-solo-es-trasllada\/#primaryimage\",\"url\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2023\/01\/Edificio-Trade-Coderch-scaled.jpg\",\"contentUrl\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2023\/01\/Edificio-Trade-Coderch-scaled.jpg\",\"width\":1920,\"height\":2560,\"caption\":\"Torre Este. Edificios Trade. Jose Antonio Coderch\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/casasolo.es\/ca\/casa-solo-es-trasllada\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/casasolo.es\/ca\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CASA SOLO es trasllada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/casasolo.es\/ca\/#website\",\"url\":\"https:\/\/casasolo.es\/ca\/\",\"name\":\"CASA SOLO arquitectos\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/casasolo.es\/ca\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/casasolo.es\/ca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/casasolo.es\/ca\/#organization\",\"name\":\"CASA SOLO arquitectos\",\"url\":\"https:\/\/casasolo.es\/ca\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/casasolo.es\/ca\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2021\/10\/casasolo-logo.svg\",\"contentUrl\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2021\/10\/casasolo-logo.svg\",\"caption\":\"CASA SOLO arquitectos\"},\"image\":{\"@id\":\"https:\/\/casasolo.es\/ca\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/casasolo.es\/ca\/#\/schema\/person\/5fc60cf44aa387460af4ccaa862ac1b4\",\"name\":\"casaweb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/casasolo.es\/ca\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fc9cf1dfa9383b5d06e9ea4952a17ca69d4f4a2f3a07f60d4b52a5cd6e11ca07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fc9cf1dfa9383b5d06e9ea4952a17ca69d4f4a2f3a07f60d4b52a5cd6e11ca07?s=96&d=mm&r=g\",\"caption\":\"casaweb\"},\"url\":\"https:\/\/casasolo.es\/ca\/author\/casaweb\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CASA SOLO es trasllada - CASA SOLO arquitectos","description":"Despr\u00e9s de 35 anys d'activitat a Cerdanyola del Vall\u00e8s, CASA SOLO trasllada la seva seu a la capital catalana.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casasolo.es\/ca\/casa-solo-es-trasllada\/","og_locale":"ca_ES","og_type":"article","og_title":"CASA SOLO es trasllada - CASA SOLO arquitectos","og_description":"Despr\u00e9s de 35 anys d'activitat a Cerdanyola del Vall\u00e8s, CASA SOLO trasllada la seva seu a la capital catalana.","og_url":"https:\/\/casasolo.es\/ca\/casa-solo-es-trasllada\/","og_site_name":"CASA SOLO arquitectos","article_published_time":"2023-01-23T11:42:52+00:00","article_modified_time":"2023-01-23T13:51:50+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/casasolo.es\/wp-content\/uploads\/2023\/01\/Edificio-Trade-Coderch-scaled.jpg","type":"image\/jpeg"}],"author":"casaweb","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"casaweb","Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/casasolo.es\/ca\/casa-solo-es-trasllada\/#article","isPartOf":{"@id":"https:\/\/casasolo.es\/ca\/casa-solo-es-trasllada\/"},"author":{"name":"casaweb","@id":"https:\/\/casasolo.es\/ca\/#\/schema\/person\/5fc60cf44aa387460af4ccaa862ac1b4"},"headline":"CASA SOLO es trasllada","datePublished":"2023-01-23T11:42:52+00:00","dateModified":"2023-01-23T13:51:50+00:00","mainEntityOfPage":{"@id":"https:\/\/casasolo.es\/ca\/casa-solo-es-trasllada\/"},"wordCount":175,"publisher":{"@id":"https:\/\/casasolo.es\/ca\/#organization"},"image":{"@id":"https:\/\/casasolo.es\/ca\/casa-solo-es-trasllada\/#primaryimage"},"thumbnailUrl":"https:\/\/casasolo.es\/wp-content\/uploads\/2023\/01\/Edificio-Trade-Coderch-scaled.jpg","articleSection":["Uncategorized @ca"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/casasolo.es\/ca\/casa-solo-es-trasllada\/","url":"https:\/\/casasolo.es\/ca\/casa-solo-es-trasllada\/","name":"CASA SOLO es trasllada - CASA SOLO arquitectos","isPartOf":{"@id":"https:\/\/casasolo.es\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casasolo.es\/ca\/casa-solo-es-trasllada\/#primaryimage"},"image":{"@id":"https:\/\/casasolo.es\/ca\/casa-solo-es-trasllada\/#primaryimage"},"thumbnailUrl":"https:\/\/casasolo.es\/wp-content\/uploads\/2023\/01\/Edificio-Trade-Coderch-scaled.jpg","datePublished":"2023-01-23T11:42:52+00:00","dateModified":"2023-01-23T13:51:50+00:00","description":"Despr\u00e9s de 35 anys d'activitat a Cerdanyola del Vall\u00e8s, CASA SOLO trasllada la seva seu a la capital catalana.","breadcrumb":{"@id":"https:\/\/casasolo.es\/ca\/casa-solo-es-trasllada\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casasolo.es\/ca\/casa-solo-es-trasllada\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/casasolo.es\/ca\/casa-solo-es-trasllada\/#primaryimage","url":"https:\/\/casasolo.es\/wp-content\/uploads\/2023\/01\/Edificio-Trade-Coderch-scaled.jpg","contentUrl":"https:\/\/casasolo.es\/wp-content\/uploads\/2023\/01\/Edificio-Trade-Coderch-scaled.jpg","width":1920,"height":2560,"caption":"Torre Este. Edificios Trade. Jose Antonio Coderch"},{"@type":"BreadcrumbList","@id":"https:\/\/casasolo.es\/ca\/casa-solo-es-trasllada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/casasolo.es\/ca\/home\/"},{"@type":"ListItem","position":2,"name":"CASA SOLO es trasllada"}]},{"@type":"WebSite","@id":"https:\/\/casasolo.es\/ca\/#website","url":"https:\/\/casasolo.es\/ca\/","name":"CASA SOLO arquitectos","description":"","publisher":{"@id":"https:\/\/casasolo.es\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casasolo.es\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/casasolo.es\/ca\/#organization","name":"CASA SOLO arquitectos","url":"https:\/\/casasolo.es\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/casasolo.es\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/casasolo.es\/wp-content\/uploads\/2021\/10\/casasolo-logo.svg","contentUrl":"https:\/\/casasolo.es\/wp-content\/uploads\/2021\/10\/casasolo-logo.svg","caption":"CASA SOLO arquitectos"},"image":{"@id":"https:\/\/casasolo.es\/ca\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/casasolo.es\/ca\/#\/schema\/person\/5fc60cf44aa387460af4ccaa862ac1b4","name":"casaweb","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/casasolo.es\/ca\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fc9cf1dfa9383b5d06e9ea4952a17ca69d4f4a2f3a07f60d4b52a5cd6e11ca07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fc9cf1dfa9383b5d06e9ea4952a17ca69d4f4a2f3a07f60d4b52a5cd6e11ca07?s=96&d=mm&r=g","caption":"casaweb"},"url":"https:\/\/casasolo.es\/ca\/author\/casaweb\/"}]}},"_links":{"self":[{"href":"https:\/\/casasolo.es\/ca\/wp-json\/wp\/v2\/posts\/5245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casasolo.es\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casasolo.es\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casasolo.es\/ca\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/casasolo.es\/ca\/wp-json\/wp\/v2\/comments?post=5245"}],"version-history":[{"count":0,"href":"https:\/\/casasolo.es\/ca\/wp-json\/wp\/v2\/posts\/5245\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casasolo.es\/ca\/wp-json\/wp\/v2\/media\/5233"}],"wp:attachment":[{"href":"https:\/\/casasolo.es\/ca\/wp-json\/wp\/v2\/media?parent=5245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casasolo.es\/ca\/wp-json\/wp\/v2\/categories?post=5245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casasolo.es\/ca\/wp-json\/wp\/v2\/tags?post=5245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}