{"id":1884,"date":"2019-04-25T14:28:10","date_gmt":"2019-04-25T14:28:10","guid":{"rendered":"http:\/\/casasolo.es\/?p=1884"},"modified":"2019-04-25T14:28:10","modified_gmt":"2019-04-25T14:28:10","slug":"hospital-amigable-con-las-personas-mayores-una-adaptacion-al-cambio-demografico-en-la-vanguardia","status":"publish","type":"post","link":"https:\/\/casasolo.es\/ca\/hospital-amigable-con-las-personas-mayores-una-adaptacion-al-cambio-demografico-en-la-vanguardia\/","title":{"rendered":"&#8220;Hospital amigable con las personas mayores: una adaptaci\u00f3n al cambio demogr\u00e1fico&#8221; en La Vanguardia"},"content":{"rendered":"<p><!--:es--><\/p>\n<h3><\/h3>\n<p><a href=\"http:\/\/casasolo.es\/wp-content\/uploads\/2019\/04\/20190424_LaVanguardia_Hospital-amigable-con-las-personas-mayores_-una-adaptacio\u0301n-al-cambio-demogra\u0301fico-CASA-SOLO-11.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-1891\" src=\"http:\/\/casasolo.es\/wp-content\/uploads\/2019\/04\/20190424_LaVanguardia_Hospital-amigable-con-las-personas-mayores_-una-adaptacio\u0301n-al-cambio-demogra\u0301fico-CASA-SOLO-11.jpg\" alt=\"20190424_LaVanguardia_Hospital-amigable-con-las-personas-mayores_-una-adaptacio\u0301n-al-cambio-demogra\u0301fico-CASA-SOLO-1\" width=\"2166\" height=\"1654\" srcset=\"https:\/\/casasolo.es\/wp-content\/uploads\/2019\/04\/20190424_LaVanguardia_Hospital-amigable-con-las-personas-mayores_-una-adaptacio\u0301n-al-cambio-demogra\u0301fico-CASA-SOLO-11.jpg 2166w, https:\/\/casasolo.es\/wp-content\/uploads\/2019\/04\/20190424_LaVanguardia_Hospital-amigable-con-las-personas-mayores_-una-adaptacio\u0301n-al-cambio-demogra\u0301fico-CASA-SOLO-11-300x229.jpg 300w, https:\/\/casasolo.es\/wp-content\/uploads\/2019\/04\/20190424_LaVanguardia_Hospital-amigable-con-las-personas-mayores_-una-adaptacio\u0301n-al-cambio-demogra\u0301fico-CASA-SOLO-11-1024x782.jpg 1024w, https:\/\/casasolo.es\/wp-content\/uploads\/2019\/04\/20190424_LaVanguardia_Hospital-amigable-con-las-personas-mayores_-una-adaptacio\u0301n-al-cambio-demogra\u0301fico-CASA-SOLO-11-768x586.jpg 768w, https:\/\/casasolo.es\/wp-content\/uploads\/2019\/04\/20190424_LaVanguardia_Hospital-amigable-con-las-personas-mayores_-una-adaptacio\u0301n-al-cambio-demogra\u0301fico-CASA-SOLO-11-1536x1173.jpg 1536w, https:\/\/casasolo.es\/wp-content\/uploads\/2019\/04\/20190424_LaVanguardia_Hospital-amigable-con-las-personas-mayores_-una-adaptacio\u0301n-al-cambio-demogra\u0301fico-CASA-SOLO-11-2048x1564.jpg 2048w\" sizes=\"(max-width: 2166px) 100vw, 2166px\" \/><\/a><\/p>\n<h3>El ingreso hospitalario de la gente mayor, si se gestiona desde una \u00f3ptica hol\u00edstica con equipos multidisciplinarios permite coordinar mejor los tratamientos y orientar al paciente<\/h3>\n<p>En la actualidad <strong>m\u00e1s del 50% de todos los ingresos hospitalarios corresponden a personas de m\u00e1s de 65 a\u00f1os<\/strong>, con estancias m\u00e1s largas que el resto de la poblaci\u00f3n y con reingresos m\u00e1s frecuentes (datos 2017 de la sanidad p\u00fablica. Unidad de Informaci\u00f3n y Conocimiento, CatSalut).<\/p>\n<p>El cambio demogr\u00e1fico en nuestro pa\u00eds tendr\u00e1 una progresi\u00f3n espectacular. Se prev\u00e9 que <strong>seremos uno de los pa\u00edses m\u00e1s envejecidos del planeta<\/strong>, debido a la combinaci\u00f3n de una alta esperanza de vida (de las m\u00e1s elevadas del mundo) y una baja tasa de fecundidad (de las m\u00e1s bajas de Europa). Los datos nos lo muestran: En 1960 la poblaci\u00f3n de 65 a\u00f1os y m\u00e1s era del 8\u20192% (dato del INE), en 2018 del 18,8% y, previsiblemente, en 2030 alcanzar\u00e1 el 25% y en 2050 el 30% (casi triplic\u00e1ndose el n\u00famero de mayores de 85 a\u00f1os). A 1 de enero del 2018 hab\u00eda 119,3 personas mayores de 65 a\u00f1os por cada 100 menores de 15 a\u00f1os (\u00edndice de envejecimiento). Del total de mayores de 65 a\u00f1os (1.417.311 personas), el 16\u20197% ten\u00eda m\u00e1s de 85 a\u00f1os (236.434 personas), seg\u00fan el \u00edndice de sobreenvejecimiento (datos de Catalunya, Idescat).<\/p>\n<p><strong>Este gran aumento del porcentaje de gente mayor (\u201cla revoluci\u00f3n de la longevidad\u201d) ha producido un desfase entre la concepci\u00f3n de los hospitales, como unidades pensadas para tratar las patolog\u00edas agudas sobre todo en pacientes j\u00f3venes, y el hecho de que el envejecimiento de la poblaci\u00f3n haga que las personas mayores sean sus usuarias mayoritarias.<\/strong><\/p>\n<p>Las personas mayores y sobre todo las muy mayores, usuarias de los servicios hospitalarios, son especialmente vulnerables porque pueden padecer con frecuencia y de forma simult\u00e1nea varias enfermedades cr\u00f3nicas, junto con alteraci\u00f3n de los \u00f3rganos sensoriales o p\u00e9rdida de funciones cognitivas o de movilidad, y a veces todo ello al mismo tiempo. A causa de su fragilidad (entendida como riesgo de dependencia) es m\u00e1s probable que la estancia en el hospital (incluyendo las unidades de urgencias), constituya para ellas un hecho determinante. Por todas estas circunstancias, su hospitalizaci\u00f3n es m\u00e1s compleja, caracter\u00edstica que si no es atendida con conocimiento experto o no es tenida suficientemente en cuenta, puede derivar en complicaciones, como por ejemplo en una posible disminuci\u00f3n de sus capacidades cognitivas y\/o motrices, y que resulte en una menor independencia en el momento del alta hospitalaria. Estas complicaciones pueden comportar asimismo una alza significativa de los gastos (permanencias m\u00e1s largas, reingresos, aumento de la dependencia\u2026).<\/p>\n<p><strong>Nos encontramos pues ante un cambio de tipolog\u00eda en la mayor\u00eda de las personas usuarias: son mayores y presentan a menudo pluripatolog\u00eda y cronicidad. Nuestros establecimientos hospitalarios no est\u00e1n suficientemente adaptados para responder a esta nueva situaci\u00f3n<\/strong> que podr\u00eda ir complic\u00e1ndose a\u00fan m\u00e1s debido a la aceleraci\u00f3n en los pr\u00f3ximos a\u00f1os del cambio demogr\u00e1fico (los baby boomers -la generaci\u00f3n m\u00e1s numerosa- ir\u00e1n llegando pronto a la vejez).<\/p>\n<p>Ya en los a\u00f1os noventa, en EEUU y Canad\u00e1, aparecieron algunas primeras ideas en este sentido, es decir sobre <strong>la conveniencia de dise\u00f1ar hospitales m\u00e1s adaptados a las necesidades espec\u00edficas de las y los pacientes de mayor edad<\/strong> (\u201chospitales amigables\u201d), apuntada por profesionales de la enfermer\u00eda a partir de su experiencia en atenci\u00f3n geri\u00e1trica.<\/p>\n<h3>Hospital amigable con las personas mayores<\/h3>\n<p><strong>Es un concepto multidimensional<\/strong> que por lo que sabemos empez\u00f3 a aplicarse a finales de los a\u00f1os noventa en Victoria (Vancouver Island, British Columbia, Canad\u00e1) por decisi\u00f3n de los responsables regionales de salud (the Capital Health Region). Es un tipo de hospital (o unidad hospitalaria) que adem\u00e1s de estar pensado para dar a los y las pacientes mayores una atenci\u00f3n integrada de tratamientos y cuidados con un enfoque geri\u00e1trico, est\u00e1 gestionado con una visi\u00f3n que tiene en cuenta sus diversas prioridades. Su cultura organizativa fomenta la sensibilidad, la \u00e9tica, la comunicaci\u00f3n y el trato m\u00e1s adecuado hacia la diversidad de usuarias y usuarios, garantizando tolerancia cero en toda la organizaci\u00f3n a cualquier tipo de discriminaci\u00f3n, entre ellas el edatismo. Ofrece tambi\u00e9n un dise\u00f1o muy apropiado del entorno f\u00edsico (m\u00e1s accesible, inclusivo, confortable y seguro) que maximiza el mantenimiento de las funciones de las personas mayores usuarias, asegurando su tranquilidad, respeto, intimidad, dignidad e independencia.<\/p>\n<p>El ingreso hospitalario de la gente mayor, si se gestiona desde una \u00f3ptica hol\u00edstica (bio-psico-social), con equipos multidisciplinarios y desde la Geriatr\u00eda, permite no s\u00f3lo coordinar mejor los tratamientos de las diferentes dolencias, facilitando as\u00ed la recuperaci\u00f3n, sino tambi\u00e9n orientar al\/la paciente desde el inicio en el caso de que deba enfrentarse a una nueva situaci\u00f3n funcional y\/o social al salir del hospital (por ejemplo dificultades de movilidad que requerir\u00e1n hacer modificaciones a partir de este momento en su modo de vida, asistencia, etc.). Incluso puede contribuir a racionalizar la utilizaci\u00f3n de los recursos (es importante ya que nos veremos pronto ante un escenario de incremento de la demanda de servicios y de recursos limitados para responder al mismo). Las Unidades de Geriatr\u00eda de Agudos (UGA) que existen en algunos hospitales p\u00fablicos lo han experimentado y evaluado, obteniendo resultados positivos (lamentablemente, s\u00f3lo un 12% -dato no oficial- de los hospitales p\u00fablicos dispone de una de estas unidades). Tenemos ejemplos en otros pa\u00edses de <strong>centros hospitalarios que han transformado su organizaci\u00f3n, fij\u00e1ndose como prioridad responder de una forma integral a las necesidades y preocupaciones de las y los pacientes de mayor edad.<\/strong> Como buena pr\u00e1ctica destacar\u00edamos la del <a href=\"https:\/\/sinaigeriatrics.ca\/new-culture-of-care\/\">Mount Sinai Hospital<\/a> (Canad\u00e1) y su sistema de salud (\u201cDesde la forma en que atendemos a como dise\u00f1amos nuestros espacios, el envejecimiento saludable y la geriatr\u00eda est\u00e1n ahora en el n\u00facleo de lo que hacemos\u2026Nuestros pacientes muestran 99% de satisfacci\u00f3n\u2026y nosotros hemos demostrado nuestra capacidad de ahorrar\u2026\u201d).<\/p>\n<p><strong>Creemos que es necesario conseguir que nuestros servicios sanitarios y sociosanitarios sean m\u00e1s amigables con las personas mayores<\/strong>, aunque ello suponga un esfuerzo considerable de creaci\u00f3n de nuevos espacios o adaptaci\u00f3n de los actuales, de cambios en la organizaci\u00f3n y, en muchos casos, de los protocolos de actuaci\u00f3n existentes. En Catalunya y en otras Comunidades Aut\u00f3nomas hay algunas primeras iniciativas. En Europa se van desarrollando diversos proyectos en esta direcci\u00f3n. En Canad\u00e1 son pioneros y han avanzado mucho, unos 90 hospitales de la Regi\u00f3n de Ontario se han adherido al programa de adecuaci\u00f3n con el apoyo del Health System Research Fund, entre otros ejemplos. En EEUU lo est\u00e1 impulsando la <a href=\"https:\/\/www.johnahartford.org\/%20\">John A. Hartford Foundation<\/a> y el Institute for Healthcare Improvement, con el objetivo de conseguir que el 20% de los hospitales y del sistema sanitario sean \u201cAge-friendly\u201d (amigables) para el 2020 en el marco de la acci\u00f3n de amplio alcance Age-friendly Health System initiative (\u201cEstamos transformando la forma en que la gente piensa sobre el cuidado de los mayores invirtiendo en lo que funciona\u201d, Terry Fulmer, Presidenta de la J.A.Hartford Foundation).<\/p>\n<p>Los buenos resultados que se han logrado con los servicios hospitalarios particularmente organizados para atender a las personas de mayor edad son evidentes. Para poder avanzar por este camino se precisa m\u00e1s especializaci\u00f3n en Geriatr\u00eda y Gerontolog\u00eda, m\u00e1s formaci\u00f3n del personal que trabaja en los \u00e1mbitos sanitario y sociosanitario sobre la vejez, el envejecimiento activo y saludable y la atenci\u00f3n a los mayores, y adem\u00e1s mucha determinaci\u00f3n a diferentes niveles, entre otros condicionantes. Ayudar\u00eda a este cometido hacer campa\u00f1as de sensibilizaci\u00f3n para reconocer la experiencia de las personas mayores y para mejorar su imagen que es a menudo mala debido a los estereotipos negativos y a la extremada valoraci\u00f3n de la imagen de juventud y vitalidad que vemos en los medios de comunicaci\u00f3n.<\/p>\n<p><strong>Disponer de atenci\u00f3n hospitalaria adaptada a lo que requieren las personas mayores usuarias, y especialmente las muy mayores (ancianas), es una mejora de los servicios de salud<\/strong> que podr\u00e1 seguir acometi\u00e9ndose con la intervenci\u00f3n de instituciones, planificadores sanitarios y responsables de los centros, y la implicaci\u00f3n de profesionales de la salud, de la gerontolog\u00eda, de la arquitectura y del dise\u00f1o, y otros profesionales y colectivos que trabajan, de una manera u otra, para asegurar la calidad de vida y confortabilidad de la gente mayor.<\/p>\n<p>Esta adaptaci\u00f3n forma parte de los objetivos establecidos (como marco de actuaci\u00f3n para los Estados) en la \u201cEstrategia Global y Plan de Acci\u00f3n sobre Envejecimiento y Salud\u201d (OMS, 2107) (\u201c<a href=\"https:\/\/www.who.int\/ageing\/GSAP-Summary-EN.pdf\">The Global Strategy and Action Plan on Ageing and Health<\/a>\u201d). Los objetivos son los siguientes: comprometerse a adoptar medidas sobre el envejecimiento saludable en cada pa\u00eds; crear entornos adaptados a las personas mayores; armonizar los sistemas de salud con las necesidades de las personas mayores; fomentar sistemas sostenibles y equitativos para ofrecer atenci\u00f3n a largo plazo (domiciliaria, comunitaria e institucional); y mejorar los sistemas de medici\u00f3n, seguimiento e investigaci\u00f3n en materia de envejecimiento saludable.<\/p>\n<p><strong>Desde hace tiempo, ya se viene debatiendo sobre la urgencia de revisar el modelo asistencial vigente, ante el envejecimiento de la poblaci\u00f3n, y la forma de gestionar el aumento de la cronicidad y la complejidad que representa.<\/strong> Varias iniciativas se est\u00e1n llevando a cabo con resultados muy satisfactorios, entre ellas las que se realizan en el marco del \u201cPrograma de atenci\u00f3n al paciente cr\u00f3nico complejo\u201d del sistema sanitario catal\u00e1n, pero no se ha contemplado el enfoque de amigabilidad que comportar\u00eda actuar con una perspectiva m\u00e1s global y teniendo mucho en cuenta aspectos como el dise\u00f1o de los espacios, la comunicaci\u00f3n, la diversidad, etc.<\/p>\n<p>Proponemos crear una plataforma p\u00fablico-privada que impulse la incorporaci\u00f3n del concepto de amigabilidad\u00a0(*) a estos cambios necesarios, con la participaci\u00f3n de instituciones, colegios profesionales, centros hospitalarios, fundaciones, universidades, asociaciones\u2026.Ser\u00e1 positivo para todo el mundo (pacientes, familiares, profesionales) porque<strong> los entornos amigables con las personas mayores benefician a las personas de todas las edades.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>(*)La OMS public\u00f3 en 2007 \u201c<a href=\"https:\/\/www.who.int\/ageing\/AFCSpanishfinal.pdf\">Ciudades Globales Amigables con los Mayores: Una Gu\u00eda<\/a>\u201d.\u00a0Este documento establece ocho \u00e1mbitos en los que se deber\u00eda actuar para conseguir una ciudad amigable.Uno de los \u00e1mbitos es el de los \u201cServicios sociales y de salud\u201d. Hasta ahora se ha avanzado bastante en amigabilidad con respecto a la accesibilidad de los espacios al aire libre, edificios y transportes, pero queda mucho por hacer en otros, como en los servicios de salud que para ser amigables se debe poder afirmar que<em>\u201cresponden a las necesidades y preocupaciones de las personas mayores; los profesionales de la salud poseen habilidades y capacitaci\u00f3n apropiadas para comunicarse y atender de manera efectiva a las personas mayores\u201d. <\/em>Anteriomente, en 2004, la OMS hab\u00eda recomendado aplicar el concepto de \u201camigabilidad con las personas mayores\u201d en los Centros de Atenci\u00f3n Primaria (\u201cTowards age-friendly primary health care\u201d).Para poder considerar que una ciudad o municipio es amigable con las personas mayores sus servicios sanitarios lo tendr\u00edan que ser, no habr\u00eda de olvidarse.<\/p>\n<p>&#8212;<\/p>\n<p>En CASA SOLO trabajamos con el concepto de &#8220;dise\u00f1o para todos&#8221; y proponemos hospitales 100% inclusivos, teniendo en cuenta las diferentes necesidades de sus usuarios.<\/p>\n<p>Art\u00edculo publicado en La Vanguardia el 26\/04\/2019: <a href=\"https:\/\/www.lavanguardia.com\/economia\/management\/20190424\/461837574082\/hospital-personas-mayores.html\">https:\/\/www.lavanguardia.com\/economia\/management\/20190424\/461837574082\/hospital-personas-mayores.html<\/a><\/p>\n<p><!--:-->&nbsp;<\/p>\n<p><!--:en--><a href=\"http:\/\/casasolo.es\/wp-content\/uploads\/2019\/04\/20190424_LaVanguardia_Hospital-amigable-con-las-personas-mayores_-una-adaptacio\u0301n-al-cambio-demogra\u0301fico-CASA-SOLO-11.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-1891\" src=\"http:\/\/casasolo.es\/wp-content\/uploads\/2019\/04\/20190424_LaVanguardia_Hospital-amigable-con-las-personas-mayores_-una-adaptacio\u0301n-al-cambio-demogra\u0301fico-CASA-SOLO-11.jpg\" alt=\"20190424_LaVanguardia_Hospital-amigable-con-las-personas-mayores_-una-adaptacio\u0301n-al-cambio-demogra\u0301fico-CASA-SOLO-1\" width=\"2166\" height=\"1654\" srcset=\"https:\/\/casasolo.es\/wp-content\/uploads\/2019\/04\/20190424_LaVanguardia_Hospital-amigable-con-las-personas-mayores_-una-adaptacio\u0301n-al-cambio-demogra\u0301fico-CASA-SOLO-11.jpg 2166w, https:\/\/casasolo.es\/wp-content\/uploads\/2019\/04\/20190424_LaVanguardia_Hospital-amigable-con-las-personas-mayores_-una-adaptacio\u0301n-al-cambio-demogra\u0301fico-CASA-SOLO-11-300x229.jpg 300w, https:\/\/casasolo.es\/wp-content\/uploads\/2019\/04\/20190424_LaVanguardia_Hospital-amigable-con-las-personas-mayores_-una-adaptacio\u0301n-al-cambio-demogra\u0301fico-CASA-SOLO-11-1024x782.jpg 1024w, https:\/\/casasolo.es\/wp-content\/uploads\/2019\/04\/20190424_LaVanguardia_Hospital-amigable-con-las-personas-mayores_-una-adaptacio\u0301n-al-cambio-demogra\u0301fico-CASA-SOLO-11-768x586.jpg 768w, https:\/\/casasolo.es\/wp-content\/uploads\/2019\/04\/20190424_LaVanguardia_Hospital-amigable-con-las-personas-mayores_-una-adaptacio\u0301n-al-cambio-demogra\u0301fico-CASA-SOLO-11-1536x1173.jpg 1536w, https:\/\/casasolo.es\/wp-content\/uploads\/2019\/04\/20190424_LaVanguardia_Hospital-amigable-con-las-personas-mayores_-una-adaptacio\u0301n-al-cambio-demogra\u0301fico-CASA-SOLO-11-2048x1564.jpg 2048w\" sizes=\"(max-width: 2166px) 100vw, 2166px\" \/><\/a> We are very happy to share with you the article published by La Vanguardia &#8220;Age-friendly hospital: an adaptation to demographic change&#8221; written together with our collaborator and CASA SOLO&#8217;s consultant for Age-friendly projects, Paulina Ballb\u00e8, director of the Postgraduate on Active &amp; Healthy Ageing Project Management of the BSM-Pompeu Fabra University, and Enric Duaso, specialist doctor in Geriatrics, and director of the Sociosanitary Area Service of the Health Consortium of L&#8217;Anoia. The article highlights the need to design more accessible, inclusive, comfortable and safe hospitals that maximize the maintenance of the functions of the elderly, ensuring their tranquility, respect, privacy, dignity and independence. Spain is expected to &#8220;be one of the oldest countries of the planet, due to the combination of a high life expectancy (one of the highest in the world) and a low fertility rate (one of the lowest in Europe)&#8221;. At CASA SOLO we work with the concept of &#8220;design for all&#8221; and we propose 100% inclusive hospitals, considering the different needs of its users.<\/p>\n<p>Article (in spanish): <a href=\"https:\/\/www.lavanguardia.com\/economia\/management\/20190424\/461837574082\/hospital-personas-mayores.html\">https:\/\/www.lavanguardia.com\/economia\/management\/20190424\/461837574082\/hospital-personas-mayores.html<\/a><\/p>\n<p><!--:-->&nbsp;<\/p>\n<p><!--:ca--><a href=\"http:\/\/casasolo.es\/wp-content\/uploads\/2019\/04\/20190424_LaVanguardia_Hospital-amigable-con-las-personas-mayores_-una-adaptacio\u0301n-al-cambio-demogra\u0301fico-CASA-SOLO-11.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-1891\" src=\"http:\/\/casasolo.es\/wp-content\/uploads\/2019\/04\/20190424_LaVanguardia_Hospital-amigable-con-las-personas-mayores_-una-adaptacio\u0301n-al-cambio-demogra\u0301fico-CASA-SOLO-11.jpg\" alt=\"20190424_LaVanguardia_Hospital-amigable-con-las-personas-mayores_-una-adaptacio\u0301n-al-cambio-demogra\u0301fico-CASA-SOLO-1\" width=\"2166\" height=\"1654\" srcset=\"https:\/\/casasolo.es\/wp-content\/uploads\/2019\/04\/20190424_LaVanguardia_Hospital-amigable-con-las-personas-mayores_-una-adaptacio\u0301n-al-cambio-demogra\u0301fico-CASA-SOLO-11.jpg 2166w, https:\/\/casasolo.es\/wp-content\/uploads\/2019\/04\/20190424_LaVanguardia_Hospital-amigable-con-las-personas-mayores_-una-adaptacio\u0301n-al-cambio-demogra\u0301fico-CASA-SOLO-11-300x229.jpg 300w, https:\/\/casasolo.es\/wp-content\/uploads\/2019\/04\/20190424_LaVanguardia_Hospital-amigable-con-las-personas-mayores_-una-adaptacio\u0301n-al-cambio-demogra\u0301fico-CASA-SOLO-11-1024x782.jpg 1024w, https:\/\/casasolo.es\/wp-content\/uploads\/2019\/04\/20190424_LaVanguardia_Hospital-amigable-con-las-personas-mayores_-una-adaptacio\u0301n-al-cambio-demogra\u0301fico-CASA-SOLO-11-768x586.jpg 768w, https:\/\/casasolo.es\/wp-content\/uploads\/2019\/04\/20190424_LaVanguardia_Hospital-amigable-con-las-personas-mayores_-una-adaptacio\u0301n-al-cambio-demogra\u0301fico-CASA-SOLO-11-1536x1173.jpg 1536w, https:\/\/casasolo.es\/wp-content\/uploads\/2019\/04\/20190424_LaVanguardia_Hospital-amigable-con-las-personas-mayores_-una-adaptacio\u0301n-al-cambio-demogra\u0301fico-CASA-SOLO-11-2048x1564.jpg 2048w\" sizes=\"(max-width: 2166px) 100vw, 2166px\" \/><\/a><\/p>\n<h3>Hospital amigable amb les persones grans: Una adaptaci\u00f3 al canvi demogr\u00e0fic.<\/h3>\n<p>En l&#8217;actualitat <strong>m\u00e9s del 50% de tots els<\/strong> <strong>ingressos hospitalaris corresponen a persones de m\u00e9s de 65 anys,<\/strong> amb estades m\u00e9s llargues que la resta de la poblaci\u00f3 i amb reingressos m\u00e9s freq\u00fcents (dades 2017 de la sanitat p\u00fablica, Unitat d&#8217;Informaci\u00f3 i Coneixement, CatSalut).<\/p>\n<p>El canvi demogr\u00e0fic al nostre pa\u00eds tindr\u00e0 una progressi\u00f3 espectacular. Es preveu que <strong>serem un dels pa\u00efsos m\u00e9s envellits del planeta<\/strong>, a causa de la combinaci\u00f3 d&#8217;una alta esperan\u00e7a de vida (de les m\u00e9s elevades del m\u00f3n) i una baixa taxa de fecunditat (de les m\u00e9s baixes d&#8217;Europa). Les dades ens ho mostren: El 1960 la poblaci\u00f3 de 65 anys i m\u00e9s era del 8&#8217;2% (dada de l&#8217;INE), el 2018 del 18,8% i, previsiblement, el 2030 arribar\u00e0 al 25% i el 2050 al 30% (gaireb\u00e9 triplicant el nombre de majors de 85 anys). A 1 de gener del 2018 hi havia 119,3 persones majors de 65 anys per cada 100 menors de 15 anys (\u00edndex d&#8217;envelliment). Del total de majors de 65 anys (1.417.311), el 16&#8217;7% tenia m\u00e9s de 85 anys (236.434) (\u00edndex de sobreenvelliment) (dades de Catalunya IDESCAT).<\/p>\n<p><strong>Aquest gran augment del percentatge de gent gran (&#8220;la revoluci\u00f3 de la longevitat&#8221;) ha produ\u00eft un desfasament entre la concepci\u00f3 dels hospitals, com a unitats pensades per tractar les patologies agudes sobretot en pacients joves, i el fet que l&#8217;envelliment de la poblaci\u00f3 faci que les persones grans siguin les seves usu\u00e0ries majorit\u00e0ries.<\/strong><\/p>\n<p>Les persones grans i sobretot les molt grans, usu\u00e0ries dels serveis hospitalaris, s\u00f3n especialment vulnerables perqu\u00e8 poden patir amb freq\u00fc\u00e8ncia i de forma simult\u00e0nia diverses malalties cr\u00f2niques, juntament amb alteraci\u00f3 dels \u00f2rgans sensorials o p\u00e8rdua de funcions cognitives o de mobilitat, i de vegades tot aix\u00f2 al mateix temps. A causa de la seva fragilitat (entesa com a risc de depend\u00e8ncia) \u00e9s m\u00e9s probable que l&#8217;estada a l&#8217;hospital (incloent les unitats d&#8217;urg\u00e8ncies), constitueixi per a elles un fet determinant. Per totes aquestes circumst\u00e0ncies, la seva hospitalitzaci\u00f3 \u00e9s m\u00e9s complexa, caracter\u00edstica que si no \u00e9s atesa amb coneixement expert o no \u00e9s tinguda prou en compte, pot derivar en complicacions, com per exemple en una possible disminuci\u00f3 de les seves capacitats cognitives i \/ o motrius, i que resulti en una menor independ\u00e8ncia al moment de l&#8217;alta hospital\u00e0ria. Aquestes complicacions poden comportar aix\u00ed mateix una al\u00e7a significativa de les despeses (perman\u00e8ncies m\u00e9s llargues, reingressos, augment de la depend\u00e8ncia &#8230;).<\/p>\n<p><strong>Ens trobem, doncs, davant un canvi de tipologia en la majoria de les persones usu\u00e0ries: s\u00f3n m\u00e9s grans i presenten sovint pluripatologia i cronicitat. Els nostres establiments hospitalaris no estan prou adaptats per respondre a aquesta nova situaci\u00f3<\/strong> que es podria anar complicant encara m\u00e9s a causa de l&#8217;acceleraci\u00f3 en els propers anys del canvi demogr\u00e0fic (els <em>baby boomers<\/em> -la generaci\u00f3 m\u00e9s nombrosa- aniran arribant aviat a la vellesa). Ja en els anys noranta, als EUA i al Canad\u00e0, van apar\u00e8ixer algunes primeres idees en aquest sentit, \u00e9s a dir sobre <strong>la conveni\u00e8ncia de dissenyar hospitals m\u00e9s adaptats a les necessitats espec\u00edfiques de les i els pacients de major edat<\/strong> (&#8220;hospitals amigables&#8221;), apuntada per professionals de la infermeria a partir de la seva experi\u00e8ncia en atenci\u00f3 geri\u00e0trica.<\/p>\n<h3>Hospital amigable amb les persones grans<\/h3>\n<p><strong>\u00c9s un concepte multidimensional<\/strong> que pel que sabem va comen\u00e7ar a aplicar-se a finals dels anys noranta a Vict\u00f2ria (Vancouver Island, British Columbia, Canad\u00e0) per decisi\u00f3 dels responsables regionals de salut (the Capital Health Region). \u00c9s un tipus d&#8217;hospital (o d\u2019unitat hospital\u00e0ria) que a m\u00e9s d&#8217;estar pensat per donar als i les pacients de major edat una atenci\u00f3 integrada de tractaments i cures amb un enfocament geri\u00e0tric, est\u00e0 gestionat amb una visi\u00f3 que t\u00e9 en compte les seves diverses prioritats. La seva cultura organitzativa fomenta la sensibilitat, l&#8217;\u00e8tica, la comunicaci\u00f3 i el tracte m\u00e9s adequat cap a la diversitat d&#8217;usu\u00e0ries i usuaris, garantint toler\u00e0ncia zero en tota l&#8217;organitzaci\u00f3 a qualsevol tipus de discriminaci\u00f3, entre elles l\u2019edatisme. Ofereix tamb\u00e9 un disseny molt apropiat de l&#8217;entorn f\u00edsic (m\u00e9s accessible, inclusiu, confortable i segur) que maximitza el manteniment de les funcions des persones grans usu\u00e0ries, assegurant la seva tranquil\u00b7litat, respecte, intimitat, dignitat i independ\u00e8ncia.<\/p>\n<p>L&#8217;ingr\u00e9s hospitalari de les persones grans, si es gestiona des d&#8217;una \u00f2ptica hol\u00edstica (bio-psico-social), amb equips multidisciplinaris i des de la Geriatria, permet no nom\u00e9s coordinar millor els tractaments de les diferents malalties, facilitant aix\u00ed la recuperaci\u00f3, sin\u00f3 tamb\u00e9 orientar el \/ la pacient des de l&#8217;inici en el cas que s&#8217;hagi d&#8217;enfrontar a una nova situaci\u00f3 funcional i \/ o social en sortir de l&#8217;hospital (per exemple dificultats de mobilitat que requeriran fer modificacions a partir d&#8217;aquest moment en la seva manera de viure, assist\u00e8ncia, etc.). Fins i tot pot contribuir a racionalitzar la utilitzaci\u00f3 dels recursos (\u00e9s important ja que ens veurem aviat davant un escenari d&#8217;increment de la demanda de serveis i de recursos limitats per respondre al mateix). Les Unitats de Geriatria d&#8217;Aguts (UGA) que hi ha en alguns hospitals p\u00fablics ho han experimentat i avaluat, obtenint resultats positius (lamentablement, nom\u00e9s un 12% -dada no oficial- dels hospitals p\u00fablics disposa d&#8217;una d&#8217;aquestes unitats). Tenim exemples en altres pa\u00efsos de <strong>centres hospitalaris que han transformat la seva organitzaci\u00f3, fixant com a prioritat respondre d&#8217;una manera integral a les necessitats i preocupacions de les i els pacients de major edat.<\/strong> Com a bona pr\u00e0ctica destacar\u00edem la del <a href=\"https:\/\/sinaigeriatrics.ca\/new-culture-of-care\/\">Mount Sinai Hospital<\/a>\u00a0(Canad\u00e0) i el seu sistema de salut (&#8220;Des de la forma en qu\u00e8 atenem a com dissenyem els nostres espais, l&#8217;envelliment saludable i la geriatria estan ara en el nucli del que fem &#8230; Els nostres pacients mostren un 99% de satisfacci\u00f3 &#8230; i nosaltres hem demostrat la nostra capacitat d&#8217;estalviar &#8230; &#8220;).<\/p>\n<p><strong>Creiem que cal aconseguir que els nostres serveis sanitaris i sociosanitaris siguin m\u00e9s amigables amb les persones grans<\/strong>, encara que aix\u00f2 suposi un esfor\u00e7 considerable de creaci\u00f3 de nous espais o adaptaci\u00f3 dels actuals, de canvis en l&#8217;organitzaci\u00f3 i, en molts casos, dels protocols d&#8217;actuaci\u00f3 existents. A Catalunya i en altres Comunitats Aut\u00f2nomes hi ha algunes primeres iniciatives. A Europa es van desenvolupant diversos projectes en aquesta direcci\u00f3. A Canad\u00e0 s\u00f3n pioners i han avan\u00e7at molt, uns 90 hospitals de la Regi\u00f3 d&#8217;Ontario s&#8217;han adherit al programa d&#8217;adequaci\u00f3 amb el suport del Health System Research Fund, entre d&#8217;altres exemples. Als EUA ho est\u00e0 impulsant la <a href=\"https:\/\/www.johnahartford.org\/\">John A. Hartford Foundation<\/a> i l&#8217;Institute for Healthcare Improvement, amb l&#8217;objectiu d&#8217;aconseguir que el 20% dels hospitals i del sistema sanitari siguin &#8220;Age-friendly&#8221; (amigables) al 2020, en el marc de l&#8217;acci\u00f3 d&#8217;ampli abast Age-friendly Health System initiative (&#8220;Estem transformant la forma en qu\u00e8 la gent pensa sobre la cura de la gent gran invertint en el que funciona&#8221;, Terry Fulmer, Presidenta de la JAHartford Foundation).<\/p>\n<p>Els bons resultats que s&#8217;han aconseguit amb els serveis hospitalaris particularment organitzats per atendre les persones de m\u00e9s edat s\u00f3n evidents. Per poder avan\u00e7ar per aquest cam\u00ed es necessita m\u00e9s especialitzaci\u00f3 en Geriatria i Gerontologia, m\u00e9s formaci\u00f3 del personal que treballa en els \u00e0mbits sanitari i sociosanitari sobre la vellesa, l&#8217;envelliment actiu i saludable i l&#8217;atenci\u00f3 a la gent gran, i a m\u00e9s molta determinaci\u00f3 a diferents nivells, entre d&#8217;altres condicionants. Ajudaria a aquesta comesa fer campanyes de sensibilitzaci\u00f3 per recon\u00e8ixer el valor de l&#8217;experi\u00e8ncia de les persones grans, aix\u00f2 milloraria la seva imatge que \u00e9s sovint dolenta a causa dels estereotips negatius i de l&#8217;extremada valoraci\u00f3 de la imatge de joventut i vitalitat que veiem en els mitjans de comunicaci\u00f3.<\/p>\n<p><strong>Disposar d&#8217;atenci\u00f3 hospital\u00e0ria adaptada al que requereixen les persones grans usu\u00e0ries, i especialment les molt grans (ancianes), \u00e9s una millora dels serveis de salut<\/strong> que es podr\u00e0 seguir escometent amb la intervenci\u00f3 d&#8217;institucions, planificadors sanitaris i responsables dels centres, i la implicaci\u00f3 de professionals de la salut, de la gerontologia, de l&#8217;arquitectura i del disseny, i altres professionals i col\u00b7lectius que treballen, d&#8217;una manera o altra, per assegurar la qualitat de vida i confortabilitat de la gent gran.<\/p>\n<p>Aquesta adaptaci\u00f3 forma part dels objectius establerts (com a marc d&#8217;actuaci\u00f3 per als Estats) a l\u2019 &#8220;Estrat\u00e8gia Global i Pla d&#8217;Acci\u00f3 sobre Envelliment i Salut&#8221; (OMS, 2107) (<a href=\"https:\/\/www.who.int\/ageing\/GSAP-Summary-EN.pdf\">&#8220;The Global Strategy and Action Plan on Ageing and Health&#8221;<\/a>). Els objectius s\u00f3n els seg\u00fcents: comprometre a adoptar mesures sobre l&#8217;envelliment saludable a cada pa\u00eds; crear entorns adaptats a les persones grans; harmonitzar els sistemes de salut amb les necessitats de les persones grans; fomentar sistemes sostenibles i equitatius per oferir atenci\u00f3 a llarg termini (domicili\u00e0ria, comunit\u00e0ria i institucional); i millorar els sistemes de mesurament, seguiment i recerca en mat\u00e8ria d&#8217;envelliment saludable.<\/p>\n<p><strong>Des de fa temps, ja es ve debatent sobre la urg\u00e8ncia de revisar el model assistencial vigent, davant l&#8217;envelliment de la poblaci\u00f3, i la forma de gestionar l&#8217;augment de la cronicitat i la complexitat que representa.<\/strong> Diverses iniciatives s&#8217;estan duent a terme amb resultats molt satisfactoris, entre elles les que es realitzen en el marc del &#8220;Programa d&#8217;atenci\u00f3 al pacient cr\u00f2nic complex&#8221; del sistema sanitari catal\u00e0, per\u00f2 no s&#8217;ha contemplat l&#8217;enfocament d\u2019 amigabilitat que comportaria actuar amb una perspectiva m\u00e9s global i tenint molt en compte aspectes com el disseny dels espais, la comunicaci\u00f3, la diversitat, etc.<\/p>\n<p>Proposem crear una plataforma p\u00fablic-privada que impulsi la incorporaci\u00f3 del concepte de amigabilitat (*) a aquests canvis necessaris, amb la participaci\u00f3 d&#8217;institucions, col\u00b7legis professionals, centres hospitalaris, fundacions, universitats, associacions &#8230; Ser\u00e0 positiu per a tothom (pacients, familiars, professionals) perqu\u00e8 <strong>els entorns amigables amb la gent gran beneficien les persones de totes les edats.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>(*)<\/strong> L&#8217;OMS va publicar el 2007 &#8220;<a href=\"https:\/\/www.who.int\/ageing\/AFCSpanishfinal.pdf\">Ciutats Globals Amigables amb les Persones Grans: Una Guia<\/a>&#8220;. Aquest document estableix vuit \u00e0mbits en qu\u00e8 s&#8217;hauria d&#8217;actuar per aconseguir una ciutat amigable. Un dels \u00e0mbits \u00e9s el dels &#8220;Serveis socials i de salut&#8221;. Fins ara s&#8217;ha avan\u00e7at for\u00e7a en amigabilitat pel que fa a l&#8217;accessibilitat dels espais a l&#8217;aire lliure, edificis i transports, per\u00f2 queda molt per fer en altres, com en els serveis de salut, que per ser amigables s&#8217;ha de poder afirmar que &#8220;responen a les necessitats i preocupacions de la gent gran; els professionals de la salut posseeixen habilitats i capacitaci\u00f3 apropiades per comunicar-se i atendre de manera efectiva a la gent gran&#8221;. Anteriorment, el 2004, l&#8217;OMS havia recomanat aplicar el concepte de &#8220;amigabilitat amb les persones grans&#8221; en els Centres d&#8217;Atenci\u00f3 Prim\u00e0ria ( &#8220;Towards Age-friendly Primary Health Care&#8221;). Per poder considerar que una ciutat o municipi \u00e9s amigable amb les persones grans els seus serveis sanitaris ho haurien de ser, no hauria d&#8217;oblidar-se.<\/p>\n<p>&#8212;<\/p>\n<p>A CASA SOLO treballem amb el concepte de &#8220;disseny per a tots&#8221; i proposem hospitals 100% inclusius, tenint en compte les diferents necessitats dels seus usuaris.<\/p>\n<p>Article: <a href=\"https:\/\/www.lavanguardia.com\/economia\/management\/20190424\/461837574082\/hospital-personas-mayores.html\">https:\/\/www.lavanguardia.com\/economia\/management\/20190424\/461837574082\/hospital-personas-mayores.html<\/a><\/p>\n<p><!--:--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ingreso hospitalario de la gente mayor, si se gestiona desde una \u00f3ptica hol\u00edstica con equipos multidisciplinarios permite coordinar mejor los tratamientos y orientar al paciente En la actualidad m\u00e1s del 50% de todos los ingresos hospitalarios corresponden a personas de m\u00e1s de 65 a\u00f1os, con estancias m\u00e1s largas que el resto de la poblaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":1889,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[28,6],"tags":[71,13,72],"class_list":["post-1884","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gente-mayor","category-news","tag-age-friendly","tag-diseno-hospitales","tag-la-vanguardia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hospital amigable con las personas mayores - CASA SOLO<\/title>\n<meta name=\"description\" content=\"Hospital amigable, art\u00edculo publicado por La Vanguardia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casasolo.es\/ca\/hospital-amigable-con-las-personas-mayores-una-adaptacion-al-cambio-demografico-en-la-vanguardia\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hospital amigable con las personas mayores - CASA SOLO\" \/>\n<meta property=\"og:description\" content=\"Hospital amigable, art\u00edculo publicado por La Vanguardia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casasolo.es\/ca\/hospital-amigable-con-las-personas-mayores-una-adaptacion-al-cambio-demografico-en-la-vanguardia\/\" \/>\n<meta property=\"og:site_name\" content=\"CASA SOLO arquitectos\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-25T14:28:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casasolo.es\/wp-content\/uploads\/2019\/04\/img_isainzdebaranda_20170417-140143_imagenes_lv_propias_isainzdebaranda_hospital2-057-knKD-U461837574082qOH-992x558@LaVanguardia-Web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"992\" \/>\n\t<meta property=\"og:image:height\" content=\"558\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"casaweb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"casaweb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"20 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/casasolo.es\/ca\/hospital-amigable-con-las-personas-mayores-una-adaptacion-al-cambio-demografico-en-la-vanguardia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/casasolo.es\/ca\/hospital-amigable-con-las-personas-mayores-una-adaptacion-al-cambio-demografico-en-la-vanguardia\/\"},\"author\":{\"name\":\"casaweb\",\"@id\":\"https:\/\/casasolo.es\/ca\/#\/schema\/person\/5fc60cf44aa387460af4ccaa862ac1b4\"},\"headline\":\"&#8220;Hospital amigable con las personas mayores: una adaptaci\u00f3n al cambio demogr\u00e1fico&#8221; en La Vanguardia\",\"datePublished\":\"2019-04-25T14:28:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/casasolo.es\/ca\/hospital-amigable-con-las-personas-mayores-una-adaptacion-al-cambio-demografico-en-la-vanguardia\/\"},\"wordCount\":3970,\"publisher\":{\"@id\":\"https:\/\/casasolo.es\/ca\/#organization\"},\"image\":{\"@id\":\"https:\/\/casasolo.es\/ca\/hospital-amigable-con-las-personas-mayores-una-adaptacion-al-cambio-demografico-en-la-vanguardia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2019\/04\/img_isainzdebaranda_20170417-140143_imagenes_lv_propias_isainzdebaranda_hospital2-057-knKD-U461837574082qOH-992x558@LaVanguardia-Web.jpg\",\"keywords\":[\"age-friendly\",\"dise\u00f1o hospitales\",\"La Vanguardia\"],\"articleSection\":[\"Gente mayor\",\"Noticias Corporativas\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/casasolo.es\/ca\/hospital-amigable-con-las-personas-mayores-una-adaptacion-al-cambio-demografico-en-la-vanguardia\/\",\"url\":\"https:\/\/casasolo.es\/ca\/hospital-amigable-con-las-personas-mayores-una-adaptacion-al-cambio-demografico-en-la-vanguardia\/\",\"name\":\"Hospital amigable con las personas mayores - CASA SOLO\",\"isPartOf\":{\"@id\":\"https:\/\/casasolo.es\/ca\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/casasolo.es\/ca\/hospital-amigable-con-las-personas-mayores-una-adaptacion-al-cambio-demografico-en-la-vanguardia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/casasolo.es\/ca\/hospital-amigable-con-las-personas-mayores-una-adaptacion-al-cambio-demografico-en-la-vanguardia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2019\/04\/img_isainzdebaranda_20170417-140143_imagenes_lv_propias_isainzdebaranda_hospital2-057-knKD-U461837574082qOH-992x558@LaVanguardia-Web.jpg\",\"datePublished\":\"2019-04-25T14:28:10+00:00\",\"description\":\"Hospital amigable, art\u00edculo publicado por La Vanguardia.\",\"breadcrumb\":{\"@id\":\"https:\/\/casasolo.es\/ca\/hospital-amigable-con-las-personas-mayores-una-adaptacion-al-cambio-demografico-en-la-vanguardia\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/casasolo.es\/ca\/hospital-amigable-con-las-personas-mayores-una-adaptacion-al-cambio-demografico-en-la-vanguardia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/casasolo.es\/ca\/hospital-amigable-con-las-personas-mayores-una-adaptacion-al-cambio-demografico-en-la-vanguardia\/#primaryimage\",\"url\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2019\/04\/img_isainzdebaranda_20170417-140143_imagenes_lv_propias_isainzdebaranda_hospital2-057-knKD-U461837574082qOH-992x558@LaVanguardia-Web.jpg\",\"contentUrl\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2019\/04\/img_isainzdebaranda_20170417-140143_imagenes_lv_propias_isainzdebaranda_hospital2-057-knKD-U461837574082qOH-992x558@LaVanguardia-Web.jpg\",\"width\":992,\"height\":558},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/casasolo.es\/ca\/hospital-amigable-con-las-personas-mayores-una-adaptacion-al-cambio-demografico-en-la-vanguardia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/casasolo.es\/ca\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abHospital amigable con las personas mayores: una adaptaci\u00f3n al cambio demogr\u00e1fico\u00bb en La Vanguardia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/casasolo.es\/ca\/#website\",\"url\":\"https:\/\/casasolo.es\/ca\/\",\"name\":\"CASA SOLO arquitectos\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/casasolo.es\/ca\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/casasolo.es\/ca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/casasolo.es\/ca\/#organization\",\"name\":\"CASA SOLO arquitectos\",\"url\":\"https:\/\/casasolo.es\/ca\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/casasolo.es\/ca\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2021\/10\/casasolo-logo.svg\",\"contentUrl\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2021\/10\/casasolo-logo.svg\",\"caption\":\"CASA SOLO arquitectos\"},\"image\":{\"@id\":\"https:\/\/casasolo.es\/ca\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/casasolo.es\/ca\/#\/schema\/person\/5fc60cf44aa387460af4ccaa862ac1b4\",\"name\":\"casaweb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/casasolo.es\/ca\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fc9cf1dfa9383b5d06e9ea4952a17ca69d4f4a2f3a07f60d4b52a5cd6e11ca07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fc9cf1dfa9383b5d06e9ea4952a17ca69d4f4a2f3a07f60d4b52a5cd6e11ca07?s=96&d=mm&r=g\",\"caption\":\"casaweb\"},\"url\":\"https:\/\/casasolo.es\/ca\/author\/casaweb\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hospital amigable con las personas mayores - CASA SOLO","description":"Hospital amigable, art\u00edculo publicado por La Vanguardia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casasolo.es\/ca\/hospital-amigable-con-las-personas-mayores-una-adaptacion-al-cambio-demografico-en-la-vanguardia\/","og_locale":"ca_ES","og_type":"article","og_title":"Hospital amigable con las personas mayores - CASA SOLO","og_description":"Hospital amigable, art\u00edculo publicado por La Vanguardia.","og_url":"https:\/\/casasolo.es\/ca\/hospital-amigable-con-las-personas-mayores-una-adaptacion-al-cambio-demografico-en-la-vanguardia\/","og_site_name":"CASA SOLO arquitectos","article_published_time":"2019-04-25T14:28:10+00:00","og_image":[{"width":992,"height":558,"url":"https:\/\/casasolo.es\/wp-content\/uploads\/2019\/04\/img_isainzdebaranda_20170417-140143_imagenes_lv_propias_isainzdebaranda_hospital2-057-knKD-U461837574082qOH-992x558@LaVanguardia-Web.jpg","type":"image\/jpeg"}],"author":"casaweb","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"casaweb","Temps estimat de lectura":"20 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/casasolo.es\/ca\/hospital-amigable-con-las-personas-mayores-una-adaptacion-al-cambio-demografico-en-la-vanguardia\/#article","isPartOf":{"@id":"https:\/\/casasolo.es\/ca\/hospital-amigable-con-las-personas-mayores-una-adaptacion-al-cambio-demografico-en-la-vanguardia\/"},"author":{"name":"casaweb","@id":"https:\/\/casasolo.es\/ca\/#\/schema\/person\/5fc60cf44aa387460af4ccaa862ac1b4"},"headline":"&#8220;Hospital amigable con las personas mayores: una adaptaci\u00f3n al cambio demogr\u00e1fico&#8221; en La Vanguardia","datePublished":"2019-04-25T14:28:10+00:00","mainEntityOfPage":{"@id":"https:\/\/casasolo.es\/ca\/hospital-amigable-con-las-personas-mayores-una-adaptacion-al-cambio-demografico-en-la-vanguardia\/"},"wordCount":3970,"publisher":{"@id":"https:\/\/casasolo.es\/ca\/#organization"},"image":{"@id":"https:\/\/casasolo.es\/ca\/hospital-amigable-con-las-personas-mayores-una-adaptacion-al-cambio-demografico-en-la-vanguardia\/#primaryimage"},"thumbnailUrl":"https:\/\/casasolo.es\/wp-content\/uploads\/2019\/04\/img_isainzdebaranda_20170417-140143_imagenes_lv_propias_isainzdebaranda_hospital2-057-knKD-U461837574082qOH-992x558@LaVanguardia-Web.jpg","keywords":["age-friendly","dise\u00f1o hospitales","La Vanguardia"],"articleSection":["Gente mayor","Noticias Corporativas"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/casasolo.es\/ca\/hospital-amigable-con-las-personas-mayores-una-adaptacion-al-cambio-demografico-en-la-vanguardia\/","url":"https:\/\/casasolo.es\/ca\/hospital-amigable-con-las-personas-mayores-una-adaptacion-al-cambio-demografico-en-la-vanguardia\/","name":"Hospital amigable con las personas mayores - CASA SOLO","isPartOf":{"@id":"https:\/\/casasolo.es\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casasolo.es\/ca\/hospital-amigable-con-las-personas-mayores-una-adaptacion-al-cambio-demografico-en-la-vanguardia\/#primaryimage"},"image":{"@id":"https:\/\/casasolo.es\/ca\/hospital-amigable-con-las-personas-mayores-una-adaptacion-al-cambio-demografico-en-la-vanguardia\/#primaryimage"},"thumbnailUrl":"https:\/\/casasolo.es\/wp-content\/uploads\/2019\/04\/img_isainzdebaranda_20170417-140143_imagenes_lv_propias_isainzdebaranda_hospital2-057-knKD-U461837574082qOH-992x558@LaVanguardia-Web.jpg","datePublished":"2019-04-25T14:28:10+00:00","description":"Hospital amigable, art\u00edculo publicado por La Vanguardia.","breadcrumb":{"@id":"https:\/\/casasolo.es\/ca\/hospital-amigable-con-las-personas-mayores-una-adaptacion-al-cambio-demografico-en-la-vanguardia\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casasolo.es\/ca\/hospital-amigable-con-las-personas-mayores-una-adaptacion-al-cambio-demografico-en-la-vanguardia\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/casasolo.es\/ca\/hospital-amigable-con-las-personas-mayores-una-adaptacion-al-cambio-demografico-en-la-vanguardia\/#primaryimage","url":"https:\/\/casasolo.es\/wp-content\/uploads\/2019\/04\/img_isainzdebaranda_20170417-140143_imagenes_lv_propias_isainzdebaranda_hospital2-057-knKD-U461837574082qOH-992x558@LaVanguardia-Web.jpg","contentUrl":"https:\/\/casasolo.es\/wp-content\/uploads\/2019\/04\/img_isainzdebaranda_20170417-140143_imagenes_lv_propias_isainzdebaranda_hospital2-057-knKD-U461837574082qOH-992x558@LaVanguardia-Web.jpg","width":992,"height":558},{"@type":"BreadcrumbList","@id":"https:\/\/casasolo.es\/ca\/hospital-amigable-con-las-personas-mayores-una-adaptacion-al-cambio-demografico-en-la-vanguardia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/casasolo.es\/ca\/home\/"},{"@type":"ListItem","position":2,"name":"\u00abHospital amigable con las personas mayores: una adaptaci\u00f3n al cambio demogr\u00e1fico\u00bb en La Vanguardia"}]},{"@type":"WebSite","@id":"https:\/\/casasolo.es\/ca\/#website","url":"https:\/\/casasolo.es\/ca\/","name":"CASA SOLO arquitectos","description":"","publisher":{"@id":"https:\/\/casasolo.es\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casasolo.es\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/casasolo.es\/ca\/#organization","name":"CASA SOLO arquitectos","url":"https:\/\/casasolo.es\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/casasolo.es\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/casasolo.es\/wp-content\/uploads\/2021\/10\/casasolo-logo.svg","contentUrl":"https:\/\/casasolo.es\/wp-content\/uploads\/2021\/10\/casasolo-logo.svg","caption":"CASA SOLO arquitectos"},"image":{"@id":"https:\/\/casasolo.es\/ca\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/casasolo.es\/ca\/#\/schema\/person\/5fc60cf44aa387460af4ccaa862ac1b4","name":"casaweb","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/casasolo.es\/ca\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fc9cf1dfa9383b5d06e9ea4952a17ca69d4f4a2f3a07f60d4b52a5cd6e11ca07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fc9cf1dfa9383b5d06e9ea4952a17ca69d4f4a2f3a07f60d4b52a5cd6e11ca07?s=96&d=mm&r=g","caption":"casaweb"},"url":"https:\/\/casasolo.es\/ca\/author\/casaweb\/"}]}},"_links":{"self":[{"href":"https:\/\/casasolo.es\/ca\/wp-json\/wp\/v2\/posts\/1884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casasolo.es\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casasolo.es\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casasolo.es\/ca\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/casasolo.es\/ca\/wp-json\/wp\/v2\/comments?post=1884"}],"version-history":[{"count":0,"href":"https:\/\/casasolo.es\/ca\/wp-json\/wp\/v2\/posts\/1884\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casasolo.es\/ca\/wp-json\/wp\/v2\/media\/1889"}],"wp:attachment":[{"href":"https:\/\/casasolo.es\/ca\/wp-json\/wp\/v2\/media?parent=1884"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casasolo.es\/ca\/wp-json\/wp\/v2\/categories?post=1884"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casasolo.es\/ca\/wp-json\/wp\/v2\/tags?post=1884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}