{"id":1224,"date":"2015-12-17T15:35:42","date_gmt":"2015-12-17T15:35:42","guid":{"rendered":"http:\/\/casasolo.es\/?p=1224"},"modified":"2015-12-17T15:35:42","modified_gmt":"2015-12-17T15:35:42","slug":"diseno-de-espacios-para-mayores-apartamentos-tutelados-y-centros-sociosanitarios","status":"publish","type":"post","link":"https:\/\/casasolo.es\/ca\/diseno-de-espacios-para-mayores-apartamentos-tutelados-y-centros-sociosanitarios\/","title":{"rendered":"Dise\u00f1o de espacios para mayores:  apartamentos tutelados y centros sociosanitarios"},"content":{"rendered":"<p><!--:es--><\/p>\n<p>En los \u00faltimos a\u00f1os se est\u00e1 haciendo palpable el progresivo envejecimiento de la poblaci\u00f3n. La medicina y la mejora de la calidad de vida permiten a una persona disfrutar de una media de 15 a 20 a\u00f1os de jubilaci\u00f3n. <\/p>\n<p>En 2015, un 17% de los espa\u00f1oles son mayores de 65 a\u00f1os y se prev\u00e9 que durante los pr\u00f3ximos 50 a\u00f1os este porcentaje aumente hasta el 37%.<\/p>\n<p>Los retos que conlleva el aumento de la media de edad de la poblaci\u00f3n en relaci\u00f3n al desarrollo y mantenimiento de una sociedad mayor estable econ\u00f3mica y socialmente son una de las principales preocupaciones de los pa\u00edses desarrollados y en este sentido, la Asamblea Mundial sobre el envejecimiento estableci\u00f3 recientemente unas directrices de acci\u00f3n para cumplir el objetivo de asegurar que la sociedad envejezca de una manera digna y segura.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" src=\"http:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-00.jpg\" alt=\"espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-00\" width=\"1200\" height=\"763\" class=\"alignnone size-full wp-image-1230\" srcset=\"https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-00.jpg 1200w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-00-300x191.jpg 300w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-00-1024x651.jpg 1024w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-00-768x488.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p>Dentro del marco de estas condiciones de dignidad y seguridad, aparece la creaci\u00f3n de espacios de calidad para las personas de avanzada edad, en el que el dise\u00f1o arquitect\u00f3nico toma un papel relevante.<\/p>\n<p>Las tipolog\u00edas edificatorias destinadas a la atenci\u00f3n y mejora de la calidad de vida de nuestros mayores son muy variadas y van desde los centros m\u00e9dicos especializados a centros de d\u00eda, residencias o apartamentos tutelados que garantizan la independencia de la persona.<\/p>\n<p>En este sentido, hoy hemos querido analizar el dise\u00f1o de los centros residenciales tanto en su modalidad residencial como en la tipolog\u00eda de apartamento, dos tipolog\u00edas en auge que se han venido implementando con mucho \u00e9xito en Estados Unidos desde hace ya varias d\u00e9cadas y que en los \u00faltimos a\u00f1os est\u00e1n empezando a implementarse como alternativa en Europa y Am\u00e9rica del Sur, donde tradicionalmente el cuidado y atenci\u00f3n de los mayores se mantiene en el hogar familiar.<\/p>\n<h2>Tipolog\u00edas de espacios y servicios para la gente mayor<\/h2>\n<p>Las alternativas a la atenci\u00f3n domiciliaria -ya sea en casa de un familiar o en la propia vivienda-, son las residencias y los apartamentos tutelados en funci\u00f3n del nivel de dependencia de la persona mayor.<\/p>\n<p>En ambos casos como veremos, la arquitectura y el dise\u00f1o de los espacios van a jugar un papel clave en el bienestar y calidad de vida de los usuarios. <\/p>\n<h3>Los apartamentos tutelados<\/h3>\n<p>Las viviendas para mayores tuteladas son zonas residenciales que mantienen la independencia del residente pero que gozan de una serie de servicios especializados y destinados a garantizar la seguridad y bienestar del usuario. <\/p>\n<p>Estos centros pueden estar ubicados en el centro urbano y conectados con los servicios de la propia ciudad o bien ser unidades aisladas que disponen de servicios propios como supermercado, peluquer\u00eda o asistencia m\u00e9dica. En ambos casos las zonas comunes van a jugar un papel esencial en la formaci\u00f3n de una comunidad estable de residentes.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-01.jpg\" alt=\"espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-01\" width=\"1200\" height=\"800\" class=\"alignnone size-full wp-image-1231\" srcset=\"https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-01.jpg 1200w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-01-300x200.jpg 300w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-01-1024x683.jpg 1024w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-01-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p>Las viviendas est\u00e1n dise\u00f1adas para ser c\u00f3modas y seguras, pensando en personas jubiladas o pr\u00f3ximas a la jubilaci\u00f3n que no se sientan &#8220;tercera edad&#8221; o ancianos, sino que est\u00e9n activos y busquen un entorno agradable y seguro donde pasar unos meses al a\u00f1o o vivir de forma definitiva.<\/p>\n<p>El dise\u00f1o de los espacios adem\u00e1s de estar totalmente adaptados, tiene muy en cuenta la iluminaci\u00f3n natural y la ventilaci\u00f3n, sobre todo en los espacios comunes, as\u00ed como la creaci\u00f3n de zonas de sombra exteriores para facilitar la actividad al aire libre de la gente mayor. <\/p>\n<p>Los pisos tutelados, adem\u00e1s, pueden estar adaptados a los requerimientos f\u00edsicos de cada caso concreto, como pueden ser viviendas para personas con alteraciones en la visi\u00f3n, en el o\u00eddo o en la psicomotricidad.<\/p>\n<p>En todos los casos los pisos tutelados est\u00e1n pensados para personas con un cierto nivel de independencia y pueden estar conectados con una residencia para personas dependientes que permita al inquilino mantener su residencia en el mismo complejo en caso de pasar a necesitar de forma temporal o permanente asistencia en su vida diaria.<\/p>\n<h3>Los centros sociosanitarios<\/h3>\n<p>Los centros sociosanitarios se diferencian de los pisos tutelados en cuanto a la autonom\u00eda de sus usuarios. <\/p>\n<p>En los pisos tutelados encontraremos personas con absoluta independencia para realizar las tareas diarias de higiene, alimentaci\u00f3n e incluso est\u00e1n capacitados para llevar a cado otras actividades m\u00e1s complejas.<\/p>\n<p>En los centros sociosanitarios la situaci\u00f3n es de una mayor dependencia y requiere la asistencia continuada de profesionales m\u00e9dicos y de enfermer\u00eda. Las exigencias t\u00e9cnicas de dise\u00f1o de este tipo de centros as\u00ed como la normativa aplicable son parecidas a las de un hospital.<\/p>\n<p>En cuanto a tipolog\u00edas de centros, \u00e9stas se distinguen en funci\u00f3n del tiempo y de las condiciones en que se asistir\u00e1n a las personas mayores. <\/p>\n<p>Por un lado, aparecen los hospitales y centros de d\u00eda para personas con un cierto nivel de autonom\u00eda, que requieren una atenci\u00f3n puntual pero despu\u00e9s pueden volver al domicilio familiar.<\/p>\n<p>Por otro lado est\u00e1n las residencias asistidas o de larga duraci\u00f3n, en las que los usuarios permanecen 24 horas al d\u00eda y que requieren una planificaci\u00f3n completa de espacios de d\u00eda y de noche.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-02.jpg\" alt=\"espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-02\" width=\"1200\" height=\"800\" class=\"alignnone size-full wp-image-1232\" srcset=\"https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-02.jpg 1200w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-02-300x200.jpg 300w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-02-1024x683.jpg 1024w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-02-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p><strong>\u00bfQu\u00e9 aspectos clave valoramos en el dise\u00f1o de centros sociosanitarios?<\/strong><\/p>\n<p>Como en cualquier proyecto de arquitectura, el dise\u00f1o de un centro sociosanitario requiere la valoraci\u00f3n de m\u00faltiples aspectos, desde la integraci\u00f3n urban\u00edstica en el n\u00facleo urbano hasta la eficiencia energ\u00e9tica o los acabados de materiales y mobiliario. <\/p>\n<p>Hoy queremos, sin embargo, centrarnos en aquellos aspectos clave que van a marcar la diferencia en relaci\u00f3n a la calidad de vida del usuario en el centro y que son el ambiente interior y la psicolog\u00eda del espacio, veamos en detalle cada uno de los mismos:<\/p>\n<p><strong>El ambiente interior<\/strong><\/p>\n<p>La iluminaci\u00f3n es siempre un factor clave en todo dise\u00f1o arquitect\u00f3nico, pero adquiere una relevancia especial en entornos donde residen personas sensibles, enfermas o de avanzada edad.<\/p>\n<p>En primer lugar, ser\u00e1 esencial que haya aporte de luz de sol directa tanto en habitaciones como en espacios comunes. No solo es importante poder abrir las ventanas para recibir calor solar sobre la piel, es necesario tambi\u00e9n el contacto directo con el exterior a trav\u00e9s del dise\u00f1o de jardines, espacios de paseo y recorridos a lo largo de espacios soleados.<\/p>\n<p>Por su parte, la protecci\u00f3n solar tambi\u00e9n va a ser importante para garantizar el confort, todo este aporte de luz y calor solar necesita ser controlado mediante protecciones en las ventanas que garanticen una iluminaci\u00f3n y radiaci\u00f3n correcta tanto en verano como en invierno as\u00ed como en los espacios exteriores que deben estar dotados de espacios sombreados donde reposar.<\/p>\n<p>Otro factor a tener en cuenta en relaci\u00f3n al sol es el calor radiante, una fuente renovable de energ\u00eda que es \u00f3ptima para calentar los espacios y que adem\u00e1s va a significar un ahorro energ\u00e9tico.<\/p>\n<p>A nivel de iluminaci\u00f3n artificial, como siempre que hablamos de centros sanitarios, es importante garantizar diversos tipos de iluminaci\u00f3n, en funci\u00f3n de la actividad. En este tipo de centros priorizamos la iluminaci\u00f3n indirecta y los puntos de luz para realizar actividades de lectura, trabajos manuales y dem\u00e1s.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-03.jpg\" alt=\"espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-03\" width=\"1200\" height=\"825\" class=\"alignnone size-full wp-image-1233\" srcset=\"https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-03.jpg 1200w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-03-300x206.jpg 300w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-03-1024x704.jpg 1024w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-03-768x528.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p>En relaci\u00f3n a la ventilaci\u00f3n, es necesario recordar que las personas mayores tienden a reducir su capacidad pulmonar y con ello el aporte de oxigeno a la sangre, algo esencial para mantenernos activos y despiertos. <\/p>\n<p>Por este motivo, es necesario garantizar una renovaci\u00f3n de aire continua recordando que una persona necesita entre 30 y 60 m3 de aire por hora.<\/p>\n<p>En el caso de centros sanitarios puede ser recomendable instalar un sistema de ventilaci\u00f3n mec\u00e1nica, que puede ser a trav\u00e9s de un intercambiador de calor -un sistema de alta eficiencia energ\u00e9tica- o a trav\u00e9s de una apertura autom\u00e1tica de ventanas para generar una ventilaci\u00f3n cruzada r\u00e1pida y efectiva.<\/p>\n<p>Por \u00faltimo, en relaci\u00f3n a la temperatura, es mejor mantener una temperatura relativamente baja para mantenernos activos. Esto no quiere decir que el usuario pase fr\u00edo, ya que lo primordial va a ser garantizar el confort, pero s\u00ed que se pueda regular por zonas en funci\u00f3n de las necesidades de los usuarios y que, especialmente en los espacios de d\u00eda, se priorice el aporte de calor solar o calor radiante y se mantenga una temperatura de confort alrededor de 22 grados. <\/p>\n<p><strong>Psicolog\u00eda del espacio<\/strong><\/p>\n<p>Es importante tener en cuenta las sensaciones que transmite el espacio ya sea a trav\u00e9s de materiales, colores o distribuci\u00f3n espacial. <\/p>\n<p>Pensar espacios para personas mayores es pensar en espacios sencillos y f\u00e1cilmente reconocibles, teniendo en cuenta que estamos dise\u00f1ando para personas que han reducido sus facultades y su agudeza mental, visual o sonora. <\/p>\n<p>Tambi\u00e9n es necesario recordar que una residencia no es un hospital y que es el lugar donde muchos van a pasar varios a\u00f1os de su vida. Las personas que all\u00ed residen identifican el espacio como su hogar propio y esto se debe tener en cuenta en la elecci\u00f3n de acabados y mobiliario ya que muchos de estos centros se parecen m\u00e1s a hospitales de larga estancia que a centros residenciales.<\/p>\n<p>Se debe pensar el espacio de forma hol\u00edstica valorando no solo la salubridad, higiene y seguridad sino los factores que van a conseguir que el residente se sienta como en casa. <\/p>\n<p>Otro aspecto importante en relaci\u00f3n a la psicolog\u00eda del espacio ser\u00e1 los espacios de recepci\u00f3n de familiares que visitan al residente y la relaci\u00f3n con el resto del entorno urbano. <\/p>\n<p>Es importante propiciar no s\u00f3lo a nivel arquitect\u00f3nico espacios que permitan presentar al centro como un lugar abierto y de acogida, con espacios de actividades comunes para la comunidad como pueden ser un huerto o un centro c\u00edvico y de actividades comunitarias.<\/p>\n<p>Desde CASA SOLO llevamos m\u00e1s de 25 a\u00f1os dise\u00f1ando centros hospitalarios y nuestra experiencia en dise\u00f1o de entornos para personas mayores nos ha llevado a entender la necesidad de la implicaci\u00f3n y trabajo conjunto de promotores, dise\u00f1adores y de la propia comunidad donde se va a ubicar el centro residencial para asegurar el \u00e9xito del proyecto. <\/p>\n<p><!--:--><\/p>\n<p><!--:en--><\/p>\n<p>In the recent years it is palpable the progressive aging of the population. Medicine and the improvement of the quality of life allow a person to enjoy an average of 15-20 years of retirement.<\/p>\n<p>In 2015, 17% of Spanish people are over 65 years and it is expected that during the next 50 years this percentage will be increased to 37%.<\/p>\n<p>The challenges of increasing the average age of the population in relation to development and maintenance of more stable economic and social society, are one of the main concerns of the developed countries and, in this sense, the World Assembly on Ageing established recently guidelines for action to achieve the objective of ensuring that society age in a dignified and safe manner.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" src=\"http:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-00.jpg\" alt=\"espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-00\" width=\"1200\" height=\"763\" class=\"alignnone size-full wp-image-1230\" srcset=\"https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-00.jpg 1200w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-00-300x191.jpg 300w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-00-1024x651.jpg 1024w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-00-768x488.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p>As part of these conditions of dignity and security, creating quality spaces for the elderly appears, in which the architectural design takes a leading role.<\/p>\n<p>The building types for the care and improvement of the quality of life of our seniors are varied and range from specialized medical centres, day centres, nursing homes or assisted living apartments that guarantee the independence of the individual.<\/p>\n<p>In this sense, today we wanted to analyze the design of residential centres, both in public health centres mode and assisted living apartments, two booming types that have been implemented with great success in the United States for several decades and in the recent years are beginning to be implemented as an alternative in Europe and South America, where traditionally the care of the elderly remains at home.<\/p>\n<h2>Types of spaces and services for the elderly<\/h2>\n<p>Alternatives to home care -whether in a relative&#8217;s house or at our own home-are nursing homes and assisted living apartments, according to the level of dependence on the old person.<\/p>\n<p>In both cases, as we shall see, the architecture and design of the spaces will play a key role in the welfare and quality of users&#8217; life.<\/p>\n<h3>The assisted living apartments<\/h3>\n<p>Sheltered housing for older residential areas are maintaining the independence of the resident but enjoy a range of specialized services and for ensuring the safety and welfare of the user.<\/p>\n<p>These centres may be located in the city centre and connected with the services of the city itself or be isolated units that have their own services such as supermarket, hairdresser or medical assistance. In both cases the common areas will play an essential role in the formation of a stable community of residents.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-01.jpg\" alt=\"espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-01\" width=\"1200\" height=\"800\" class=\"alignnone size-full wp-image-1231\" srcset=\"https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-01.jpg 1200w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-01-300x200.jpg 300w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-01-1024x683.jpg 1024w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-01-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p>The houses are designed to be comfortable and safe, thinking of retired or close to retirement that &#8220;elderly&#8221; or elders can not sit people; they are active and seek a pleasant and safe place to spend a few months a year or live permanently.<\/p>\n<p>The design of the spaces as well as being fully adapted, takes into account natural lighting and ventilation, especially in common areas, and the creation of shaded outdoor areas for easy outdoor activity for most people.<\/p>\n<p>The supervised apartments also can be adapted to the physical requirements of each case, such as housing for people with impaired vision, hearing or motor skills.<\/p>\n<p>In all cases, supervised apartments are designed for people with a certain level of independence and may be connected to a residence for dependents that allows the tenant to maintain his residence in the same complex should go to need temporary or permanent assistance in their daily lives.<\/p>\n<h3>The health centres<\/h3>\n<p>The health centres differ from sheltered accommodation as to the autonomy of its members.<\/p>\n<p>In the supervised apartments we find people with absolute independence to perform daily tasks of hygiene, food and even are able to carry more complex market activities.<\/p>\n<p>In the health centres, the situation is of greater dependence and requires the continued assistance of medical professionals and nursing. The technical requirements of this type of design centres and the applicable rules are similar to those of a hospital.<\/p>\n<p>As for types of centres, they differ depending on the time and the conditions under which shall assist the elderly.<\/p>\n<p>On the one hand, hospitals and day centres for people with a certain level of autonomy, requiring prompt attention but after returning to the family home may appear.<\/p>\n<p>Then there are nursing homes or long-term, in which users remain 24 hours a day and require a comprehensive space planning day and night.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-02.jpg\" alt=\"espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-02\" width=\"1200\" height=\"800\" class=\"alignnone size-full wp-image-1232\" srcset=\"https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-02.jpg 1200w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-02-300x200.jpg 300w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-02-1024x683.jpg 1024w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-02-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p><strong>What key aspects in the design value of health centres?<\/strong><\/p>\n<p>As with any project of architecture, design of a welfare centre requires assessment of multiple aspects, from the urban integration in the urban core to energy efficiency or finished materials and furniture.<\/p>\n<p>Today we, however, focus on those key aspects that will make a difference in relation to the quality of life for users in the centre and are the indoor environment and the psychology of space, see in detail each of them:<\/p>\n<p><strong>The indoor environment<\/strong><\/p>\n<p>The lighting is always a key factor in any architectural design, but is especially relevant in environments where they reside sick, sensitive or aged people.<\/p>\n<p>First, it is essential that there be input from direct sunlight in rooms and in common areas. Is not only important to open the windows for solar heat on the skin, it is also necessary direct contact with the outside through the design of gardens, walking areas and paths along sunny spaces.<\/p>\n<p>For its part, the sunscreen will also be important to ensure comfort, the whole contribution of light and solar heat needs to be controlled through window guards to ensure proper lighting and radiation in both summer and winter as well as in the outdoor spaces should be provided with shaded areas to rest.<\/p>\n<p>Another factor to consider in relation to the sun&#8217;s radiant heat, a renewable energy source that is optimal for space heating and also will mean energy savings.<\/p>\n<p>A level of artificial lighting, as long as we talk about health centres is important to ensure various types of lighting, depending on the activity. In this type of indirect lighting prioritize centres and points of light for reading activities, manuals and other works.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-03.jpg\" alt=\"espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-03\" width=\"1200\" height=\"825\" class=\"alignnone size-full wp-image-1233\" srcset=\"https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-03.jpg 1200w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-03-300x206.jpg 300w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-03-1024x704.jpg 1024w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-03-768x528.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p>With regard to ventilation, you remember that older people tend to reduce their lung capacity and thus the supply of oxygen to the blood, which is essential to keep active and awake.<\/p>\n<p>For this reason, it is necessary to ensure continuous air renewal remembering that a person needs 30 to 60 m3 of air per hour.<\/p>\n<p>In the case of health centres it may be advisable to install a mechanical ventilation system, which can be through a heat exchanger system-a high energy- efficiency or through an automatic opening windows to generate fast and effective cross ventilation .<\/p>\n<p>Finally, in relation to the temperature, it is best to maintain a relatively low temperature to keep active. This does not mean that the user get cold, because the bottom line will be to ensure comfort, but it can be regulated by zones according to the needs of users and that, especially in the areas of day, prioritize the contribution of solar heat or radiant heat and keep a comfortable temperature about 22 degrees.<\/p>\n<p><strong>Space Psychology<\/strong><\/p>\n<p>It is important to consider the feelings conveyed by the space either through materials, colours or spatial distribution.<\/p>\n<p>Think spaces for seniors is to think simple and easily recognizable spaces, given that we are designing for people who have reduced their powers and their mental, visual or sound sharpness.<\/p>\n<p>You also need to remember that a home is not a hospital and that is where many will spend years of his life. People who live there identify the space as their own home and this should be taken into account in the choice of finishes and furnishings as many of these centres are more like long-stay hospitals to residential centres.<\/p>\n<p>One should think holistically space valuing not only the health, hygiene and safety factors but they will get the resident feel at home.<\/p>\n<p>Another important aspect in relation to the psychology of space will be receiving spaces resident visiting family and relationship with the rest of the urban environment.<\/p>\n<p>It is important not only to promote spaces that allow the centre to present an open and welcoming place, with common spaces for community activities such as gardening or a civic and community activities centre architectural level.<\/p>\n<p>From home only we took over 25 years designing hospitals and our experience in design environments for older people has led us to understand the need for the involvement and joint work of developers, designers and the community where they will locate the centre residential to ensure project success.<\/p>\n<p><!--:--><\/p>\n<p><!--:ca--><\/p>\n<p>En els \u00faltims anys s&#8217;est\u00e0 fent palpable el progressiu envelliment de la poblaci\u00f3. La medicina i la millora de la qualitat de vida permeten a una persona gaudir d&#8217;una mitjana de 15 a 20 anys de jubilaci\u00f3.<\/p>\n<p>El 2015, un 17% dels espanyols s\u00f3n majors de 65 anys i es preveu que durant els propers 50 anys aquest percentatge augmenti fins al 37%.<\/p>\n<p>Els reptes que comporta l&#8217;augment de la mitjana d&#8217;edat de la poblaci\u00f3, en relaci\u00f3 al desenvolupament i manteniment d&#8217;una societat m\u00e9s estable econ\u00f2micament i socialment, s\u00f3n una de les principals preocupacions dels pa\u00efsos desenvolupats i, en aquest sentit, l&#8217;Assemblea Mundial sobre l&#8217;envelliment va establir recentment unes directrius d&#8217;acci\u00f3 per complir l&#8217;objectiu d&#8217;assegurar que la societat envelleixi d&#8217;una manera digna i segura.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" src=\"http:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-00.jpg\" alt=\"espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-00\" width=\"1200\" height=\"763\" class=\"alignnone size-full wp-image-1230\" srcset=\"https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-00.jpg 1200w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-00-300x191.jpg 300w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-00-1024x651.jpg 1024w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-00-768x488.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p>Dins el marc d&#8217;aquestes condicions de dignitat i seguretat, apareix la creaci\u00f3 d&#8217;espais de qualitat per a les persones d&#8217;avan\u00e7ada edat, en el qual el disseny arquitect\u00f2nic pren un paper rellevant.<\/p>\n<p>Les tipologies edificat\u00f2ries destinades a l&#8217;atenci\u00f3 i millora de la qualitat de vida dels nostres majors s\u00f3n molt variades i van des dels centres m\u00e8dics especialitzats a centres de dia, resid\u00e8ncies o apartaments tutelats que garanteixen la independ\u00e8ncia de la persona.<\/p>\n<p>En aquest sentit, avui hem volgut analitzar el disseny dels centres residencials tant en la modalitat residencial com en la tipologia d&#8217;apartament, dues tipologies en auge que s&#8217;han implementat amb molt \u00e8xit als Estats Units des de fa ja diverses d\u00e8cades i que en els \u00faltims anys s&#8217;estan comen\u00e7ant a implementar com a alternativa a Europa i Am\u00e8rica del Sud, on tradicionalment la cura i atenci\u00f3 de la gent gran es mant\u00e9 a la llar familiar.<\/p>\n<h2>Tipologies d&#8217;espais i serveis per a la gent gran<\/h2>\n<p>Les alternatives a l&#8217;atenci\u00f3 domicili\u00e0ria -ja sigui a casa d&#8217;un familiar o al propi habitatge-, s\u00f3n les resid\u00e8ncies i els apartaments tutelats en funci\u00f3 del nivell de depend\u00e8ncia de la persona gran.<\/p>\n<p>En tots dos casos com veurem, l&#8217;arquitectura i el disseny dels espais jugaran un paper clau en el benestar i qualitat de vida dels usuaris.<\/p>\n<h3>Els apartaments tutelats<\/h3>\n<p>Els habitatges per a gent gran tutelats s\u00f3n zones residencials que mantenen la independ\u00e8ncia del resident per\u00f2 que gaudeixen d&#8217;una s\u00e8rie de serveis especialitzats i destinats a garantir la seguretat i benestar de l&#8217;usuari.<\/p>\n<p>Aquests centres poden estar ubicats al centre urb\u00e0 i connectats amb els serveis de la pr\u00f2pia ciutat o b\u00e9 ser unitats a\u00efllades que disposen de serveis propis com supermercat, perruqueria o assist\u00e8ncia m\u00e8dica. En ambd\u00f3s casos les zones comunes jugaran un paper essencial en la formaci\u00f3 d&#8217;una comunitat estable de residents.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-01.jpg\" alt=\"espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-01\" width=\"1200\" height=\"800\" class=\"alignnone size-full wp-image-1231\" srcset=\"https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-01.jpg 1200w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-01-300x200.jpg 300w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-01-1024x683.jpg 1024w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-01-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p>Els habitatges estan dissenyats per ser c\u00f2modes i segurs, pensant en persones jubilades o pr\u00f2ximes a la jubilaci\u00f3 que no se sentin &#8220;tercera edat&#8221; o gent gran, sin\u00f3 que estiguin actius i busquin un entorn agradable i segur on passar uns mesos a l&#8217;any o viure de forma definitiva.<\/p>\n<p>El disseny dels espais m\u00e9s d&#8217;estar totalment adaptats t\u00e9 molt en compte la il\u2022luminaci\u00f3 natural i la ventilaci\u00f3, sobretot en els espais comuns, aix\u00ed com la creaci\u00f3 de zones d&#8217;ombra exteriors per facilitar l&#8217;activitat a l&#8217;aire lliure de la gent gran.<\/p>\n<p>Els pisos tutelats, a m\u00e9s, poden estar adaptats als requeriments f\u00edsics de cada cas concret, com poden ser habitatges per a persones amb alteracions en la visi\u00f3, en l&#8217;o\u00efda o la psicomotricitat.<\/p>\n<p>En tots els casos els pisos tutelats estan pensats per a persones amb un cert nivell d&#8217;independ\u00e8ncia i poden estar connectats amb una resid\u00e8ncia per a persones dependents que permeti a l&#8217; inquil\u00ed mantenir la seva resid\u00e8ncia al mateix complex en cas de passar a necessitar de forma temporal o permanent assist\u00e8ncia en la seva vida di\u00e0ria.<\/p>\n<h3>Els centres sociosanitaris<\/h3>\n<p>Els centres sociosanitaris es diferencien dels pisos tutelats pel que fa a l&#8217;autonomia dels seus usuaris.<\/p>\n<p>En els pisos tutelats trobarem persones amb absoluta independ\u00e8ncia per realitzar les tasques di\u00e0ries d&#8217;higiene, alimentaci\u00f3 i fins i tot capacitades per dur a terme altres activitats m\u00e9s complexes.<\/p>\n<p>En els centres sociosanitaris la situaci\u00f3 \u00e9s d&#8217;una major depend\u00e8ncia i requereix l&#8217;assist\u00e8ncia continuada de professionals m\u00e8dics i d&#8217;infermeria. Les exig\u00e8ncies t\u00e8cniques de disseny d&#8217;aquest tipus de centres, aix\u00ed com la normativa aplicable, s\u00f3n semblants a les d&#8217;un hospital.<\/p>\n<p>Pel que fa a les tipologies de centres, aquestes es distingeixen en funci\u00f3 del temps i de les condicions en qu\u00e8 s&#8217;ha d&#8217;assistir a la gent gran.<\/p>\n<p>D&#8217;una banda, apareixen els hospitals i centres de dia per a persones amb un cert nivell d&#8217;autonomia, que requereixen una atenci\u00f3 puntual per\u00f2 despr\u00e9s poden tornar al domicili familiar.<\/p>\n<p>D&#8217;altra banda estan les resid\u00e8ncies assistides o de llarga durada, en qu\u00e8 els usuaris romanen 24 hores al dia i que requereixen una planificaci\u00f3 completa d&#8217;espais de dia i de nit.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-02.jpg\" alt=\"espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-02\" width=\"1200\" height=\"800\" class=\"alignnone size-full wp-image-1232\" srcset=\"https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-02.jpg 1200w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-02-300x200.jpg 300w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-02-1024x683.jpg 1024w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-02-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p><strong>Quins aspectes clau valorem en el disseny de centres sociosanitaris?<\/strong><\/p>\n<p>Com en qualsevol projecte d&#8217;arquitectura, el disseny d&#8217;un centre sociosanitari requereix la valoraci\u00f3 de m\u00faltiples aspectes, des de la integraci\u00f3 urban\u00edstica en el nucli urb\u00e0 fins l&#8217;efici\u00e8ncia energ\u00e8tica o els acabats de materials i mobiliari.<\/p>\n<p>Avui volem, per\u00f2, centrar-nos en aquells aspectes clau que marcaran la difer\u00e8ncia en relaci\u00f3 a la qualitat de vida de l&#8217;usuari en el centre i que s\u00f3n l&#8217;ambient interior i la psicologia de l&#8217;espai, vegem en detall cadascun dels mateixos:<\/p>\n<p><strong>L&#8217;ambient interior<\/strong><\/p>\n<p>La il\u2022luminaci\u00f3 \u00e9s sempre un factor clau en tot disseny arquitect\u00f2nic, per\u00f2 adquireix una rellev\u00e0ncia especial en entorns on resideixen persones sensibles, malaltes o d&#8217;avan\u00e7ada edat.<\/p>\n<p>En primer lloc, ser\u00e0 essencial que hi hagi aportaci\u00f3 de llum solar directa tant en les habitacions com en els espais comuns. No nom\u00e9s \u00e9s important poder obrir les finestres per rebre calor sobre la pell, sin\u00f3 que tamb\u00e9 \u00e9s necessari el contacte directe amb l&#8217;exterior a trav\u00e9s del disseny de jardins, espais de passeig i recorreguts al llarg d&#8217;espais assolellats.<\/p>\n<p>Per la seva banda, la protecci\u00f3 solar tamb\u00e9 ser\u00e0 important per garantir el confort, ja que tota aquesta aportaci\u00f3 de llum i calor solar necessita ser controlada mitjan\u00e7ant proteccions en les finestres que garanteixin una il\u2022luminaci\u00f3 i radiaci\u00f3 correcta tant a l&#8217;estiu com a l&#8217;hivern, aix\u00ed com en els espais exteriors els quals han d&#8217;estar dotats d&#8217;espais ombrejats on reposar.<\/p>\n<p>Un altre factor a tenir en compte en relaci\u00f3 al sol \u00e9s la calor radiant, una font renovable d&#8217;energia que \u00e9s \u00f2ptima per escalfar els espais i que a m\u00e9s significar\u00e0 un estalvi energ\u00e8tic.<\/p>\n<p>En quant a la il\u2022luminaci\u00f3 artificial, com sempre que parlem de centres sanitaris, \u00e9s important garantir diversos tipus d&#8217;il\u2022luminaci\u00f3, en funci\u00f3 de l&#8217;activitat. En aquest tipus de centres prioritzem la il\u2022luminaci\u00f3 indirecta i els punts de llum per a realitzar activitats de lectura, treballs manuals i altres.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-03.jpg\" alt=\"espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-03\" width=\"1200\" height=\"825\" class=\"alignnone size-full wp-image-1233\" srcset=\"https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-03.jpg 1200w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-03-300x206.jpg 300w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-03-1024x704.jpg 1024w, https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-03-768x528.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p>En relaci\u00f3 a la ventilaci\u00f3, cal recordar que les persones grans tendeixen a reduir la seva capacitat pulmonar i amb aix\u00f2 l&#8217;aportaci\u00f3 d&#8217;oxigen a la sang, cosa essencial per mantenir-nos actius i desperts.<\/p>\n<p>Per aquest motiu, cal garantir una renovaci\u00f3 d&#8217;aire cont\u00ednua recordant que una persona necessita entre 30 i 60 m3 d&#8217;aire per hora.<\/p>\n<p>En el cas de centres sanitaris pot ser recomanable instal\u2022lar un sistema de ventilaci\u00f3 mec\u00e0nica, que pot ser a trav\u00e9s d&#8217;un intercanviador de calor -un sistema d&#8217;alta efici\u00e8ncia energ\u00e8tica- o a trav\u00e9s d&#8217;una obertura autom\u00e0tica de finestres per generar una ventilaci\u00f3 creuada r\u00e0pida i efectiva .<\/p>\n<p>Finalment, en relaci\u00f3 a la temperatura, \u00e9s millor mantenir una temperatura relativament baixa per mantenir-nos actius. Aix\u00f2 no vol dir que l&#8217;usuari passi fred, ja que all\u00f2 primordial ser\u00e0 garantir el confort, per\u00f2 s\u00ed que es pugui regular per zones en funci\u00f3 de les necessitats dels usuaris i que, especialment en els espais de dia, es prioritzi l&#8217;aportaci\u00f3 de calor solar o calor radiant i es mantingui una temperatura de confort al voltant de 22 graus.<\/p>\n<p><strong>Psicologia de l&#8217;espai<\/strong><\/p>\n<p>\u00c9s important tenir en compte les sensacions que transmet l&#8217;espai ja sigui a trav\u00e9s de materials, colors o distribuci\u00f3 espacial.<\/p>\n<p>Pensar espais per a gent gran \u00e9s pensar en espais senzills i de f\u00e0cil reconeixement, tenint en compte que estem dissenyant per a persones que han redu\u00eft les seves facultats i la seva agudesa mental, visual o sonora.<\/p>\n<p>Tamb\u00e9 cal recordar que una resid\u00e8ncia no \u00e9s un hospital i que \u00e9s el lloc on molts van a passar diversos anys de la seva vida. Les persones que hi resideixen identifiquen l&#8217;espai com la seva pr\u00f2pia llar i aix\u00f2 s&#8217;ha de tenir en compte en l&#8217;elecci\u00f3 dels acabats i el mobiliari, ja que molts d&#8217;aquests centres s&#8217;assemblen m\u00e9s a hospitals de llarga estada que a centres residencials.<\/p>\n<p>S&#8217;ha de pensar l&#8217;espai de forma general valorant no nom\u00e9s la salubritat, higiene i seguretat sin\u00f3 tamb\u00e9 els factors que aconseguiran que el resident es senti com a casa.<\/p>\n<p>Un altre aspecte important en relaci\u00f3 a la psicologia de l&#8217;espai seran els espais de recepci\u00f3 de familiars que visiten al resident i la relaci\u00f3 amb la resta de l&#8217;entorn urb\u00e0.<\/p>\n<p>\u00c9s important propiciar, no nom\u00e9s a nivell arquitect\u00f2nic, espais que permetin presentar al centre com un lloc obert i d&#8217;acolliment, amb espais d&#8217;activitats comunes per a la comunitat com poden ser un hort o un centre c\u00edvic i d&#8217;activitats comunit\u00e0ries.<\/p>\n<p>Des de CASA SOLO portem m\u00e9s de 25 anys dissenyant centres hospitalaris i la nostra experi\u00e8ncia en disseny d&#8217;entorns per a gent gran ens ha portat a entendre la necessitat de la implicaci\u00f3 i el treball conjunt de promotors, dissenyadors i de la pr\u00f2pia comunitat on s&#8217;ubicar\u00e0 el centre residencial per assegurar l&#8217;\u00e8xit del projecte.<\/p>\n<p><!--:--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En los \u00faltimos a\u00f1os se est\u00e1 haciendo palpable el progresivo envejecimiento de la poblaci\u00f3n. La medicina y la mejora de la calidad de vida permiten a una persona disfrutar de una media de 15 a 20 a\u00f1os de jubilaci\u00f3n. En 2015, un 17% de los espa\u00f1oles son mayores de 65 a\u00f1os y se prev\u00e9 que [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":1232,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[28],"tags":[],"class_list":["post-1224","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gente-mayor"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dise\u00f1o de espacios para mayores: apartamentos tutelados y centros sociosanitarios<\/title>\n<meta name=\"description\" content=\"Desde CASASOLO llevamos a\u00f1os dise\u00f1ando centros hospitalarios y entendemos la necesidad del trabajo conjunto de promotores, dise\u00f1adores y la misma comunidad.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casasolo.es\/ca\/diseno-de-espacios-para-mayores-apartamentos-tutelados-y-centros-sociosanitarios\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dise\u00f1o de espacios para mayores: apartamentos tutelados y centros sociosanitarios\" \/>\n<meta property=\"og:description\" content=\"Desde CASASOLO llevamos a\u00f1os dise\u00f1ando centros hospitalarios y entendemos la necesidad del trabajo conjunto de promotores, dise\u00f1adores y la misma comunidad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casasolo.es\/ca\/diseno-de-espacios-para-mayores-apartamentos-tutelados-y-centros-sociosanitarios\/\" \/>\n<meta property=\"og:site_name\" content=\"CASA SOLO arquitectos\" \/>\n<meta property=\"article:published_time\" content=\"2015-12-17T15:35:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-02.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"casaweb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"casaweb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"24 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/casasolo.es\/ca\/diseno-de-espacios-para-mayores-apartamentos-tutelados-y-centros-sociosanitarios\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/casasolo.es\/ca\/diseno-de-espacios-para-mayores-apartamentos-tutelados-y-centros-sociosanitarios\/\"},\"author\":{\"name\":\"casaweb\",\"@id\":\"https:\/\/casasolo.es\/ca\/#\/schema\/person\/5fc60cf44aa387460af4ccaa862ac1b4\"},\"headline\":\"Dise\u00f1o de espacios para mayores: apartamentos tutelados y centros sociosanitarios\",\"datePublished\":\"2015-12-17T15:35:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/casasolo.es\/ca\/diseno-de-espacios-para-mayores-apartamentos-tutelados-y-centros-sociosanitarios\/\"},\"wordCount\":4801,\"publisher\":{\"@id\":\"https:\/\/casasolo.es\/ca\/#organization\"},\"image\":{\"@id\":\"https:\/\/casasolo.es\/ca\/diseno-de-espacios-para-mayores-apartamentos-tutelados-y-centros-sociosanitarios\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-02.jpg\",\"articleSection\":[\"Gente mayor\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/casasolo.es\/ca\/diseno-de-espacios-para-mayores-apartamentos-tutelados-y-centros-sociosanitarios\/\",\"url\":\"https:\/\/casasolo.es\/ca\/diseno-de-espacios-para-mayores-apartamentos-tutelados-y-centros-sociosanitarios\/\",\"name\":\"Dise\u00f1o de espacios para mayores: apartamentos tutelados y centros sociosanitarios\",\"isPartOf\":{\"@id\":\"https:\/\/casasolo.es\/ca\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/casasolo.es\/ca\/diseno-de-espacios-para-mayores-apartamentos-tutelados-y-centros-sociosanitarios\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/casasolo.es\/ca\/diseno-de-espacios-para-mayores-apartamentos-tutelados-y-centros-sociosanitarios\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-02.jpg\",\"datePublished\":\"2015-12-17T15:35:42+00:00\",\"description\":\"Desde CASASOLO llevamos a\u00f1os dise\u00f1ando centros hospitalarios y entendemos la necesidad del trabajo conjunto de promotores, dise\u00f1adores y la misma comunidad.\",\"breadcrumb\":{\"@id\":\"https:\/\/casasolo.es\/ca\/diseno-de-espacios-para-mayores-apartamentos-tutelados-y-centros-sociosanitarios\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/casasolo.es\/ca\/diseno-de-espacios-para-mayores-apartamentos-tutelados-y-centros-sociosanitarios\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/casasolo.es\/ca\/diseno-de-espacios-para-mayores-apartamentos-tutelados-y-centros-sociosanitarios\/#primaryimage\",\"url\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-02.jpg\",\"contentUrl\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-02.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/casasolo.es\/ca\/diseno-de-espacios-para-mayores-apartamentos-tutelados-y-centros-sociosanitarios\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/casasolo.es\/ca\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dise\u00f1o de espacios para mayores: apartamentos tutelados y centros sociosanitarios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/casasolo.es\/ca\/#website\",\"url\":\"https:\/\/casasolo.es\/ca\/\",\"name\":\"CASA SOLO arquitectos\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/casasolo.es\/ca\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/casasolo.es\/ca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/casasolo.es\/ca\/#organization\",\"name\":\"CASA SOLO arquitectos\",\"url\":\"https:\/\/casasolo.es\/ca\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/casasolo.es\/ca\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2021\/10\/casasolo-logo.svg\",\"contentUrl\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2021\/10\/casasolo-logo.svg\",\"caption\":\"CASA SOLO arquitectos\"},\"image\":{\"@id\":\"https:\/\/casasolo.es\/ca\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/casasolo.es\/ca\/#\/schema\/person\/5fc60cf44aa387460af4ccaa862ac1b4\",\"name\":\"casaweb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/casasolo.es\/ca\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fc9cf1dfa9383b5d06e9ea4952a17ca69d4f4a2f3a07f60d4b52a5cd6e11ca07?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fc9cf1dfa9383b5d06e9ea4952a17ca69d4f4a2f3a07f60d4b52a5cd6e11ca07?s=96&d=mm&r=g\",\"caption\":\"casaweb\"},\"url\":\"https:\/\/casasolo.es\/ca\/author\/casaweb\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dise\u00f1o de espacios para mayores: apartamentos tutelados y centros sociosanitarios","description":"Desde CASASOLO llevamos a\u00f1os dise\u00f1ando centros hospitalarios y entendemos la necesidad del trabajo conjunto de promotores, dise\u00f1adores y la misma comunidad.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casasolo.es\/ca\/diseno-de-espacios-para-mayores-apartamentos-tutelados-y-centros-sociosanitarios\/","og_locale":"ca_ES","og_type":"article","og_title":"Dise\u00f1o de espacios para mayores: apartamentos tutelados y centros sociosanitarios","og_description":"Desde CASASOLO llevamos a\u00f1os dise\u00f1ando centros hospitalarios y entendemos la necesidad del trabajo conjunto de promotores, dise\u00f1adores y la misma comunidad.","og_url":"https:\/\/casasolo.es\/ca\/diseno-de-espacios-para-mayores-apartamentos-tutelados-y-centros-sociosanitarios\/","og_site_name":"CASA SOLO arquitectos","article_published_time":"2015-12-17T15:35:42+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-02.jpg","type":"image\/jpeg"}],"author":"casaweb","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"casaweb","Temps estimat de lectura":"24 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/casasolo.es\/ca\/diseno-de-espacios-para-mayores-apartamentos-tutelados-y-centros-sociosanitarios\/#article","isPartOf":{"@id":"https:\/\/casasolo.es\/ca\/diseno-de-espacios-para-mayores-apartamentos-tutelados-y-centros-sociosanitarios\/"},"author":{"name":"casaweb","@id":"https:\/\/casasolo.es\/ca\/#\/schema\/person\/5fc60cf44aa387460af4ccaa862ac1b4"},"headline":"Dise\u00f1o de espacios para mayores: apartamentos tutelados y centros sociosanitarios","datePublished":"2015-12-17T15:35:42+00:00","mainEntityOfPage":{"@id":"https:\/\/casasolo.es\/ca\/diseno-de-espacios-para-mayores-apartamentos-tutelados-y-centros-sociosanitarios\/"},"wordCount":4801,"publisher":{"@id":"https:\/\/casasolo.es\/ca\/#organization"},"image":{"@id":"https:\/\/casasolo.es\/ca\/diseno-de-espacios-para-mayores-apartamentos-tutelados-y-centros-sociosanitarios\/#primaryimage"},"thumbnailUrl":"https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-02.jpg","articleSection":["Gente mayor"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/casasolo.es\/ca\/diseno-de-espacios-para-mayores-apartamentos-tutelados-y-centros-sociosanitarios\/","url":"https:\/\/casasolo.es\/ca\/diseno-de-espacios-para-mayores-apartamentos-tutelados-y-centros-sociosanitarios\/","name":"Dise\u00f1o de espacios para mayores: apartamentos tutelados y centros sociosanitarios","isPartOf":{"@id":"https:\/\/casasolo.es\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casasolo.es\/ca\/diseno-de-espacios-para-mayores-apartamentos-tutelados-y-centros-sociosanitarios\/#primaryimage"},"image":{"@id":"https:\/\/casasolo.es\/ca\/diseno-de-espacios-para-mayores-apartamentos-tutelados-y-centros-sociosanitarios\/#primaryimage"},"thumbnailUrl":"https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-02.jpg","datePublished":"2015-12-17T15:35:42+00:00","description":"Desde CASASOLO llevamos a\u00f1os dise\u00f1ando centros hospitalarios y entendemos la necesidad del trabajo conjunto de promotores, dise\u00f1adores y la misma comunidad.","breadcrumb":{"@id":"https:\/\/casasolo.es\/ca\/diseno-de-espacios-para-mayores-apartamentos-tutelados-y-centros-sociosanitarios\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casasolo.es\/ca\/diseno-de-espacios-para-mayores-apartamentos-tutelados-y-centros-sociosanitarios\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/casasolo.es\/ca\/diseno-de-espacios-para-mayores-apartamentos-tutelados-y-centros-sociosanitarios\/#primaryimage","url":"https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-02.jpg","contentUrl":"https:\/\/casasolo.es\/wp-content\/uploads\/2015\/12\/espacios-mayores-apartamentos-tutelados-centros-sociosanitarios-02.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/casasolo.es\/ca\/diseno-de-espacios-para-mayores-apartamentos-tutelados-y-centros-sociosanitarios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/casasolo.es\/ca\/home\/"},{"@type":"ListItem","position":2,"name":"Dise\u00f1o de espacios para mayores: apartamentos tutelados y centros sociosanitarios"}]},{"@type":"WebSite","@id":"https:\/\/casasolo.es\/ca\/#website","url":"https:\/\/casasolo.es\/ca\/","name":"CASA SOLO arquitectos","description":"","publisher":{"@id":"https:\/\/casasolo.es\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casasolo.es\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/casasolo.es\/ca\/#organization","name":"CASA SOLO arquitectos","url":"https:\/\/casasolo.es\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/casasolo.es\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/casasolo.es\/wp-content\/uploads\/2021\/10\/casasolo-logo.svg","contentUrl":"https:\/\/casasolo.es\/wp-content\/uploads\/2021\/10\/casasolo-logo.svg","caption":"CASA SOLO arquitectos"},"image":{"@id":"https:\/\/casasolo.es\/ca\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/casasolo.es\/ca\/#\/schema\/person\/5fc60cf44aa387460af4ccaa862ac1b4","name":"casaweb","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/casasolo.es\/ca\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fc9cf1dfa9383b5d06e9ea4952a17ca69d4f4a2f3a07f60d4b52a5cd6e11ca07?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fc9cf1dfa9383b5d06e9ea4952a17ca69d4f4a2f3a07f60d4b52a5cd6e11ca07?s=96&d=mm&r=g","caption":"casaweb"},"url":"https:\/\/casasolo.es\/ca\/author\/casaweb\/"}]}},"_links":{"self":[{"href":"https:\/\/casasolo.es\/ca\/wp-json\/wp\/v2\/posts\/1224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casasolo.es\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casasolo.es\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casasolo.es\/ca\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/casasolo.es\/ca\/wp-json\/wp\/v2\/comments?post=1224"}],"version-history":[{"count":0,"href":"https:\/\/casasolo.es\/ca\/wp-json\/wp\/v2\/posts\/1224\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casasolo.es\/ca\/wp-json\/wp\/v2\/media\/1232"}],"wp:attachment":[{"href":"https:\/\/casasolo.es\/ca\/wp-json\/wp\/v2\/media?parent=1224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casasolo.es\/ca\/wp-json\/wp\/v2\/categories?post=1224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casasolo.es\/ca\/wp-json\/wp\/v2\/tags?post=1224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}