{"id":5372,"date":"2023-04-24T09:51:11","date_gmt":"2023-04-24T09:51:11","guid":{"rendered":"https:\/\/casasolo.es\/?post_type=cs_proyectos&#038;p=5372"},"modified":"2023-04-25T09:57:13","modified_gmt":"2023-04-25T09:57:13","slug":"hospital-comarcal-del-pallars","status":"publish","type":"cs_proyectos","link":"https:\/\/casasolo.es\/ca\/proyectos\/hospital-comarcal-del-pallars\/","title":{"rendered":"Hospital Comarcal del Pallars"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Tremp, Lleida, Espa\u00f1a<\/p>\n","protected":false},"author":9,"featured_media":5367,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"categories":[],"tags":[],"class_list":["post-5372","cs_proyectos","type-cs_proyectos","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hospital Comarcal del Pallars - CASA SOLO arquitectos<\/title>\n<meta name=\"description\" content=\"L&#039;Hospital Comarcal del Pallars substitueix les funcions assistencials d&#039;un centre ja existent destinat a l&#039;atenci\u00f3 de malalts cr\u00f2nics i de resid\u00e8ncia geri\u00e0trica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casasolo.es\/ca\/proyectos\/hospital-comarcal-del-pallars\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hospital Comarcal del Pallars - CASA SOLO arquitectos\" \/>\n<meta property=\"og:description\" content=\"L&#039;Hospital Comarcal del Pallars substitueix les funcions assistencials d&#039;un centre ja existent destinat a l&#039;atenci\u00f3 de malalts cr\u00f2nics i de resid\u00e8ncia geri\u00e0trica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casasolo.es\/ca\/proyectos\/hospital-comarcal-del-pallars\/\" \/>\n<meta property=\"og:site_name\" content=\"CASA SOLO arquitectos\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-25T09:57:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casasolo.es\/wp-content\/uploads\/2023\/04\/Hospital-del-Pallars_CASA-SOLO_03.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"886\" \/>\n\t<meta property=\"og:image:height\" content=\"609\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/casasolo.es\/ca\/proyectos\/hospital-comarcal-del-pallars\/\",\"url\":\"https:\/\/casasolo.es\/ca\/proyectos\/hospital-comarcal-del-pallars\/\",\"name\":\"Hospital Comarcal del Pallars - CASA SOLO arquitectos\",\"isPartOf\":{\"@id\":\"https:\/\/casasolo.es\/ca\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/casasolo.es\/ca\/proyectos\/hospital-comarcal-del-pallars\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/casasolo.es\/ca\/proyectos\/hospital-comarcal-del-pallars\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2023\/04\/Hospital-del-Pallars_CASA-SOLO_03.jpg\",\"datePublished\":\"2023-04-24T09:51:11+00:00\",\"dateModified\":\"2023-04-25T09:57:13+00:00\",\"description\":\"L'Hospital Comarcal del Pallars substitueix les funcions assistencials d'un centre ja existent destinat a l'atenci\u00f3 de malalts cr\u00f2nics i de resid\u00e8ncia geri\u00e0trica.\",\"breadcrumb\":{\"@id\":\"https:\/\/casasolo.es\/ca\/proyectos\/hospital-comarcal-del-pallars\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/casasolo.es\/ca\/proyectos\/hospital-comarcal-del-pallars\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/casasolo.es\/ca\/proyectos\/hospital-comarcal-del-pallars\/#primaryimage\",\"url\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2023\/04\/Hospital-del-Pallars_CASA-SOLO_03.jpg\",\"contentUrl\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2023\/04\/Hospital-del-Pallars_CASA-SOLO_03.jpg\",\"width\":886,\"height\":609,\"caption\":\"Hospital del Pallars_CASA SOLO_03\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/casasolo.es\/ca\/proyectos\/hospital-comarcal-del-pallars\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/casasolo.es\/ca\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hospital Comarcal del Pallars\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/casasolo.es\/ca\/#website\",\"url\":\"https:\/\/casasolo.es\/ca\/\",\"name\":\"CASA SOLO arquitectos\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/casasolo.es\/ca\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/casasolo.es\/ca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/casasolo.es\/ca\/#organization\",\"name\":\"CASA SOLO arquitectos\",\"url\":\"https:\/\/casasolo.es\/ca\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/casasolo.es\/ca\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2021\/10\/casasolo-logo.svg\",\"contentUrl\":\"https:\/\/casasolo.es\/wp-content\/uploads\/2021\/10\/casasolo-logo.svg\",\"caption\":\"CASA SOLO arquitectos\"},\"image\":{\"@id\":\"https:\/\/casasolo.es\/ca\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hospital Comarcal del Pallars - CASA SOLO arquitectos","description":"L'Hospital Comarcal del Pallars substitueix les funcions assistencials d'un centre ja existent destinat a l'atenci\u00f3 de malalts cr\u00f2nics i de resid\u00e8ncia geri\u00e0trica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casasolo.es\/ca\/proyectos\/hospital-comarcal-del-pallars\/","og_locale":"ca_ES","og_type":"article","og_title":"Hospital Comarcal del Pallars - CASA SOLO arquitectos","og_description":"L'Hospital Comarcal del Pallars substitueix les funcions assistencials d'un centre ja existent destinat a l'atenci\u00f3 de malalts cr\u00f2nics i de resid\u00e8ncia geri\u00e0trica.","og_url":"https:\/\/casasolo.es\/ca\/proyectos\/hospital-comarcal-del-pallars\/","og_site_name":"CASA SOLO arquitectos","article_modified_time":"2023-04-25T09:57:13+00:00","og_image":[{"width":886,"height":609,"url":"https:\/\/casasolo.es\/wp-content\/uploads\/2023\/04\/Hospital-del-Pallars_CASA-SOLO_03.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/casasolo.es\/ca\/proyectos\/hospital-comarcal-del-pallars\/","url":"https:\/\/casasolo.es\/ca\/proyectos\/hospital-comarcal-del-pallars\/","name":"Hospital Comarcal del Pallars - CASA SOLO arquitectos","isPartOf":{"@id":"https:\/\/casasolo.es\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casasolo.es\/ca\/proyectos\/hospital-comarcal-del-pallars\/#primaryimage"},"image":{"@id":"https:\/\/casasolo.es\/ca\/proyectos\/hospital-comarcal-del-pallars\/#primaryimage"},"thumbnailUrl":"https:\/\/casasolo.es\/wp-content\/uploads\/2023\/04\/Hospital-del-Pallars_CASA-SOLO_03.jpg","datePublished":"2023-04-24T09:51:11+00:00","dateModified":"2023-04-25T09:57:13+00:00","description":"L'Hospital Comarcal del Pallars substitueix les funcions assistencials d'un centre ja existent destinat a l'atenci\u00f3 de malalts cr\u00f2nics i de resid\u00e8ncia geri\u00e0trica.","breadcrumb":{"@id":"https:\/\/casasolo.es\/ca\/proyectos\/hospital-comarcal-del-pallars\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casasolo.es\/ca\/proyectos\/hospital-comarcal-del-pallars\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/casasolo.es\/ca\/proyectos\/hospital-comarcal-del-pallars\/#primaryimage","url":"https:\/\/casasolo.es\/wp-content\/uploads\/2023\/04\/Hospital-del-Pallars_CASA-SOLO_03.jpg","contentUrl":"https:\/\/casasolo.es\/wp-content\/uploads\/2023\/04\/Hospital-del-Pallars_CASA-SOLO_03.jpg","width":886,"height":609,"caption":"Hospital del Pallars_CASA SOLO_03"},{"@type":"BreadcrumbList","@id":"https:\/\/casasolo.es\/ca\/proyectos\/hospital-comarcal-del-pallars\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/casasolo.es\/ca\/home\/"},{"@type":"ListItem","position":2,"name":"Hospital Comarcal del Pallars"}]},{"@type":"WebSite","@id":"https:\/\/casasolo.es\/ca\/#website","url":"https:\/\/casasolo.es\/ca\/","name":"CASA SOLO arquitectos","description":"","publisher":{"@id":"https:\/\/casasolo.es\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casasolo.es\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/casasolo.es\/ca\/#organization","name":"CASA SOLO arquitectos","url":"https:\/\/casasolo.es\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/casasolo.es\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/casasolo.es\/wp-content\/uploads\/2021\/10\/casasolo-logo.svg","contentUrl":"https:\/\/casasolo.es\/wp-content\/uploads\/2021\/10\/casasolo-logo.svg","caption":"CASA SOLO arquitectos"},"image":{"@id":"https:\/\/casasolo.es\/ca\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/casasolo.es\/ca\/wp-json\/wp\/v2\/cs_proyectos\/5372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casasolo.es\/ca\/wp-json\/wp\/v2\/cs_proyectos"}],"about":[{"href":"https:\/\/casasolo.es\/ca\/wp-json\/wp\/v2\/types\/cs_proyectos"}],"author":[{"embeddable":true,"href":"https:\/\/casasolo.es\/ca\/wp-json\/wp\/v2\/users\/9"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casasolo.es\/ca\/wp-json\/wp\/v2\/media\/5367"}],"wp:attachment":[{"href":"https:\/\/casasolo.es\/ca\/wp-json\/wp\/v2\/media?parent=5372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casasolo.es\/ca\/wp-json\/wp\/v2\/categories?post=5372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casasolo.es\/ca\/wp-json\/wp\/v2\/tags?post=5372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}